{"id":14871,"date":"2020-12-20T13:29:23","date_gmt":"2020-12-20T19:29:23","guid":{"rendered":"http:\/\/bambapolitica.com.mx\/?p=14871"},"modified":"2020-12-20T13:29:24","modified_gmt":"2020-12-20T19:29:24","slug":"protestan-contra-medidas-sanitarias-para-frenar-el-covid-19","status":"publish","type":"post","link":"https:\/\/bambapolitica.com.mx\/index.php\/2020\/12\/20\/protestan-contra-medidas-sanitarias-para-frenar-el-covid-19\/","title":{"rendered":"Protestan contra medidas sanitarias para frenar el Covid-19"},"content":{"rendered":"\n<p>A pesar de los miles de muertos por la covid en nuestro pa\u00eds y m\u00e1s de un mill\u00f3n de contagiados, esta ma\u00f1ana, sali\u00f3 a protestar un reducido grupo de personas que rechazan la vacuna obligatoria contra esta enfermedad de origen chino.<\/p>\n\n\n\n<p>La concentraci\u00f3n fue a las 10 de la ma\u00f1ana en la Estela de Luz y tambi\u00e9n exig\u00edan que cesar\u00e1n las medidas sanitarias contra la Pandemia.<\/p>\n\n\n\n<p>En su marcha al \u00c1ngel de la Independencia exhibieron cartulinas y mantas que dec\u00edan:<\/p>\n\n\n\n<p>\u2013 Alto a la vacuna obligatoria.<br>\u2013 Alto a la nueva normalidad.<br>\u2013 Alto a la imposici\u00f3n del cubre bocas.<br>\u2013 Alto a las pruebas diagnostica \u201cPCR\u201d, ya que no funcionan.<br>\u2013 Implementaci\u00f3n del di\u00f3xido de cloro, en hospitales como cura del Covid-19.<\/p>\n\n\n\n<p>Adem\u00e1s, tambi\u00e9n estaban contra de las medidas sanitarias implementadas por las autoridades, para frenar el corona virus Covid-19, por considerarlas \u00abinnecesarias y violatorias de las garant\u00edas individuales\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A pesar de los miles de muertos por la covid en nuestro pa\u00eds y m\u00e1s&#8230;<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-14871","post","type-post","status-publish","format-standard","hentry","category-noticias-del-dia"],"_links":{"self":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/14871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=14871"}],"version-history":[{"count":1,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/14871\/revisions"}],"predecessor-version":[{"id":14891,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/14871\/revisions\/14891"}],"wp:attachment":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=14871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=14871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=14871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}