{"id":14944,"date":"2020-12-21T15:29:21","date_gmt":"2020-12-21T21:29:21","guid":{"rendered":"http:\/\/bambapolitica.com.mx\/?p=14944"},"modified":"2020-12-21T15:29:24","modified_gmt":"2020-12-21T21:29:24","slug":"pese-a-semaforo-rojo-el-centro-historico-continua-conglomerado-cmdx","status":"publish","type":"post","link":"https:\/\/bambapolitica.com.mx\/index.php\/2020\/12\/21\/pese-a-semaforo-rojo-el-centro-historico-continua-conglomerado-cmdx\/","title":{"rendered":"Pese a sem\u00e1foro rojo, el Centro Hist\u00f3rico contin\u00faa conglomerado: CMDX"},"content":{"rendered":"\n<p>A 3 d\u00edas del decreto del sem\u00e1foro rojo en la CDMX, el Centro Hist\u00f3rico contin\u00faa aglomerado en temporada navide\u00f1a.<br>M\u00e9xico.- A tres d\u00edas de que la CDMX decretara la entrada en vigor del color rojo en el Sem\u00e1foro de Alerta Covid-19, el Centro Hist\u00f3rico contin\u00faa aglomerado por la circulaci\u00f3n de personas que lo visitan para adquirir productos durante la temporada decembrina.<\/p>\n\n\n\n<p>De acuerdo con el reporte de Noticieros Televisa, la congesti\u00f3n de personas se registra en calles como Mixcalco, Joaqu\u00edn Herrera y Miguel Hidalgo hasta Rep\u00fablica de Venezuela pese a la presencia de polic\u00edas de la CDMX quienes colocaron vallas met\u00e1licas para impedir la instalaci\u00f3n de comercio ambulante sin \u00e9xito.<\/p>\n\n\n\n<p>El Gobierno de la CDMX anunci\u00f3 la implementaci\u00f3n del sem\u00e1foro rojo a partir del 19 de diciembre y hasta el 10 de enero de 2021 por lo cual todas las actividades no esenciales quedar\u00edan cerradas, mismas de las cuales queda excluido el comercio, con el objetivo de no saturar los servicios sanitarios en el Valle de M\u00e9xico.<\/p>\n\n\n\n<p>A pesar de ello, nada de esto fue impedimento para que miles de personas se dieran cita el fin de semana y este lunes 21 de diciembre en el Centro Hist\u00f3rico con el objetivo de adquirir mercanc\u00eda previa a las celebraciones de Nochebuena y Navidad, aunque el llamado de las autoridades ha sido a evitar los festejos y permanecer en casa.<\/p>\n\n\n\n<p>CDMX registra 290 mil casos de Covid-19 al 20 de diciembre<br>Hasta el 20 de diciembre, la CDMX reportaba 290 mil casos confirmados de coronavirus (Covid-19) en la capital, de los que 35 mil 867 permanecen activos, adem\u00e1s se reportan 20 mil 33 defunciones, lo que significa 107 muertes m\u00e1s con respecto al d\u00eda previo.<\/p>\n\n\n\n<p>En lo que se refiere a la hospitalizaci\u00f3n, se registran 5 mil 89 camas ocupadas que representan el 72 por ciento de la ocupaci\u00f3n hospitalaria, donde 3 mil 747 est\u00e1n en camas generales y mil 342 en camas con ventilador. Adicional a ello, el 30 por ciento de los pacientes son for\u00e1neos: 29 por ciento provienen del Estado de M\u00e9xico y un uno por ciento de otras entidades.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A 3 d\u00edas del decreto del sem\u00e1foro rojo en la CDMX, el Centro Hist\u00f3rico contin\u00faa&#8230;<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-14944","post","type-post","status-publish","format-standard","hentry","category-noticias-del-dia"],"_links":{"self":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/14944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=14944"}],"version-history":[{"count":1,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/14944\/revisions"}],"predecessor-version":[{"id":14946,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/14944\/revisions\/14946"}],"wp:attachment":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=14944"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=14944"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=14944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}