{"id":16805,"date":"2021-01-26T13:01:41","date_gmt":"2021-01-26T19:01:41","guid":{"rendered":"http:\/\/bambapolitica.com.mx\/?p=16805"},"modified":"2021-01-26T13:01:42","modified_gmt":"2021-01-26T19:01:42","slug":"donald-trump-que-va-a-pasar-ahora-con-el-expresidente-y-el-trumpismo","status":"publish","type":"post","link":"https:\/\/bambapolitica.com.mx\/index.php\/2021\/01\/26\/donald-trump-que-va-a-pasar-ahora-con-el-expresidente-y-el-trumpismo\/","title":{"rendered":"Donald Trump: qu\u00e9 va a pasar ahora con el expresidente y el &#8220;trumpismo&#8221;"},"content":{"rendered":"\n<p>Donald Trump abord\u00f3 el Air Force One por \u00faltima vez el mi\u00e9rcoles diciendo adi\u00f3s.<\/p>\n\n\n\n<p>Mientras se escuchaba &#8220;A mi manera&#8221;, de Frank Sinatra, a todo volumen en los altavoces en la Base A\u00e9rea Andrews, el que pronto ser\u00eda ya expresidente parti\u00f3 rumbo a su nuevo hogar en Florida.<\/p>\n\n\n\n<p>Aunque acababa de prometer a una peque\u00f1a multitud de seguidores que volver\u00eda &#8220;de alguna forma&#8221;, el futuro de Trump y del movimiento pol\u00edtico que lo condujo a la victoria en 2016 se ve turbio.<\/p>\n\n\n\n<p>Hace apenas dos meses, parec\u00eda listo para encabezar una fuerza poderosa en la pol\u00edtica estadounidense, incluso despu\u00e9s de su derrota en noviembre.<\/p>\n\n\n\n<p>Todav\u00eda era querido por los republicanos, temido y respetado por los pol\u00edticos de ese partido y visto positivamente por casi la mitad de los estadounidenses, seg\u00fan encuestas de opini\u00f3n p\u00fablica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Donald Trump abord\u00f3 el Air Force One por \u00faltima vez el mi\u00e9rcoles diciendo adi\u00f3s. Mientras&#8230;<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-16805","post","type-post","status-publish","format-standard","hentry","category-internacional"],"_links":{"self":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/16805","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=16805"}],"version-history":[{"count":1,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/16805\/revisions"}],"predecessor-version":[{"id":16808,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/16805\/revisions\/16808"}],"wp:attachment":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=16805"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=16805"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=16805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}