{"id":22671,"date":"2021-04-28T10:27:03","date_gmt":"2021-04-28T16:27:03","guid":{"rendered":"http:\/\/bambapolitica.com.mx\/?p=22671"},"modified":"2021-04-28T10:27:06","modified_gmt":"2021-04-28T16:27:06","slug":"habilitan-mas-espacios-para-cremaciones-por-covid-19-en-india","status":"publish","type":"post","link":"https:\/\/bambapolitica.com.mx\/index.php\/2021\/04\/28\/habilitan-mas-espacios-para-cremaciones-por-covid-19-en-india\/","title":{"rendered":"Habilitan m\u00e1s espacios para cremaciones por covid-19 en India"},"content":{"rendered":"\n<p class=\"has-medium-font-size\">\u201cYa perd\u00ed la cuenta\u201d, suspir\u00f3 Sanjay, un sacerdote, al mismo tiempo que dio los \u00faltimos sacramentos de un en\u00e9simo difunto de covid-19 en un crematorio de Nueva Delhi, tan saturado que envi\u00f3 a v\u00edctimas hasta el estacionamiento de un estadio adyacente.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">&#8220;Comenzamos cuando sale el sol y las cremaciones contin\u00faan m\u00e1s all\u00e1 de la medianoche\u201d, explic\u00f3, con la mirada perdida en las llamas de las hogueras y en montones de cenizas, una escena que se repite desde la semana pasada ante la saturaci\u00f3n en los crematorios.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Las familias oran en silencio en el borde de la carretera, esperando el turno de la cremaci\u00f3n de sus familiares difuntos.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Las sirenas de las ambulancias que llevan otros cuerpos no dejan de sonar.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Los hospitales de India y su personal est\u00e1n rebasados y la gente muere en las puertas de los centros de salud o en sus hogares por falta de camas, medicamentos y ox\u00edgeno.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">En los \u00faltimos tres d\u00edas, el crematorio de Seemapuri, en el noreste de Nueva Delhi, ha organizado m\u00e1s de 100 funerales por d\u00eda y ya no tiene espacio.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">&#8220;Hemos tratado de acoger las cremaciones en los callejones y en todos los lugares en los que pod\u00edamos encontrar espacio, ahora edificios de departamentos y estacionamiento de estadios\u201d, detall\u00f3 el coordinador Jitender Singh Shanty, vestido con un traje de protecci\u00f3n azul y un turbante amarillo.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Ayer empez\u00f3 a llegar a India ayuda internacional. Reino Unido entreg\u00f3 suministros m\u00e9dicos y Estados Unidos inform\u00f3 el env\u00edo de compuestos para la producci\u00f3n de vacunas, equipos de protecci\u00f3n, pruebas de diagn\u00f3stico r\u00e1pido y ventiladores.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Familiares de muertos por covid-19 esperan su turno para cremar a las v\u00edctimas en hogueras montadas en espacios p\u00fablicos, como un estacionamiento de Nueva Delhi o condominios desocupados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cYa perd\u00ed la cuenta\u201d, suspir\u00f3 Sanjay, un sacerdote, al mismo tiempo que dio los \u00faltimos&#8230;<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-22671","post","type-post","status-publish","format-standard","hentry","category-internacional"],"_links":{"self":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/22671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=22671"}],"version-history":[{"count":1,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/22671\/revisions"}],"predecessor-version":[{"id":22673,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/22671\/revisions\/22673"}],"wp:attachment":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=22671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=22671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=22671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}