{"id":25082,"date":"2021-06-06T10:24:31","date_gmt":"2021-06-06T16:24:31","guid":{"rendered":"http:\/\/bambapolitica.com.mx\/?p=25082"},"modified":"2021-06-06T10:24:33","modified_gmt":"2021-06-06T16:24:33","slug":"hombres-destrozan-casillas-y-agreden-a-ciudadanos-durante-votaciones-en-metepec","status":"publish","type":"post","link":"https:\/\/bambapolitica.com.mx\/index.php\/2021\/06\/06\/hombres-destrozan-casillas-y-agreden-a-ciudadanos-durante-votaciones-en-metepec\/","title":{"rendered":"Hombres destrozan casillas y agreden a ciudadanos durante votaciones en Metepec"},"content":{"rendered":"\n<p class=\"has-medium-font-size\">\u201cTodos ten\u00edan gorras, sudaderas y cubrebocas. Llegaron a voltear las mesas, voltear las urnas, seg\u00fan yo no se llevaron ning\u00fan paquete&#8221;: testigo.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Un grupo de aproximadamente 20 personas irrumpieron en la casilla n\u00famero 2491, ubicada en la unidad habitacional, L\u00e1zaro C\u00e1rdenas, de Metepec donde los sujetos destrozaron diferentes casillas y golpearon a algunas personas formadas para emitir su voto. <\/p>\n\n\n\n<p class=\"has-medium-font-size\">Los hechos ocurrieron aproximadamente a las 09:40 horas cuando los presuntos agresores arribaron a esta casilla en un veh\u00edculo blanco Spark y otros m\u00e1s a pie con gorras y cubrebocas con la intenci\u00f3n de impedir que la jornada electoral se realice.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/bambapolitica.com.mx\/wp-content\/uploads\/2021\/06\/votaciones-en-metepec-1024x683.jpeg\" alt=\"\" class=\"wp-image-25084\"\/><\/figure>\n\n\n\n<p class=\"has-medium-font-size\">A pesar del arribo de las autoridades, los agresores huyeron del lugar. Las actividades se reanudaron media hora despu\u00e9s de los hechos. <\/p>\n\n\n\n<p class=\"has-medium-font-size\">De acuerdo con C\u00e9sar, uno de los testigos y v\u00edctimas de este hecho ya que result\u00f3 lesionado, precis\u00f3 que s\u00f3lo causaron desmanes y no hubo robo de papeler\u00eda electoral.<\/p>\n\n\n\n<figure class=\"wp-block-embed-twitter wp-block-embed is-type-rich is-provider-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\"><a href=\"https:\/\/twitter.com\/hashtag\/META21?src=hash&amp;ref_src=twsrc%5Etfw\">#META21<\/a> | Destrozan casillas y golpean a ciudadanos en votaciones de Metepec.<br>\u201cTodos ten\u00edan gorras, sudaderas y cubrebocas. Llegaron a voltear las mesas, voltear las urnas, seg\u00fan yo no se llevaron ning\u00fan paquete&quot;&#8230;<a href=\"https:\/\/t.co\/HfW1x5Geyo\">https:\/\/t.co\/HfW1x5Geyo<\/a><br>Video: Fabi\u00e1n Rodr\u00edguez <a href=\"https:\/\/t.co\/prLRLOE3Za\">pic.twitter.com\/prLRLOE3Za<\/a><\/p>&mdash; Milenio Estado de M\u00e9xico (@milenio_edomex) <a href=\"https:\/\/twitter.com\/milenio_edomex\/status\/1401572391440904195?ref_src=twsrc%5Etfw\">June 6, 2021<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"has-medium-font-size\"><strong>\u201cTodos ten\u00edan gorras, sudaderas y cubrebocas.&#8221;<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\">Llegaron aqu\u00ed a voltear las mesas, voltear las urnas, seg\u00fan yo vi no se llevaron ning\u00fan paquete pero s\u00ed ocasionaron muchos destrozos aqu\u00ed junto uno agresiones directas en contra de vecinos que se confrontaron, hirieron a una persona de la tercera edad que result\u00f3 golpeada\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/bambapolitica.com.mx\/wp-content\/uploads\/2021\/06\/votaciones-en-metepec-2-1024x683.jpeg\" alt=\"\" class=\"wp-image-25083\"\/><\/figure>\n\n\n\n<p class=\"has-medium-font-size\">Al sitio acudieron elementos de la Guardia Nacional, quienes inspeccionaron todo y despu\u00e9s de unos minutos se retiraron.<\/p>\n\n\n\n<figure class=\"wp-block-embed-twitter wp-block-embed is-type-rich is-provider-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\"><a href=\"https:\/\/twitter.com\/hashtag\/META21?src=hash&amp;ref_src=twsrc%5Etfw\">#META21<\/a> | La ma\u00f1ana de este domingo en Metepec fue quemada la lona de una casilla y reportan actos de violencia&#8230; <a href=\"https:\/\/t.co\/8ZIwh54YqA\">https:\/\/t.co\/8ZIwh54YqA<\/a><br>Video: Especial. <a href=\"https:\/\/t.co\/gzLnbbdTQC\">pic.twitter.com\/gzLnbbdTQC<\/a><\/p>&mdash; Milenio Estado de M\u00e9xico (@milenio_edomex) <a href=\"https:\/\/twitter.com\/milenio_edomex\/status\/1401555939858075652?ref_src=twsrc%5Etfw\">June 6, 2021<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u201cTodos ten\u00edan gorras, sudaderas y cubrebocas. Llegaron a voltear las mesas, voltear las urnas, seg\u00fan&#8230;<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-25082","post","type-post","status-publish","format-standard","hentry","category-noticias-del-dia"],"_links":{"self":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/25082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=25082"}],"version-history":[{"count":1,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/25082\/revisions"}],"predecessor-version":[{"id":25086,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/25082\/revisions\/25086"}],"wp:attachment":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=25082"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=25082"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=25082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}