{"id":38732,"date":"2021-12-15T07:44:25","date_gmt":"2021-12-15T13:44:25","guid":{"rendered":"http:\/\/bambapolitica.com.mx\/?p=38732"},"modified":"2021-12-15T07:44:27","modified_gmt":"2021-12-15T13:44:27","slug":"alcalde-electo-de-ocuilan-detenido-por-secuestro-fue-llevado-al-penal-de-tenancingo","status":"publish","type":"post","link":"https:\/\/bambapolitica.com.mx\/index.php\/2021\/12\/15\/alcalde-electo-de-ocuilan-detenido-por-secuestro-fue-llevado-al-penal-de-tenancingo\/","title":{"rendered":"Alcalde electo de Ocuilan detenido por secuestro; fue llevado al penal de Tenancingo"},"content":{"rendered":"\n<p class=\"has-medium-font-size\">Toluca, Estado de Mexico, 15 de diciembre de 2021.<\/p>\n\n\n\n<figure class=\"wp-block-video aligncenter\"><video controls src=\"https:\/\/bambapolitica.com.mx\/wp-content\/uploads\/2021\/12\/VID-20211214-WA0353-1.mp4\"><\/video><\/figure>\n\n\n\n<p class=\"has-medium-font-size\">La Fiscal\u00eda General de Justicia del Estado de M\u00e9xico (FGJEM) informa que esta tarde Polic\u00edas de Investigaci\u00f3n de esta Instituci\u00f3n cumplimentaron una orden de aprehensi\u00f3n en contra de Emilio \u201cN\u201d, quien recientemente tom\u00f3 protesta como Presidente Municipal de Ocuilan, y es investigado por su probable participaci\u00f3n en el delito de privaci\u00f3n ilegal de la libertad.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Este individuo fue detenido en la Ciudad de Cuernavaca, con apoyo de la Fiscal\u00eda de Morelos, posteriormente fue trasladado a territorio mexiquense en un veh\u00edculo blindado de la FGJEM en el cual fue ingresado al Centro Penitenciario y de Reinserci\u00f3n Social de Tenancingo, en cumplimiento del mandamiento judicial por el delito referido.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Emilio \u201cN\u201d qued\u00f3 a disposici\u00f3n de la Autoridad Judicial quien habr\u00e1 de determinar su situaci\u00f3n legal. Al detenido se le debe considerar inocente hasta que sea dictada una sentencia condenatoria en su contra.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Toluca, Estado de Mexico, 15 de diciembre de 2021. La Fiscal\u00eda General de Justicia del&#8230;<\/p>\n","protected":false},"author":4,"featured_media":38742,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-38732","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-del-dia"],"_links":{"self":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/38732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=38732"}],"version-history":[{"count":1,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/38732\/revisions"}],"predecessor-version":[{"id":38759,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/38732\/revisions\/38759"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media\/38742"}],"wp:attachment":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=38732"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=38732"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=38732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}