{"id":38733,"date":"2021-12-15T07:44:22","date_gmt":"2021-12-15T13:44:22","guid":{"rendered":"http:\/\/bambapolitica.com.mx\/?p=38733"},"modified":"2021-12-15T07:44:23","modified_gmt":"2021-12-15T13:44:23","slug":"canirac-abandona-a-patricia-yunes","status":"publish","type":"post","link":"https:\/\/bambapolitica.com.mx\/index.php\/2021\/12\/15\/canirac-abandona-a-patricia-yunes\/","title":{"rendered":"CANIRAC abandona a Patricia Yunes!!!"},"content":{"rendered":"\n<p class=\"has-medium-font-size\">Ten\u00eda que ser!!!<br>CANIRAC respeta el fallo del Tribunal Electoral en Veracruz: Marcel Van Eyck<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Respetamos los procedimientos legales, lo importante es coordinarnos bien con quien llegue.<\/li><\/ul>\n\n\n\n<p class=\"has-medium-font-size\">Veracruz, Ver. 15 diciembre 2021.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">La C\u00e1mara Nacional de la Industria Restaurantera y Alimentos Condimentados en Veracruz (CANIRAC) es apartidista y trabajar\u00e1 con quien sea el pr\u00f3ximo alcalde de Veracruz, manifest\u00f3 su presidente Marcel Van Eyck.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Entrevistado sobre la anulaci\u00f3n de la elecci\u00f3n a la alcald\u00eda de Veracruz que determin\u00f3 el Tribunal Electoral de Veracruz (TEV), al comprobar las m\u00faltiples ilegalidades en que incurri\u00f3 la candidata de la alianza del PAN-PRI-PRD, el l\u00edder empresarial precis\u00f3 que respetan la decisi\u00f3n de las autoridades electorales, no es competencia de la CANIRAC decir quien gan\u00f3 o a quien quieren como ganador.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Se dijo respetuoso de los procedimientos legales, pues eso est\u00e1 fuera del alcance de los organismos empresariales, pero como c\u00e1mara industrial gastron\u00f3mica ellos van a coordinarse y trabajar con quien sea alcalde de Veracruz.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">\u201cLo importante es trabajar bien, con quien llegue al cargo de alcalde, nosotros tenemos que trabajar con la persona que llega, el procedimiento est\u00e1 fuera de nuestro alcance y la postura de nuestra c\u00e1mara es que tenemos que trabajar no importa qui\u00e9n sea, nosotros somos apartidistas\u201d.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Insisti\u00f3 que como CANIRAC no pueden inclinarse por alg\u00fan partido o persona, pues son apartidistas.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">\u201cSi de un partido llega una persona o de otro llega la otra persona, nosotros tenemos que trabajar con esta persona que llegue\u201d, puntualiz\u00f3 Marcel Van Eyck.<\/p>\n\n\n\n<figure class=\"wp-block-audio aligncenter\"><audio controls src=\"https:\/\/bambapolitica.com.mx\/wp-content\/uploads\/2021\/12\/AUDIO-1.mp3\"><\/audio><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Ten\u00eda que ser!!!CANIRAC respeta el fallo del Tribunal Electoral en Veracruz: Marcel Van Eyck Respetamos&#8230;<\/p>\n","protected":false},"author":4,"featured_media":38745,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-38733","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-del-dia"],"_links":{"self":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/38733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=38733"}],"version-history":[{"count":1,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/38733\/revisions"}],"predecessor-version":[{"id":38758,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/38733\/revisions\/38758"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media\/38745"}],"wp:attachment":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=38733"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=38733"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=38733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}