{"id":39061,"date":"2021-12-20T08:26:06","date_gmt":"2021-12-20T14:26:06","guid":{"rendered":"http:\/\/bambapolitica.com.mx\/?p=39061"},"modified":"2021-12-20T08:26:08","modified_gmt":"2021-12-20T14:26:08","slug":"la-izquierda-latinoamericana-celebra-el-ascenso-de-gabriel-boric-a-la-presidencia-de-chile","status":"publish","type":"post","link":"https:\/\/bambapolitica.com.mx\/index.php\/2021\/12\/20\/la-izquierda-latinoamericana-celebra-el-ascenso-de-gabriel-boric-a-la-presidencia-de-chile\/","title":{"rendered":"La izquierda latinoamericana celebra el ascenso de Gabriel Boric a la Presidencia de Chile"},"content":{"rendered":"\n<p class=\"has-medium-font-size\">Maduro pone en valor el \u00e9xito de Boric frente al &#8220;fascismo&#8221; de Kast y D\u00edaz-Canel celebra la &#8220;victoria popular&#8221; en Chile<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Los l\u00edderes de izquierda de naciones latinoamericanas han celebrado la victoria de Gabriel Boric en la segunda vuelta de las elecciones presidenciales de Chile al superar al candidato ultraderechista Jos\u00e9 Antonio Kast con un 55,8 por ciento de los votos.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">La izquierda latinoamericana celebra el ascenso de Gabriel Boric a la Presidencia de Chile As\u00ed, desde la naci\u00f3n vecina Argentina, el presidente Alberto Fern\u00e1ndez ha apuntado a la colaboraci\u00f3n con el nuevo mandatario para &#8220;fortalecer los lazos&#8221; que unen a ambos pa\u00edses y combatir la &#8220;desigualdad&#8221; que azota Am\u00e9rica Latina. Leer m\u00e1s: https:\/\/www.europapress.es\/internacional\/noticia-izquierda-latinoamericana-celebra-ascenso-gabriel-boric-presidencia-chile-20211220052807.html (c) 2021 Eu \u2026<\/p>\n\n\n\n<p class=\"has-medium-font-size\">De este modo, Fern\u00e1ndez se ha unido a las palabras de la vicepresidenta argentina, Cristina Fern\u00e1ndez, quien previamente hab\u00eda trasladado sus felicitaciones a Boric y hab\u00eda expresado que &#8220;el pueblo siempre vuelve&#8221;.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Asimismo, desde Bolivia el presidente Luis Arce ha celebrado la victoria del candidato de Apruebo Dignidad al representar tambi\u00e9n &#8220;el triunfo del pueblo chileno&#8221; y el fortalecimiento de la democracia latinoamericana.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">&#8220;La democracia latinoamericana se fortalece con base en la unidad, el respeto y, sobre todo, la voluntad de nuestro pueblos&#8221;, ha expresado Arce en su perfil de Twitter.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">En la misma l\u00ednea, el mandatario venezolano, Nicol\u00e1s Maduro, ha recordado figuras como el expresidente chileno Salvador Allende o el m\u00fasico V\u00edctor Jara, y ha puesto en valor la &#8220;contundente victoria sobre el fascismo&#8221;, en alusi\u00f3n a Kast.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Desde la isla de Cuba, el presidente, Miguel D\u00edaz-Canel, ha ratificado la voluntad de &#8220;ampliar las relaciones bilaterales y de cooperaci\u00f3n&#8221; entre ambos pueblos y gobiernos tras el \u00e9xito de Boric en las presidenciales.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Con la misma idea de seguir &#8220;bregando por la unidad&#8221; de sus pueblos, el mandatario peruano, Pedro Castillo, se ha mostrado satisfecho por la elecci\u00f3n de Boric como presidente electo de Chile.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">&#8220;La victoria que has alcanzado es la del pueblo chileno y la compartimos los pueblos latinoamericanos que queremos vivir con libertad, paz, justicia y dignidad&#8221;, ha se\u00f1alado Castillo en sus redes sociales.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">A las felicitaciones se han sumado el presidente y la vicepresidenta de Nicaragua, Daniel Ortega y Rosario Murillo, respectivamente, quienes han destacado el &#8220;hist\u00f3rico triunfo&#8221; de Boric, tal y como ha recogido la cadena de televisi\u00f3n TeleSur.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">As\u00ed, han dicho que ha sido &#8220;alcanzado con el valiente pueblo chileno, inspirados con el legado siempre presente del presidente de la dignidad, Salvador Allende, y de tantos h\u00e9roes y m\u00e1rtires de ese gran pueblo&#8221;. De esta forma, han deseado a Chile &#8220;caminos de avance en esperanzas ciertas, creando los cambios que se proponen, en justicia y paz&#8221;.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">La victoria ha sido igualmente aplaudida por expresidentes como el ecuatoriano Rafael Correa, el boliviano Evo Morales y el brasile\u00f1o Luis In\u00e1cio Lula da Silva, quienes han recurrido a sus redes sociales para ello.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">&#8220;Saludamos la vocaci\u00f3n democr\u00e1tica del hermano pueblo chileno y felicitamos a Gabriel Boric por su triunfo&#8221;, ha dicho Morales. &#8220;\u00a1Gabriel Boric, nuevo presidente de Chile! \u00a1Viva Chile! \u00a1Viva la Patria Grande! \u00a1Hasta la victoria siempre!&#8221;, ha manifestado Correa.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Lula da Silva ha publicado en Twitter una fotograf\u00eda suya con una gorra en apoyo a Boric y ha trasladado sus felicitaciones al &#8220;compa\u00f1ero&#8221; por su victoria en Chile. &#8220;Me alegro por otra victoria de un candidato democr\u00e1tico y progresista en nuestra Am\u00e9rica Latina, para la construcci\u00f3n de un futuro mejor para todos&#8221;, ha valorado.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Por su parte, el Grupo de Puebla &#8211;integrado por representantes de la izquierda pol\u00edtica latinoamericana y fundado en 2019&#8211; ha destacado a trav\u00e9s de un comunicado publicado en su p\u00e1gina web que &#8220;el triunfo del presidente Boric es del pueblo chileno y de todo el progresismo latinoamericano&#8221;.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">&#8220;Su llegada al gobierno confirma la tendencia progresista que vive la regi\u00f3n y que se expresa en la necesidad de un nuevo modelo de desarrollo econ\u00f3mico, m\u00e1s solidario y democr\u00e1tico, el fortalecimiento del Estado en \u00e1reas relacionadas con bienes y servicios sociales como la salud, la educaci\u00f3n y la alimentaci\u00f3n y en especial, en la exigencia inaplazable de volver a poner en marcha los mecanismos de integraci\u00f3n regional para hacer frente a la pandemia&#8221;, ha apuntado en un comunicado.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">De esta forma, ha arg\u00fcido que &#8220;el triunfo de Boric abre adem\u00e1s nuevos espacios pol\u00edticos para el pronunciamiento de fuerzas progresistas en las elecciones de Brasil y Colombia el a\u00f1o entrante&#8221;.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">&#8220;Con la reactivaci\u00f3n econ\u00f3mica, la reconstrucci\u00f3n del tejido social y el regreso a la plena vigencia democr\u00e1tica a trav\u00e9s de la Convenci\u00f3n Constitucional, se abre paso un futuro de uni\u00f3n para Chile y se entierra parte de su ingrato pasado&#8221;, ha remachado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Maduro pone en valor el \u00e9xito de Boric frente al &#8220;fascismo&#8221; de Kast y D\u00edaz-Canel&#8230;<\/p>\n","protected":false},"author":4,"featured_media":39071,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-39061","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional"],"_links":{"self":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/39061","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=39061"}],"version-history":[{"count":1,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/39061\/revisions"}],"predecessor-version":[{"id":39072,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/39061\/revisions\/39072"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media\/39071"}],"wp:attachment":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=39061"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=39061"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=39061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}