{"id":39076,"date":"2021-12-20T08:38:05","date_gmt":"2021-12-20T14:38:05","guid":{"rendered":"http:\/\/bambapolitica.com.mx\/?p=39076"},"modified":"2021-12-20T08:38:07","modified_gmt":"2021-12-20T14:38:07","slug":"jlo-habla-por-fin-de-las-polemica-declaraciones-de-ben-affleck-contra-su-ex","status":"publish","type":"post","link":"https:\/\/bambapolitica.com.mx\/index.php\/2021\/12\/20\/jlo-habla-por-fin-de-las-polemica-declaraciones-de-ben-affleck-contra-su-ex\/","title":{"rendered":"JLo habla por fin de las pol\u00e9mica declaraciones de Ben Affleck contra su ex"},"content":{"rendered":"\n<p class=\"has-medium-font-size\">Ben Affleck se puso a s\u00ed mismo sin pretenderlo en el centro de una delicada pol\u00e9mica cuando asegur\u00f3 que hab\u00eda empezado a beber de nuevo mientras a\u00fan estaba casado con Jennifer Garner.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Hace unos d\u00edas Ben Affleck se puso a s\u00ed mismo sin pretenderlo en el centro de una delicada pol\u00e9mica cuando asegur\u00f3 que hab\u00eda empezado a beber de nuevo mientras a\u00fan estaba casado con Jennifer Garner, la mam\u00e1 de sus tres hijos, porque se sent\u00eda &#8220;atrapado e infeliz&#8221; y decidi\u00f3 refugiarse en una botella.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Muchos interpretaron estas declaraciones, que realiz\u00f3 durante una entrevista con Howard Stern, como un ataque directo a su ex al culparla aparentemente de su reca\u00edda, lo cual provoc\u00f3 que le llovieran un sinf\u00edn de cr\u00edticas y que todas las miradas se fijaran en su actual pareja, Jennifer Lopez, para tratar de adivinar qu\u00e9 opinaba ella al respecto.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Los rumores afirmaban que estaba decepcionada y furiosa con el actor por su falta de tacto, pero ahora ella quiso dejar bien claro que ese no es el caso. &#8220;Esta historia simplemente no es cierta. No es lo que pienso. No podr\u00eda sentir m\u00e1s respeto por Ben como padre, como padre separado y persona&#8221;, afirm\u00f3 a la revista People.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">El propio int\u00e9rprete afirm\u00f3 posteriormente que estaba sorprendido y dolido por la manera en que se hab\u00edan sacado de contexto los comentarios que realiz\u00f3 en un momento de sinceridad porque jam\u00e1s querr\u00eda que sus hijos pensaran que hab\u00eda hablado mal en p\u00fablico de su mam\u00e1.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">&#8220;Era una conversaci\u00f3n de dos horas y la gente se centr\u00f3 solo en una parte, para que pareciera que hab\u00eda dicho justo lo contrario de lo que dije. Hab\u00eda estado hablando de lo mucho que nos respet\u00e1bamos y de c\u00f3mo nos preocup\u00e1bamos el uno por el otro y nos preocup\u00e1bamos por nuestros hijos y los antepon\u00edamos a todo lo dem\u00e1s. Y tambi\u00e9n de c\u00f3mo superamos nuestros problemas&#8221;, afirm\u00f3 en el programa de Jimmy Kimmel.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ben Affleck se puso a s\u00ed mismo sin pretenderlo en el centro de una delicada&#8230;<\/p>\n","protected":false},"author":4,"featured_media":39078,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-39076","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espectaculos"],"_links":{"self":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/39076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=39076"}],"version-history":[{"count":1,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/39076\/revisions"}],"predecessor-version":[{"id":39079,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/39076\/revisions\/39079"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media\/39078"}],"wp:attachment":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=39076"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=39076"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=39076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}