{"id":39788,"date":"2022-01-05T09:37:37","date_gmt":"2022-01-05T15:37:37","guid":{"rendered":"http:\/\/bambapolitica.com.mx\/?p=39788"},"modified":"2022-01-05T10:35:28","modified_gmt":"2022-01-05T16:35:28","slug":"se-incrementara-la-aplicacion-de-las-pruebas-rapidas-para-atencion-de-covid-19-en-el-edomex","status":"publish","type":"post","link":"https:\/\/bambapolitica.com.mx\/index.php\/2022\/01\/05\/se-incrementara-la-aplicacion-de-las-pruebas-rapidas-para-atencion-de-covid-19-en-el-edomex\/","title":{"rendered":"Se incrementara la aplicaci\u00f3n de las pruebas r\u00e1pidas para atenci\u00f3n de Covid-19 en el Edom\u00e9x"},"content":{"rendered":"\n<p class=\"has-medium-font-size\">Toluca, Estado de M\u00e9xico, 5 de enero de 2022. <\/p>\n\n\n\n<p class=\"has-medium-font-size\">La Secretar\u00eda de Salud, a trav\u00e9s del Instituto de Salud del Estado de M\u00e9xico (ISEM), ha determinado incrementar y llevar a cabo el diagn\u00f3stico de Covid-19 con la aplicaci\u00f3n de pruebas r\u00e1pidas en las unidades hospitalarias designadas para la atenci\u00f3n de casos y que cuentan con triage respiratorio.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">La dependencia precisa que inicialmente se habilitaron 164 m\u00f3dulos en toda la entidad y al avanzar en el sem\u00e1foro epidemiol\u00f3gico a color verde, est\u00e1s fueron disminuyendo, actualmente se tienen en operaci\u00f3n 71 m\u00f3dulos para pruebas r\u00e1pidas ubicados en unidades hospitalarias del Sector Salud.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Se inform\u00f3, que en breve se habilitar\u00e1n un mayor n\u00famero de m\u00f3dulos para incrementar el n\u00famero de pruebas; en este momento se realizan 800 diarias en promedio y la positividad aument\u00f3 de 3.8 a 8 en las \u00faltimas dos semanas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Toluca, Estado de M\u00e9xico, 5 de enero de 2022. La Secretar\u00eda de Salud, a trav\u00e9s&#8230;<\/p>\n","protected":false},"author":4,"featured_media":39789,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-39788","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-del-dia"],"_links":{"self":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/39788","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=39788"}],"version-history":[{"count":3,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/39788\/revisions"}],"predecessor-version":[{"id":39794,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/39788\/revisions\/39794"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media\/39789"}],"wp:attachment":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=39788"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=39788"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=39788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}