{"id":53065,"date":"2022-11-19T10:27:00","date_gmt":"2022-11-19T16:27:00","guid":{"rendered":"http:\/\/bambapolitica.com.mx\/?p=53065"},"modified":"2022-11-17T10:28:52","modified_gmt":"2022-11-17T16:28:52","slug":"que-es-el-indice-de-progreso-social-y-por-que-edomex-presenta-contracciones-en-el-rubro","status":"publish","type":"post","link":"https:\/\/bambapolitica.com.mx\/index.php\/2022\/11\/19\/que-es-el-indice-de-progreso-social-y-por-que-edomex-presenta-contracciones-en-el-rubro\/","title":{"rendered":"\u00bfQu\u00e9 es el \u00cdndice de Progreso Social y por qu\u00e9 Edomex presenta contracciones en el rubro?"},"content":{"rendered":"\n<p>sabado, 19 de noviembre de 2022<\/p>\n\n\n\n<p>El Estado de M\u00e9xico es una de las 30 entidades del pa\u00eds que durante el periodo de 2018 a 2021 han presentado una contracci\u00f3n.<\/p>\n\n\n\n<p>El Estado de M\u00e9xico es una de las 30 entidades del pa\u00eds que durante el periodo de 2018 a 2021 han presentado una contracci\u00f3n en los puntajes de progreso social, registrando para 2021 una calificaci\u00f3n de 61.7, la entidad mejor evaluada fue la Ciudad de M\u00e9xico, que presenta una calificaci\u00f3n de 73.1. El \u00cdndice de Progreso Social (IPS) es una medici\u00f3n hol\u00edstica del desempe\u00f1o social de un pa\u00eds que es independiente de factores econ\u00f3micos, dio a conocer la directora general de la organizaci\u00f3n M\u00e9xico \u00bfC\u00f3mo vamos?, Sof\u00eda Ram\u00edrez Aguilar, durante la presentaci\u00f3n del informe \u201cEl progreso social en M\u00e9xico \u00bfHacia d\u00f3nde vamos? La merma en el bienvivir de 2018 a la fecha\u2026 y una salida por medio de la apertura comercial\u201d. Explic\u00f3 que el \u00edndice est\u00e1 basado en un rango de indicadores sociales y ambientales que capturan tres dimensiones del progreso social: Necesidades Humanas B\u00e1sicas. Fundamentos del Bienestar. Oportunidades. Esto toma valores entre 0 y 100, donde 0 es el menor progreso social posible y 100 el m\u00e1ximo progreso social posible. Para esta edici\u00f3n el progreso social se calcul\u00f3 a trav\u00e9s de los indicadores que emite el Instituto Nacional de Estad\u00edstica y Geograf\u00eda (Inegi), entre otros datos oficiales, que tienen que ver con enfoques ambientales, sociales, pol\u00edticas p\u00fablicas e intervenciones sociales. Edomex Durante el periodo caracterizado por la pandemia de covid-19, es decir, los a\u00f1os 2020-2021, el Estado de M\u00e9xico perdi\u00f3 2.03 puntos en este indicador, ubic\u00e1ndose entre las ocho entidades con las mayores variaciones en el puntaje; en primer lugar se ubica Veracruz con una reducci\u00f3n de 4.18, le sigue Oaxaca con 3.31; Puebla con 2.87; Hidalgo 2.75; Campeche, 2.66; Chiapas, 2.45 y Durango con 2.37. En el caso del Estado de M\u00e9xico durante 2021 se present\u00f3 el \u00edndice m\u00e1s bajo, con 61.7; mientras que el registro m\u00e1s alto se dio en 2018 con 66.2. El indicador mejor evaluado fue el de la Vivienda con 94.5, mientras que en Fundamentos del Bienestar se obtuvo 63.4; Seguridad Personal, 48.8 y en el Acceso a conocimientos b\u00e1sicos fue de 35.4. Datos nacionales A nivel nacional el puntaje del \u00cdndice de Progreso Social (IPS) en 2021 en M\u00e9xico se ubic\u00f3 en 63, lo que lo coloca como el segundo peor a\u00f1o desde que se tiene registro; \u00fanicamente en 2015 se observa un peor puntaje, lo que significa un retroceso en el progreso social observado en el pa\u00eds en los \u00faltimos seis a\u00f1os. El progreso social se correlaciona positivamente con la escolaridad promedio, el PIB per c\u00e1pita, el acceso a atenci\u00f3n m\u00e9dica, y la apertura o dinamismo comercial de la entidad, esta \u00faltima de manera limitada por la infraestructura de cada estado. Recomendaciones Para mejorar el progreso social, se detall\u00f3, es necesario incorporar a m\u00e1s personas a los servicios de salud p\u00fablica e implementar un programa transitorio que evite el aumento de la poblaci\u00f3n en situaci\u00f3n de pobreza extrema por la alta inflaci\u00f3n. Una prioridad del gobierno, se a\u00f1adi\u00f3, debe ser ampliar la poblaci\u00f3n que tiene acceso a atenci\u00f3n m\u00e9dica no \u00fanicamente de emergencia, sino favoreciendo el cuidado preventivo y robusteciendo el esquema de vacunaci\u00f3n tanto de la primera infancia como de la poblaci\u00f3n en general. Por otra parte debe atenderse el aumento m\u00e1s que proporcional en los precios de los alimentos, as\u00ed como de la persistente y elevada inflaci\u00f3n generalizada que enfrentan de manera desigual las entidades de la rep\u00fablica. Una posible pol\u00edtica p\u00fablica para evitar que m\u00e1s personas no tengan acceso a los alimentos b\u00e1sicos es un programa social temporal y focalizado que consista en la transferencia mensual del valor de una canasta alimentaria para los 10.8 millones de personas en situaci\u00f3n de pobreza extrema identificadas por el Consejo Nacional de Evaluaci\u00f3n de la Pol\u00edtica de Desarrollo Social (Coneval) en 2020.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>sabado, 19 de noviembre de 2022 El Estado de M\u00e9xico es una de las 30&#8230;<\/p>\n","protected":false},"author":3,"featured_media":53066,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-53065","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-del-dia"],"_links":{"self":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/53065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=53065"}],"version-history":[{"count":1,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/53065\/revisions"}],"predecessor-version":[{"id":53067,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/53065\/revisions\/53067"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media\/53066"}],"wp:attachment":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=53065"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=53065"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=53065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}