{"id":55956,"date":"2023-02-01T08:34:06","date_gmt":"2023-02-01T14:34:06","guid":{"rendered":"http:\/\/bambapolitica.com.mx\/?p=55956"},"modified":"2023-02-01T08:34:08","modified_gmt":"2023-02-01T14:34:08","slug":"profesores-del-movimiento-educativo-revolucionario-flores-magon-merfm-senalaron-que-realizaran-una-marcha-sobre-la-autopista-mexico","status":"publish","type":"post","link":"https:\/\/bambapolitica.com.mx\/index.php\/2023\/02\/01\/profesores-del-movimiento-educativo-revolucionario-flores-magon-merfm-senalaron-que-realizaran-una-marcha-sobre-la-autopista-mexico\/","title":{"rendered":"Profesores del Movimiento Educativo Revolucionario Flores Mag\u00f3n (MERFM) se\u00f1alaron que realizar\u00e1n una marcha sobre la autopista M\u00e9xico"},"content":{"rendered":"\n<p>Mi\u00e9rcoles , 1 Febrero de 2023<\/p>\n\n\n\n<p>Profesores del Movimiento Educativo Revolucionario Flores Mag\u00f3n (MERFM) se\u00f1alaron que realizar\u00e1n una marcha sobre la autopista M\u00e9xico &#8211; Puebla en los pr\u00f3ximos d\u00edas para exigir a las autoridades del a Secretaria de Educaci\u00f3n del Estado de M\u00e9xico la incorporaci\u00f3n de la clave de trabajo de las once escuelas ubicadas en el municipio de Chalco, el registro de los mil 600 alumnos de los diferentes niveles escolares a la plataforma de la secretaria, as\u00ed como la basificaci\u00f3n de los profesores de las distintas escuelas as\u00ed como la entrega de libros de texto a los alumnos.<\/p>\n\n\n\n<p><br>Los profesores del Movimiento Educativo se\u00f1alaron que desde hace varios meses han buscado a las autoridades estatales para que les dieran soluci\u00f3n a su pliego petitorio, pero no han logrado avanzar, &#8221; desde diciembre quedaron de apoyarnos con los estudiantes e integrarlos a la plataforma, lo de las claves de trabajo, la basificaci\u00f3n y pago de los profesores y los \u00fatiles y libros de texto, nos dijeron que el 20 de enero y hoy el \u00faltimo d\u00eda de enero y no tenemos respuesta favorable por parte de las autoridades de educaci\u00f3n, hoy nos dicen que no es posible porque no hay los recursos&#8221;.<\/p>\n\n\n\n<p><br>Agregaron que est\u00e1s medidas de marchas por la autopista y acudir a Toluca con los padres de familia, alumnos y docentes es para que les den una respuesta, &#8220;esto no es un movimiento politico, lo que queremos es las plazas de profesores, basificaci\u00f3n, reconocimiento de las escuelas y de los mil 600 alumnos que estudian con nosotros&#8221;.<\/p>\n\n\n\n<p><br>Aseguraron que sus demandas son justas de ido a qu\u00e9 los once centros escolares ya est\u00e1n edificados, solo requieren la clave de trabajo y el pago de salarios para los profesores.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mi\u00e9rcoles , 1 Febrero de 2023 Profesores del Movimiento Educativo Revolucionario Flores Mag\u00f3n (MERFM) se\u00f1alaron&#8230;<\/p>\n","protected":false},"author":3,"featured_media":55957,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-55956","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-del-dia"],"_links":{"self":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/55956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=55956"}],"version-history":[{"count":1,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/55956\/revisions"}],"predecessor-version":[{"id":55958,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/55956\/revisions\/55958"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media\/55957"}],"wp:attachment":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=55956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=55956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=55956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}