{"id":56004,"date":"2023-02-01T09:56:11","date_gmt":"2023-02-01T15:56:11","guid":{"rendered":"http:\/\/bambapolitica.com.mx\/?p=56004"},"modified":"2023-02-03T09:28:14","modified_gmt":"2023-02-03T15:28:14","slug":"uruguay-repite-como-el-pais-con-menos-corrupcion-de-latinoamerica","status":"publish","type":"post","link":"https:\/\/bambapolitica.com.mx\/index.php\/2023\/02\/01\/uruguay-repite-como-el-pais-con-menos-corrupcion-de-latinoamerica\/","title":{"rendered":"Uruguay repite como el pa\u00eds con menos corrupci\u00f3n de Latinoam\u00e9rica"},"content":{"rendered":"\n<p>Viernes , 3 Febrero de 2023<\/p>\n\n\n\n<p>Uruguay se posicion\u00f3 en el \u00cdndice de Percepci\u00f3n de la Corrupci\u00f3n (IPC) 2022 por encima de Francia, Jap\u00f3n, Reino Unido y Estados Unidos+<br>Con un punto m\u00e1s que en 2021 y en un puesto compartido con Canad\u00e1, Uruguay volvi\u00f3 a posicionarse como el pa\u00eds con menos corrupci\u00f3n de Latinoam\u00e9rica, seg\u00fan el \u00cdndice de Percepci\u00f3n de la Corrupci\u00f3n (IPC) de 2022 que divulg\u00f3 este martes la organizaci\u00f3n Transparencia Internacional.<br>Ubicado en el und\u00e9cimo lugar del escalaf\u00f3n mundial con 74 puntos sobre 100, un puntaje que comparte con Canad\u00e1, Estonia e Islandia, el pa\u00eds sudamericano se posicion\u00f3 en el IPC por encima de naciones como Francia, Jap\u00f3n, Reino Unido y Estados Unidos.<\/p>\n\n\n\n<p>Uruguay, que en 2021 escal\u00f3 dos unidades respecto al listado de 2020 para ubicarse ya como el latinoamericano con menores niveles de corrupci\u00f3n en el \u00edndice presentado anualmente por Transparencia Internacional, super\u00f3 nuevamente a Chile, segundo m\u00e1s avanzado de la regi\u00f3n, por siete puntos.<\/p>\n\n\n\n<p>En el informe, Transparencia Internacional destac\u00f3 que los pa\u00edses con \u201cinstituciones fuertes\u201d y \u201cdemocracias en buen funcionamiento\u201d suelen encontrarse a la cabeza del IPC, a lo que las naciones \u201catravesadas por conflictos\u201d o donde \u201clas libertades b\u00e1sicas y las libertades pol\u00edticas est\u00e1n altamente restringidas\u201d ocupan los \u00faltimos puestos.<\/p>\n\n\n\n<p>El IPC clasifica a 180 pa\u00edses y territorios seg\u00fan el nivel de percepci\u00f3n de la corrupci\u00f3n en el sector p\u00fablico de cada uno, medidos a trav\u00e9s de la opini\u00f3n de especialistas, analistas de riesgo financiero, mujeres y hombres de la academia y los negocios.<\/p>\n\n\n\n<p>La clasificaci\u00f3n se da en una escala de 0 (los m\u00e1s corruptos) a 100 (los m\u00e1s limpios).<\/p>\n\n\n\n<p>A la cabeza se sit\u00faa Dinamarca con 90 puntos, seguido de Finlandia y Nueva Zelanda, con 87 cada uno.<\/p>\n\n\n\n<p>Mientras que Sud\u00e1n del Sur (13), Siria (13) y Somalia (11) quedaron con las puntuaciones m\u00e1s bajas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Viernes , 3 Febrero de 2023 Uruguay se posicion\u00f3 en el \u00cdndice de Percepci\u00f3n de&#8230;<\/p>\n","protected":false},"author":3,"featured_media":56005,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-56004","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional"],"_links":{"self":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/56004","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=56004"}],"version-history":[{"count":2,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/56004\/revisions"}],"predecessor-version":[{"id":56129,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/56004\/revisions\/56129"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media\/56005"}],"wp:attachment":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=56004"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=56004"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=56004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}