{"id":56011,"date":"2023-02-01T11:10:26","date_gmt":"2023-02-01T17:10:26","guid":{"rendered":"http:\/\/bambapolitica.com.mx\/?p=56011"},"modified":"2023-02-01T11:10:28","modified_gmt":"2023-02-01T17:10:28","slug":"brady-de-fan-de-49ers-y-seleccionado-198-del-draft-a-ser-el-mejor-de-la-nfl","status":"publish","type":"post","link":"https:\/\/bambapolitica.com.mx\/index.php\/2023\/02\/01\/brady-de-fan-de-49ers-y-seleccionado-198-del-draft-a-ser-el-mejor-de-la-nfl\/","title":{"rendered":"Brady, de fan de 49ers y seleccionado 198 del Draft a ser el mejor de la NFL"},"content":{"rendered":"\n<p>Mi\u00e9rcoles , 1 Febrero de 2023<\/p>\n\n\n\n<p>Hay una fotograf\u00eda de Tom Brady con apenas cinco a\u00f1os en la que se sembr\u00f3 la semilla de lo que ser\u00eda su historia dentro de la NFL<br>Las razones por las que Tom Brady se enamor\u00f3 del futbol americano est\u00e1n en San Francisco California y tienen nombre y apellido: Joe Montana, leyenda de los 49ers, equipo del que fue seguidor en su infancia y en el que, ir\u00f3nicamente, nunca jug\u00f3.<\/p>\n\n\n\n<p>A sus 45 a\u00f1os el m\u00e1ximo ganador de Super Bowls, con siete, y poseedor de un manojo de r\u00e9cords de la NFL anunci\u00f3 su retiro definitivo en un video que comparti\u00f3 a trav\u00e9s de sus redes sociales.<br>\u201cBuenos d\u00edas, muchachos. Ir\u00e9 al grano de inmediato. Me retiro. Para siempre. S\u00e9 que el proceso fue un gran problema la \u00faltima vez, as\u00ed que cuando me despert\u00e9 esta ma\u00f1ana, pens\u00e9 en presionar grabar y les avisar\u00eda primero\u201d, anunci\u00f3.<\/p>\n\n\n\n<p>Hay una fotograf\u00eda de Brady con apenas cinco a\u00f1os en la que se sembr\u00f3 la semilla de lo que ser\u00eda su historia.<\/p>\n\n\n\n<p>El peque\u00f1o aparece con el jersey de los 49ers en brazos de su madre durante el famoso partido conocido como \u201cThe Catch\u201d. El juego de campeonato de Conferencia Nacional que San Francisco gan\u00f3 de manera dram\u00e1tica con un pase de Joe Montana hacia de Dwight Clark en enero de 1982.<\/p>\n\n\n\n<p>El sue\u00f1o de jugar con los gambusinos no lleg\u00f3 a ser.<\/p>\n\n\n\n<p>San Francisco ni siquiera lo tuvo en su agenda en 2000, cuando un novato llamado Tom Brady vio como eran seleccionados 198 jugadores en la sexta ronda del Draft de la NFL hasta que su nombre son\u00f3 en el turno 199 para formar parte de los New England Patriots.<\/p>\n\n\n\n<p>M\u00e1s de dos d\u00e9cadas despu\u00e9s, Brady ha anunciado su retirada como el mejor jugador en la historia de la NFL, poseedor de siete anillos de Super Bowl, seis con los New England Patriots, con los que jug\u00f3 entre 2000 y 2019, y uno con los Tampa Bay Buccaneers, equipo en el que permaneci\u00f3 entre 2020 y 2022.<\/p>\n\n\n\n<p>El pasador todav\u00eda guarda entre sus pertenencias su curr\u00edculum de cuando ten\u00eda 22 a\u00f1os. Lo muestra en una fotograf\u00eda en su cuenta personal de Instagram en la que bromea sobre su utilidad para ser parte de los San Francisco 49ers.<\/p>\n\n\n\n<p>\u201c\u00a1Encontr\u00e9 mi viejo curr\u00edculum! Realmente pens\u00e9 que lo iba a necesitar despu\u00e9s de la quinta ronda del Draft\u201d, dijo.<\/p>\n\n\n\n<p>Brady rompi\u00f3 a tal grado el comparativo de logros con el resto de los quarterbacks de la NFL que se le tuvo que empezar medir contra los equipos m\u00e1s poderos de la liga a los que tambi\u00e9n super\u00f3.<\/p>\n\n\n\n<p>El due\u00f1o del jersey n\u00famero 12 necesita de sus dos manos para presumir los siete anillos de Super Bowl que obtuvo, uno m\u00e1s que Los New England Patriots y los Pittsburgh Steelers que suman seis.<\/p>\n\n\n\n<p>El nacido un 3 de agosto de 1977 particip\u00f3 en 10 juegos por el trofeo Vince Lombardi, el 18 por ciento del total de los 56 partidos por el campeonato de la NFL que se han realizado hasta ahora.<\/p>\n\n\n\n<p>Por si no fuera suficiente, esta temporada se convirti\u00f3 en el \u00fanico mariscal de campo que super\u00f3 las 100 mil yardas en la historia de la NFL. \u201cEn la historia de la NFL\u201d una frase que define pr\u00e1cticamente toda su carrera, que hoy lleg\u00f3 a su fin.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mi\u00e9rcoles , 1 Febrero de 2023 Hay una fotograf\u00eda de Tom Brady con apenas cinco&#8230;<\/p>\n","protected":false},"author":3,"featured_media":56012,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-56011","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/56011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=56011"}],"version-history":[{"count":1,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/56011\/revisions"}],"predecessor-version":[{"id":56013,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/56011\/revisions\/56013"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media\/56012"}],"wp:attachment":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=56011"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=56011"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=56011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}