{"id":56195,"date":"2023-02-07T09:12:50","date_gmt":"2023-02-07T15:12:50","guid":{"rendered":"http:\/\/bambapolitica.com.mx\/?p=56195"},"modified":"2023-02-07T09:12:51","modified_gmt":"2023-02-07T15:12:51","slug":"elecciones-edomex-pri-asegura-estar-a-7-puntos-porcentuales-de-morena","status":"publish","type":"post","link":"https:\/\/bambapolitica.com.mx\/index.php\/2023\/02\/07\/elecciones-edomex-pri-asegura-estar-a-7-puntos-porcentuales-de-morena\/","title":{"rendered":"Elecciones Edomex: PRI Asegura Estar a 7 Puntos Porcentuales de Morena"},"content":{"rendered":"\n<p>martes, 7 de febrero de 2023<\/p>\n\n\n\n<p>El CEN de este partido anunci\u00f3 nombramientos de delegados nacionales para sumarse a los trabajos de precampa\u00f1a y campa\u00f1a<\/p>\n\n\n\n<p><br>En conferencia de prensa, realizada en la sede del PRI en el Estado de M\u00e9xico, su presidente estatal, Erick Sevilla, asever\u00f3 que la precandidata tricolor, Alejandra Del Moral Vela, ya est\u00e1 a siete puntos porcentuales en las encuestas de su contra parte de Morena, Delfina G\u00f3mez.<\/p>\n\n\n\n<p><br>Asegur\u00f3 que esta es una diferencia muy menor a la que ten\u00edan hace seis a\u00f1os antes de iniciar la campa\u00f1a a la gubernatura. Esto lo dijo en compa\u00f1\u00eda del presidente nacional de su partido, Alejandro Moreno.<br>\u201cHace 6 a\u00f1os iniciamos marzo con seis puntos abajo, hoy estamos a menos de siete y todav\u00eda no arrancan las campa\u00f1as. En el Estado de M\u00e9xico, no les quepa la menor duda, ya estamos compitiendo, y el 4 de junio, s\u00ed, va a haber una primera gobernadora, se llama Alejandra Del Moral. Estamos esperando los tiempos, en estos momentos es una precandidatura y seremos respetuosos del periodo de precampa\u00f1a y despu\u00e9s en la campa\u00f1a, pero vamos a ganar.\u201d<\/p>\n\n\n\n<p><br>Sevilla declar\u00f3 listo al pri\u00edsmo mexiquense para afrontar el actual proceso electoral, en el que la sociedad tomar\u00e1 una decisi\u00f3n de trascendencia estatal y con fuerte impacto en la vida nacional, por lo que, explic\u00f3, en esta panorama lo que suceda en la entidad se vuelve altamente prioritario para lo que sigue, indic\u00f3 Sevilla Montes de Oca.<\/p>\n\n\n\n<p><br>El dirigente nacional tricolor indic\u00f3 que los priistas mexiquenses tienen claro el tama\u00f1o del reto al que se enfrentan y la forma en que lo har\u00e1n, porque hay, dijo, una militancia con probada experiencia y que ya est\u00e1 preparada para competir calle por calle y que trabajar\u00e1 con intensidad durante el tiempo que falta para la jornada comicial.<\/p>\n\n\n\n<p><br>Este d\u00eda, Alejandro Moreno C\u00e1rdenas nombr\u00f3 delegados nacionales en el Estado de M\u00e9xico, quienes se sumar\u00e1n al trabajo de precampa\u00f1a y campa\u00f1a rumbo a la jornada electoral del pr\u00f3ximo 4 de junio, y asegur\u00f3 que con coordinaci\u00f3n y trabajo entre la estructura alcanza para llegar al triunfo. Los nuevos delegados del Comit\u00e9 Ejecutivo Nacional en la entidad son Manuel Cavazos Lerma, Miguel Alonso Reyes, Francisco Olvera Ru\u00edz, Humberto Lepe Lepe, Roberto L\u00f3pez Garc\u00eda y Lorenzo Rivera Sosa.<br>Despu\u00e9s del nombramiento, el presidente nacional pri\u00edsta asegur\u00f3 que su partido tendr\u00e1 la mejor campa\u00f1a de todos los tiempos con la que le dar\u00e1n certeza al mismo partido y a la Coalici\u00f3n Va por M\u00e9xico. Calific\u00f3 a la militancia del Estado de M\u00e9xico como pilar del priismo nacional y record\u00f3 que con ella se han ganado muchas batallas.<\/p>\n\n\n\n<p><br>Esta vez no ser\u00e1 la excepci\u00f3n ganar la gubernatura con pasos firmes y con estrategia<br>Alejandro C\u00e1rdenas asever\u00f3 que el mejor activo que tiene el PRI es el gobernador Alfredo Del Mazo, que ha llevado un gobierno inteligente y que tiene un fuerte compromiso con los mexiquenses.<\/p>\n\n\n\n<p><br>Al acto asistieron Carolina Viggiano Austria, secretar\u00eda general del CEN del PRI; Alejandro Ozuna Rivero, coordinador general de precampa\u00f1a y los Diputados Miguel S\u00e1mano Peralta, Ricardo Aguilar Castillo, Ana Lilia Herrera Anzaldo, Laura Barrera Fortoul, Gustavo C\u00e1rdenas, Cristina Ruiz Sandoval, Brasil Acosta, Sue Ellen Bernal, Alan Castellanos, Jazm\u00edn Jaimes, Eduardo Zarzosa, Melissa Vargas y Frin\u00e9 Azuara. As\u00ed como los coordinadores regionales Tanya Rellstab, Alma Aquiles, Ra\u00fal Dominguez, Eduardo Bernal, Aar\u00f3n Urbina, Cruz Juvenal Roa, Ricardo Enr\u00edquez y Alberto Curi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>martes, 7 de febrero de 2023 El CEN de este partido anunci\u00f3 nombramientos de delegados&#8230;<\/p>\n","protected":false},"author":3,"featured_media":56181,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-56195","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-del-dia"],"_links":{"self":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/56195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=56195"}],"version-history":[{"count":1,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/56195\/revisions"}],"predecessor-version":[{"id":56196,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/56195\/revisions\/56196"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media\/56181"}],"wp:attachment":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=56195"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=56195"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=56195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}