{"id":57201,"date":"2023-03-01T11:58:24","date_gmt":"2023-03-01T17:58:24","guid":{"rendered":"http:\/\/bambapolitica.com.mx\/?p=57201"},"modified":"2023-03-01T11:58:30","modified_gmt":"2023-03-01T17:58:30","slug":"detienen-a-joven-de-miami-tras-amenazar-a-la-policia-en-video-con-un-ak-47","status":"publish","type":"post","link":"https:\/\/bambapolitica.com.mx\/index.php\/2023\/03\/01\/detienen-a-joven-de-miami-tras-amenazar-a-la-policia-en-video-con-un-ak-47\/","title":{"rendered":"Detienen a joven de Miami tras amenazar a la Polic\u00eda en video con un AK-47"},"content":{"rendered":"\n<p>mi\u00e9rcoles, 1 de marzo de 2023<\/p>\n\n\n\n<p>Las autoridades se\u00f1alaron que los detectives monitoreaban las redes sociales el pasado fin de semana cuando encontraron el video<br>Un joven de 22 a\u00f1os fue arrestado con cargos tras publicar un video en las redes sociales donde amenaza con un fusil de asalto AK-47 a los agentes del Departamento de Polic\u00eda del condado Miami-Dade (MDPD), en Florida, seg\u00fan anunciaron las autoridades.<\/p>\n\n\n\n<p>Vernon E. Kelson fue detenido por una serie de cargos que incluyen amenazas escritas de matar o causar da\u00f1os f\u00edsicos, mostrar un arma de fuego mientras comet\u00eda un delito grave y portar un arma de fuego oculta, inform\u00f3 el MDPD en un comunicado.<\/p>\n\n\n\n<p>Las autoridades se\u00f1alaron que los detectives monitoreaban las redes sociales el pasado fin de semana cuando encontraron el video posteado por Kelson en una cuenta que conoc\u00edan de una investigaci\u00f3n anterior.<br>En el video, publicado hoy por el MDPD junto con el comunicado, se observa a Kelson dentro de un autom\u00f3vil en marcha y sosteniendo un AK-47 mientras pasaba junto a un veh\u00edculo de la polic\u00eda de Miami-Dade.<\/p>\n\n\n\n<p>Kelson amenaz\u00f3 con disparar a los oficiales si lo deten\u00edan, se\u00f1alaron las autoridades.<\/p>\n\n\n\n<p>\u201cLos agentes del orden p\u00fablico se ponen sus uniformes todos los d\u00edas y salen de sus casas sin saber si regresar\u00e1n\u201d, dijo el director de la polic\u00eda de Miami\u2013Dade, Freddy Ram\u00edrez, en el comunicado.<\/p>\n\n\n\n<p>\u201cNo tolerar\u00e9 que nadie, de ninguna manera, amenace a mis oficiales ni a nadie que lleve la placa en el pecho. Pondr\u00e9 a disposici\u00f3n todos los recursos del Departamento de Polic\u00eda de Miami-Dade para llevar a esos individuos ante la justicia\u201d, a\u00f1adi\u00f3.<\/p>\n\n\n\n<p>Kelson fue enviado al Centro Correccional Turner Guilford Knight, del mencionado condado floridano, y se espera que comparezca ante un tribunal de fianzas este mi\u00e9rcoles, recoge la televisi\u00f3n Local 10.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>mi\u00e9rcoles, 1 de marzo de 2023 Las autoridades se\u00f1alaron que los detectives monitoreaban las redes&#8230;<\/p>\n","protected":false},"author":3,"featured_media":57202,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-57201","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional"],"_links":{"self":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/57201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=57201"}],"version-history":[{"count":1,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/57201\/revisions"}],"predecessor-version":[{"id":57203,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/57201\/revisions\/57203"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media\/57202"}],"wp:attachment":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=57201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=57201"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=57201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}