{"id":57980,"date":"2023-03-21T09:19:23","date_gmt":"2023-03-21T15:19:23","guid":{"rendered":"http:\/\/bambapolitica.com.mx\/?p=57980"},"modified":"2023-03-21T09:19:30","modified_gmt":"2023-03-21T15:19:30","slug":"red-de-mujeres-defensoras-de-la-igualdad-celebra-rodada-femenina-en-neza","status":"publish","type":"post","link":"https:\/\/bambapolitica.com.mx\/index.php\/2023\/03\/21\/red-de-mujeres-defensoras-de-la-igualdad-celebra-rodada-femenina-en-neza\/","title":{"rendered":"RED DE MUJERES DEFENSORAS DE LA IGUALDAD, CELEBRA RODADA FEMENINA EN NEZA."},"content":{"rendered":"\n<p>Martes,21 de marzo de 2023<\/p>\n\n\n\n<p>C\u00f3mo parte de la conmemoraci\u00f3n del D\u00eda Internacional de la Mujer, la Red de Mujeres Defensoras de la Igualdad, celebr\u00f3 la 1er. Rodada Femenina en Nezahualc\u00f3yotl, Estado de M\u00e9xico.<\/p>\n\n\n\n<p>Mujeres independientes y algunas integrantes de moto clubs, acompa\u00f1adas por la Diputada Local del Distrito 41, Carmen de la Rosa, se concentraron en la Glorieta del Coyote para rodar dirigi\u00e9ndose al Palacio Municipal.<\/p>\n\n\n\n<p>Escoltadas por elementos de Tr\u00e1nsito arribaron frente a la explanada, sobre la Av. Chimalhuac\u00e1n, d\u00f3nde realizaron acrobacias y compartieron algunas experiencias.<\/p>\n\n\n\n<p>La legisladora en el Congreso mexiquense, se\u00f1al\u00f3 que con este y otro tipo de eventos pretenden tomar todos los espacios p\u00fablicos en los que se desarrollan las mujeres\u2026<\/p>\n\n\n\n<p>&#8220;El prop\u00f3sito es visibilizar a las mujeres motociclistas, el que tambi\u00e9n otras mujeres podamos ver la libertad, la seguridad, queremos sentirla en nuestras calles, en nuestros espacios, queremos sentirnos empoderadas, y creo que ellas lo reflejan y vamos a caminar juntas.&#8221;<\/p>\n\n\n\n<p>Acompa\u00f1ada de Karen Naina Bakary Degante, instructora en motociclismo, anunciaron que apoyar\u00e1n con cursos de capacitaci\u00f3n a las mujeres que quieran aprender a manejar motocicleta.<\/p>\n\n\n\n<p>&#8220;Vamos a dar algunas clases, aqu\u00ed ya Karen se nos comprometi\u00f3 a darles clases a algunas mujeres y entre ello tambi\u00e9n que sepamos usar nuestro equipo.&#8221;.<\/p>\n\n\n\n<p>Al tiempo de recomendar a las chicas riders, ser responsables en su protecci\u00f3n y respetar el reglamento de tr\u00e1nsito, Karen invit\u00f3 a los automovilistas a respetarlas\u2026<\/p>\n\n\n\n<p>&#8220;Que nos respeten como motociclistas, por qu\u00e9 hay veces que una viene bien y de repente los carros se meten o tenemos el verde y de repente les vale, nos avientan, nos arrollan&#8221;.<\/p>\n\n\n\n<p>Alicia, integrante del motoclub &#8220;Demonios Obscuros&#8221;, dijo estar contenta que cada d\u00eda son m\u00e1s mujeres motociclistas .<\/p>\n\n\n\n<p>&#8220;Nos da mucho gusto que m\u00e1s mujeres se est\u00e9n integrando cada d\u00eda, porque hace muchos a\u00f1os \u00e9ramos muy poquitas y hoy la verdad es un orgullo ver a todas las chicas que ya nos acompa\u00f1an&#8221;.<\/p>\n\n\n\n<p>Angy Rivera, una mujer con m\u00e1s de 20 a\u00f1os manejando motocicletas, lo que le ha permitido aprender a reparar fallas mec\u00e1nicas, lo mas importante para las mujeres que se suben a m\u00e1nejar motocicleta, es la responsabilidad\u2026<\/p>\n\n\n\n<p>&#8220;\u00bfManejar con precauci\u00f3n, casco, protecciones si se puede, mucha precauci\u00f3n m\u00e1s que nada&#8221;.<\/p>\n\n\n\n<p>En Nezahualc\u00f3yotl y en varias entidades del pa\u00eds, el uso de la motocicleta se ha extendido y cada vez son m\u00e1s mujeres las que est\u00e1n tomando las avenidas y carreteras, pues adem\u00e1s de transportarse a su trabajo, es un medio para llevar a sus hijos a la escuela, de ah\u00ed la importancia de ser m\u00e1s responsables.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Martes,21 de marzo de 2023 C\u00f3mo parte de la conmemoraci\u00f3n del D\u00eda Internacional de la&#8230;<\/p>\n","protected":false},"author":3,"featured_media":57981,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-57980","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-del-dia"],"_links":{"self":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/57980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=57980"}],"version-history":[{"count":1,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/57980\/revisions"}],"predecessor-version":[{"id":57982,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/57980\/revisions\/57982"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media\/57981"}],"wp:attachment":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=57980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=57980"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=57980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}