{"id":58014,"date":"2023-03-21T11:49:41","date_gmt":"2023-03-21T17:49:41","guid":{"rendered":"http:\/\/bambapolitica.com.mx\/?p=58014"},"modified":"2023-03-21T11:49:45","modified_gmt":"2023-03-21T17:49:45","slug":"santiago-gimenez-y-gutierrez-unicos-europeos-confirmados-ante-surinam","status":"publish","type":"post","link":"https:\/\/bambapolitica.com.mx\/index.php\/2023\/03\/21\/santiago-gimenez-y-gutierrez-unicos-europeos-confirmados-ante-surinam\/","title":{"rendered":"Santiago Gim\u00e9nez y Guti\u00e9rrez, \u00fanicos europeos confirmados ante Surinam"},"content":{"rendered":"\n<p>Martes,21 de marzo de 2023<\/p>\n\n\n\n<p>Puedo confirmar lo de \u2018Santi\u2019&nbsp;<strong>Gim\u00e9nez<\/strong>&nbsp;y \u2018Guti\u2019, van directo porque vimos que jugaban el domingo y hay un viaje directo de Pa\u00edses Bajos a Surinam. Era preferible que no vengan a ac\u00e1, que descansen m\u00e1s en su pa\u00eds y puedan ir directo\u201d, revel\u00f3 el argentino&nbsp;<a href=\"https:\/\/lopezdoriga.com\/?s=Diego+Cocca\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Diego Cocca<\/strong><\/a>,&nbsp;<a href=\"https:\/\/twitter.com\/miseleccionmx\" target=\"_blank\" rel=\"noreferrer noopener\">seleccionador<\/a>&nbsp;de&nbsp;<strong>M\u00e9xico<\/strong>.<\/p>\n\n\n\n<p>El Tri inici\u00f3 los entrenamientos para sus \u00faltimos<strong>&nbsp;dos encuentros<\/strong>&nbsp;de la fase de grupos de la Liga de Naciones de la Concacaf, en Surinam y el pr\u00f3ximo domingo al recibir a Jamaica en el Estadio Azteca de Ciudad de M\u00e9xico.<\/p>\n\n\n\n<p>En estos partidos M\u00e9xico, segundo lugar del grupo A, se juega su pase a la fase final y marcar\u00e1n el debut de Cocca en el banquillo mexicano, al que lleg\u00f3 en febrero pasado en sustituci\u00f3n de su compatriota Gerardo Martino, quien dej\u00f3 al equipo tras llevar al Tri a la eliminaci\u00f3n en la primera ronda del&nbsp;<strong>Mundial Qatar 2022<\/strong>.<\/p>\n\n\n\n<p>Cocca dividir\u00e1 a sus primeros&nbsp;<strong>34 convocados<\/strong>&nbsp;en dos grupos, el primero se enfrentar\u00e1 a Surinam y el segundo recibir\u00e1 a Jamaica, duelo en el que se espera est\u00e9n la mayor\u00eda de las figuras que estuvieron en Qatar como Guillermo Ochoa, guardameta de la Salernitana italiana, e Hirving Lozano, extremo del N\u00e1poles italiano.<\/p>\n\n\n\n<p>\u201cTenemos una idea de qui\u00e9nes van a jugar, pero mi idea es no revelarlos porque le doy una ventaja al rival. Los que se van a quedar seguro jugar\u00e1n m\u00e1s tiempo con Jamaica. Tengo que&nbsp;<strong>conocerlos<\/strong>, las impresiones son buenas por lo que me transmiten que vieron de nosotros. Se vive una energ\u00eda positiva\u201d, a\u00f1adi\u00f3 el estratega.<\/p>\n\n\n\n<p>El manejador reiter\u00f3 que en su gesti\u00f3n buscar\u00e1 darle un cambio generacional a&nbsp;<strong>M\u00e9xico<\/strong>, por lo cual convoc\u00f3 a futbolistas como Gim\u00e9nez y Carlos Acevedo, del Santos Laguna, quien se espera sea el portero del futuro de la selecci\u00f3n.<\/p>\n\n\n\n<p>\u201cHoy hay j\u00f3venes que no estuvieron en el proceso de&nbsp;<strong>Mundial<\/strong>. Tenemos que verlos. Todos tienen deseo de transmitir esta idea de cambio, mejora, competitividad interna y de llevar a la selecci\u00f3n a otro nivel\u201d, sentenci\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Martes,21 de marzo de 2023 Puedo confirmar lo de \u2018Santi\u2019&nbsp;Gim\u00e9nez&nbsp;y \u2018Guti\u2019, van directo porque vimos&#8230;<\/p>\n","protected":false},"author":3,"featured_media":58015,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-58014","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/58014","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=58014"}],"version-history":[{"count":1,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/58014\/revisions"}],"predecessor-version":[{"id":58016,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/58014\/revisions\/58016"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media\/58015"}],"wp:attachment":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=58014"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=58014"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=58014"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}