{"id":58086,"date":"2023-03-22T10:10:16","date_gmt":"2023-03-22T16:10:16","guid":{"rendered":"http:\/\/bambapolitica.com.mx\/?p=58086"},"modified":"2023-03-22T10:10:23","modified_gmt":"2023-03-22T16:10:23","slug":"cuerpo-encontrado-en-sinaloa-seria-de-el-chueco-presunto-asesino-de-jesuitas-autoridades-investigan","status":"publish","type":"post","link":"https:\/\/bambapolitica.com.mx\/index.php\/2023\/03\/22\/cuerpo-encontrado-en-sinaloa-seria-de-el-chueco-presunto-asesino-de-jesuitas-autoridades-investigan\/","title":{"rendered":"Cuerpo encontrado en Sinaloa ser\u00eda de &#8216;El Chueco&#8217;, presunto asesino de jesuitas; autoridades investigan"},"content":{"rendered":"\n<p>Miercoles,22 de marzo de 2023<\/p>\n\n\n\n<p>Jos\u00e9 Noriel Portillo Gil es se\u00f1alado como el presunto asesino de sacerdotes jesuitas en la comunidad de Cerocahui el pasado 20 de junio de 2022.<br>Presuntamente Jos\u00e9 Noriel Portillo Gil, apodado \u201cEl Chueco\u201d a quien se le atribuye el asesinato de los sacerdotes jesuitas, fue localizado muerto.<\/p>\n\n\n\n<p>Una versi\u00f3n no confirmada por las autoridades indica que el presunto narcotraficante fue hallado sin vida la noche de ayer al parecer en Sinaloa.<br>\u00danicamente la Fiscal\u00eda General del Estado (FGE) de Chihuahua convoc\u00f3 a una conferencia de prensa a las 10:30 de la ma\u00f1ana de hoy e indic\u00f3 que personal de esa dependencia viaj\u00f3 a Sinaloa para cotejar informaci\u00f3n pues fiscales de esa entidad reportaron la muerte de una persona con las mismas caracter\u00edsticas de \u201cEl Chueco\u201d.<br>Esta persona fue se\u00f1alada por las autoridades de Chihuahua como el presunto responsable del asesinato de los jesuitas Javier Campos y Joaqu\u00edn Mora ocurridos el pasado 20 de junio en la comunidad de Cerocahui, Chihuahua. As\u00ed como del crimen del gu\u00eda de turistas Pedro Eliodoro Palma Guti\u00e9rrez.<\/p>\n\n\n\n<p>Desde el 2019 Portillo Gil es considerado uno de los principales generadores de violencia en la Sierra de Chihuahua por su presunta responsabilidad en decenas de cr\u00edmenes.<br>Tambi\u00e9n fue acusado de ser el responsable de asesinar al profesor norteamericano Patrick Braxton Andrew, seg\u00fan la Fiscal\u00eda General del Estado.<br>\u00bfQui\u00e9n es El Chueco?<\/p>\n\n\n\n<p>Fue se\u00f1alado por las autoridades de Chihuahua como el presunto responsable de tales asesinatos ocurridos el pasado 20 de junio. Desde el 2019 Portillo Gil es considerado uno de los principales generadores de violencia en la Sierra de Chihuahua por su presunta responsabilidad en decenas de cr\u00edmenes.<br>Tambi\u00e9n fue acusado de ser el responsable de asesinar al profesor norteamericano Patrick Braxton Andrew, seg\u00fan la fiscal\u00eda estatal.<\/p>\n\n\n\n<p>De acuerdo con autoridades federales y locales, El Chueco mantiene el control de las actividades delictivas en dicho municipio. Su c\u00e9lula opera para Los Salazar, brazo armado y operativo del c\u00e1rtel de Sinaloa en el estado de Chihuahua.<br>Portillo Gil, de 30 a\u00f1os, encabeza actividades il\u00edcitas en la regi\u00f3n, como extorsiones, secuestros, homicidios, robo de cobre y tala ilegal, en Urique y otros municipios.<\/p>\n\n\n\n<p>A Jos\u00e9 Noriel Portillo Gil tambi\u00e9n se la adjudica el asesinato del activista Cruz Soto Caraveo, integrante del Colectivo de Familias Desplazadas Forzadamente de la Sierra Tarahumara, quien desapareci\u00f3 el 13 de octubre de 2019.<\/p>\n\n\n\n<p>Tambi\u00e9n se le vincula como las desapariciones de Javier Mu\u00f1oz P\u00e9rez, Juan Antonio Mart\u00ednez y Rub\u00e9n Flores Cisneros, quienes hab\u00edan llegado a Chihuahua provenientes de Zacatecas.<\/p>\n\n\n\n<p>Adem\u00e1s, fue se\u00f1alado por la Fiscal\u00eda de Chihuahua como el responsable de ordenar el ataque a la comandancia de la corporaci\u00f3n estatal en Urique, el 6 de septiembre de 2017.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Miercoles,22 de marzo de 2023 Jos\u00e9 Noriel Portillo Gil es se\u00f1alado como el presunto asesino&#8230;<\/p>\n","protected":false},"author":3,"featured_media":58087,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-58086","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policiaca"],"_links":{"self":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/58086","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=58086"}],"version-history":[{"count":1,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/58086\/revisions"}],"predecessor-version":[{"id":58088,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/58086\/revisions\/58088"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media\/58087"}],"wp:attachment":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=58086"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=58086"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=58086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}