{"id":58281,"date":"2023-03-27T09:55:13","date_gmt":"2023-03-27T15:55:13","guid":{"rendered":"http:\/\/bambapolitica.com.mx\/?p=58281"},"modified":"2023-03-27T09:55:19","modified_gmt":"2023-03-27T15:55:19","slug":"ine-sanciona-a-partidos-politicos-por-irregularidades-en-precampanas-en-edomex","status":"publish","type":"post","link":"https:\/\/bambapolitica.com.mx\/index.php\/2023\/03\/27\/ine-sanciona-a-partidos-politicos-por-irregularidades-en-precampanas-en-edomex\/","title":{"rendered":"INE sanciona a partidos pol\u00edticos por irregularidades en precampa\u00f1as, en Edomex"},"content":{"rendered":"\n<p>lunes,27 marzo de 2023<\/p>\n\n\n\n<p>Los partidos pol\u00edticos fueron multados por un monto de 4 millones 866 mil 470 pesos.<br>Los partidos pol\u00edticos Movimiento Regeneraci\u00f3n Nacional (Morena), Partido Revolucionario Institucional (PRI), Partido Verde, Nueva Alianza y Partido del Trabajo (PT), fueron sancionados por un monto total de 4 millones 866 mil 470 pesos; presentaron irregularidades en el periodo de precampa\u00f1as a la gubernatura del Estado de M\u00e9xico.<\/p>\n\n\n\n<p>La Sesi\u00f3n Extraordinaria del Consejo General del Instituto Nacional Electoral (INE), desarrollada durante este viernes 24 de marzo, aprob\u00f3 esta medida<\/p>\n\n\n\n<p>El partido pol\u00edtico m\u00e1s sancionado es Morena, con la cantidad de 623 mil 777 pesos; se le acusa de presuntamente no reportar egresos, aportaci\u00f3n de ente impedido y por una falta formal en sus reportes.<br>El PRI fue multado con 403 mil 769 pesos por egresos no reportados, aportaciones de ente impedido y obstaculizaci\u00f3n de las funciones de la autoridad para verificar actos p\u00fablicos.<br>En tanto, al Partido Verde se le aplico una multa total de 54 mil 32 pesos, ya que presuntamente no report\u00f3 egresos, y por una falta formal.<\/p>\n\n\n\n<p>Durante la sesi\u00f3n extraordinaria se dijo que los partidos menos sancionados fueron el PT, con mil 99 pesos; y Nueva Alianza, con 962 pesos.<br>Precampa\u00f1as del PRI y Morena, en Edomex, son multadas por el INE<\/p>\n\n\n\n<p>Durante esta sesi\u00f3n, el consejero electoral del INE, Jaime Rivera, explic\u00f3 que el equipo de Alejandra del Moral no report\u00f3 el costo de la utilizaci\u00f3n de un predio para su precampa\u00f1a.<br>Agreg\u00f3 que por el hecho se le pidi\u00f3 a la Unidad de Fiscalizaci\u00f3n hacer una cotizaci\u00f3n con otro sitio con las caracter\u00edsticas socioecon\u00f3micas de Texcoco, lugar en donde Alejandra del Moral realiz\u00f3 el t\u00e9rmino de este proceso electoral.<\/p>\n\n\n\n<p>\u201cLo que ocurri\u00f3, por un lado, si bien se hab\u00eda considerado que el predio utilizado de la precandidata del PRI, para su cierre de precampa\u00f1a ten\u00eda un valor, que no quiso declarar, y por eso se le sanciona, con 80 mil pesos. Cuando se busc\u00f3 otro terreno en un \u00e1rea geogr\u00e1fica y econ\u00f3micamente m\u00e1s cerca a la de Texcoco, y, adem\u00e1s, se busca una superficie semejante, el resultado de la cotizaci\u00f3n se eleva de 80 mil a 100 mil pesos\u201d dijo el consejero Electoral, Jaime Rivera.<br>Coment\u00f3 que el lugar que utiliz\u00f3 Delfina G\u00f3mez para su cierre de precampa\u00f1a, que fue el Teatro del Pueblo de Texcoco, en un inicio fue desproporcionado. Adem\u00e1s, coment\u00f3 que no se hab\u00eda declarado.<\/p>\n\n\n\n<p>\u201cLos 15 mil pesos que no hab\u00edan declarado, y despu\u00e9s el municipio hubiera cobrado 15 mil pesos, resulta claramente desproporcionado. Por lo tanto, se hizo una cotizaci\u00f3n, realmente equivalente, hasta donde es posible y por lo tanto son 100 mil pesos, de manera tal que est\u00e1 razonado y justificado la nueva cotizaci\u00f3n\u201d, expres\u00f3 Jaime Rivera.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>lunes,27 marzo de 2023 Los partidos pol\u00edticos fueron multados por un monto de 4 millones&#8230;<\/p>\n","protected":false},"author":3,"featured_media":58282,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-58281","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-del-dia"],"_links":{"self":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/58281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=58281"}],"version-history":[{"count":1,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/58281\/revisions"}],"predecessor-version":[{"id":58283,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/58281\/revisions\/58283"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media\/58282"}],"wp:attachment":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=58281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=58281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=58281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}