{"id":58636,"date":"2023-04-03T13:01:43","date_gmt":"2023-04-03T19:01:43","guid":{"rendered":"http:\/\/bambapolitica.com.mx\/?p=58636"},"modified":"2023-04-03T13:01:44","modified_gmt":"2023-04-03T19:01:44","slug":"ejecutan-a-tres-personas-en-zona-hotelera-de-cancun-quintana-roo","status":"publish","type":"post","link":"https:\/\/bambapolitica.com.mx\/index.php\/2023\/04\/03\/ejecutan-a-tres-personas-en-zona-hotelera-de-cancun-quintana-roo\/","title":{"rendered":"Ejecutan a tres personas en zona hotelera de Canc\u00fan, Quintana Roo"},"content":{"rendered":"\n<p>lunes,3 Abril del 2023<\/p>\n\n\n\n<p>Tres personas fueron ejecutadas en plena zona de playa frente al hotel Fiesta Americana Condesa de Canc\u00fan, en Quintana Roo<br>Autoridades del estado de Quintana Roo encontraron los cuerpos de tres personas con impactos de bala en la zona hotelera en la ciudad de Canc\u00fan.<\/p>\n\n\n\n<p>Medios locales detallaron que lo anterior ocurri\u00f3 en plena zona de playa frente al hotel Fiesta Americana Condesa, tras reporte del servicio de emergencia 911 sobre tres personas con heridas de bala<\/p>\n\n\n\n<p>Lo anterior gener\u00f3 una fuerte movilizaci\u00f3n policiaca y de servicios de emergencia en dicha zona de Canc\u00fan, quienes implementaron un operativo de seguridad<\/p>\n\n\n\n<p>Emanuel Joaquin Mateo.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>lunes,3 Abril del 2023 Tres personas fueron ejecutadas en plena zona de playa frente al&#8230;<\/p>\n","protected":false},"author":3,"featured_media":58637,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-58636","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policiaca"],"_links":{"self":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/58636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=58636"}],"version-history":[{"count":1,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/58636\/revisions"}],"predecessor-version":[{"id":58638,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/58636\/revisions\/58638"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media\/58637"}],"wp:attachment":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=58636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=58636"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=58636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}