{"id":58771,"date":"2023-04-05T12:24:48","date_gmt":"2023-04-05T18:24:48","guid":{"rendered":"http:\/\/bambapolitica.com.mx\/?p=58771"},"modified":"2023-04-06T09:55:58","modified_gmt":"2023-04-06T15:55:58","slug":"las-capas-de-hielo-pueden-derrumbarse-mas-rapido-de-lo-que-se-pensaba","status":"publish","type":"post","link":"https:\/\/bambapolitica.com.mx\/index.php\/2023\/04\/05\/las-capas-de-hielo-pueden-derrumbarse-mas-rapido-de-lo-que-se-pensaba\/","title":{"rendered":"Las capas de hielo pueden derrumbarse m\u00e1s r\u00e1pido de lo que se pensaba"},"content":{"rendered":"\n<p>jueves, 6 Abril del 2023<\/p>\n\n\n\n<p>Investigadores concluyen que pronto podr\u00edan observarse pulsos de retroceso en las capas de hielo de algunas partes de la Ant\u00e1rtida<br>La capa de hielo euroasi\u00e1tica podr\u00eda haber retrocedido hasta 600 metros al d\u00eda en la plataforma continental noruega durante la \u00faltima deglaciaci\u00f3n, hace unos 20 mil a\u00f1os, lo que supone unas 20 veces m\u00e1s r\u00e1pido que el mayor ritmo medido hasta ahora.<\/p>\n\n\n\n<p>Los resultados de un estudio que publica Nature son \u201cuna advertencia del pasado sobre la velocidad a la que las capas de hielo son f\u00edsicamente capaces de retroceder\u201d, destac\u00f3 la l\u00edder de la investigaci\u00f3n, Christine Batchelor, de la Universidad de Newcastle (Reino Unido).<\/p>\n\n\n\n<p>Esa velocidad de retirada de las capas de hielo es muy superior a la observada desde sat\u00e9lites o deducida a partir de relieves similares en la Ant\u00e1rtida, \u201clos pulsos de retroceso r\u00e1pido pueden ser mucho m\u00e1s r\u00e1pidos que todo lo que hemos visto hasta ahora\u201d, agreg\u00f3 la investigadora.<\/p>\n\n\n\n<p>La informaci\u00f3n sobre el comportamiento de los mantos de hielo en periodos pasados de calentamiento clim\u00e1tico es importante para las simulaciones inform\u00e1ticas que predicen los cambios futuros de estos y del nivel del mar.<\/p>\n\n\n\n<p>El equipo us\u00f3 im\u00e1genes de alta resoluci\u00f3n del fondo marino para revelar la rapidez con que se retir\u00f3 una antigua capa de hielo que se extend\u00eda desde Noruega al final de la \u00faltima Edad de Hielo y cartografi\u00f3 m\u00e1s de 7 mil 600 formas geol\u00f3gicas a peque\u00f1a escala denominadas \u201ccrestas onduladas\u201d, que tienen menos de 2.5 metros de altura y est\u00e1n separadas entre s\u00ed entre 25 y 300 metros.<\/p>\n\n\n\n<p>Esas crestas onduladas se cree que se formaron cuando el margen en retirada de la capa de hielo subi\u00f3 y baj\u00f3 con las mareas, empujando los sedimentos del fondo marino hacia una cresta cada marea baja.<\/p>\n\n\n\n<p>Dado que se habr\u00edan producido dos crestas cada d\u00eda (con dos ciclos de marea al d\u00eda), los investigadores pudieron calcular la rapidez con la que se retir\u00f3 la capa de hielo.<\/p>\n\n\n\n<p>As\u00ed encontraron pruebas de un r\u00e1pido retroceso a velocidades que oscilaban entre 55 y 610 metros al d\u00eda en capas de hielo casi planas durante la \u00faltima deglaciaci\u00f3n; el estudio sugiere que los periodos de retroceso tan r\u00e1pido pueden durar poco tiempo, de d\u00edas a meses.<\/p>\n\n\n\n<p>\u201cEsto demuestra que las tasas de retroceso de la capa de hielo promediadas a lo largo de varios a\u00f1os o m\u00e1s pueden ocultar episodios m\u00e1s cortos de retroceso m\u00e1s r\u00e1pido\u201d, agreg\u00f3 el tambi\u00e9n firmante Julian Dowdeswell, de la Universidad de Cambridge.<\/p>\n\n\n\n<p>Por ello, consider\u00f3, es importante que las simulaciones por ordenador sean capaces de reproducir este comportamiento \u201cpulsado\u201d del manto de hielo.<\/p>\n\n\n\n<p>Las mayores tasas de retroceso se midieron en las zonas m\u00e1s planas del antiguo lecho marino, lo que sugiere que pueden producirse un desprendimiento y retroceso casi instant\u00e1neos del manto de hielo cuando la l\u00ednea de fondo se aproxima a la flotabilidad total.<\/p>\n\n\n\n<p>Las formas del fondo marino tambi\u00e9n arrojan luz sobre el mecanismo por el que puede producirse un retroceso tan r\u00e1pido, pues se observ\u00f3 que la antigua capa de hielo en Noruega hab\u00eda menguado m\u00e1s r\u00e1pidamente por las partes m\u00e1s planas de su lecho.<\/p>\n\n\n\n<p>\u201cUn margen de hielo puede desprenderse del fondo marino y retroceder casi instant\u00e1neamente cuando se vuelve flotante\u201d, explic\u00f3 Frazer Christie; es un tipo de retroceso que solo se produce en lechos relativamente planos, donde se requiere menos fusi\u00f3n para diluir el hielo suprayacente hasta el punto en que empieza a flotar.<\/p>\n\n\n\n<p>Los investigadores concluyen que pronto podr\u00edan observarse pulsos de retroceso igualmente r\u00e1pido en algunas partes de la Ant\u00e1rtida como el vasto glaciar Thwaites.<\/p>\n\n\n\n<p>Situado en la Ant\u00e1rtida Occidental, este glaciar es objeto de una considerable investigaci\u00f3n internacional debido a su susceptibilidad potencial a un retroceso inestable.<\/p>\n\n\n\n<p>Los autores sugieren que el Thwaites podr\u00eda sufrir un pulso de retroceso r\u00e1pido porque recientemente se ha retirado cerca de una zona plana de su lecho.<\/p>\n\n\n\n<p>Batchelor indic\u00f3 que los hallazgos apuntan a que las tasas actuales de deshielo \u201cson suficientes para provocar breves impulsos de r\u00e1pido retroceso en las zonas planas de la capa de hielo ant\u00e1rtica, incluido Thwaites\u201d.<\/p>\n\n\n\n<p>\u201cEs muy posible que los sat\u00e9lites detecten este tipo de retroceso de la capa de hielo en un futuro pr\u00f3ximo, sobre todo si se mantiene la tendencia actual de calentamiento del clima\u201d.<\/p>\n\n\n\n<p>Emanuel Joaquin Mateo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>jueves, 6 Abril del 2023 Investigadores concluyen que pronto podr\u00edan observarse pulsos de retroceso en&#8230;<\/p>\n","protected":false},"author":3,"featured_media":58772,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-58771","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional"],"_links":{"self":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/58771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=58771"}],"version-history":[{"count":2,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/58771\/revisions"}],"predecessor-version":[{"id":58811,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/58771\/revisions\/58811"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media\/58772"}],"wp:attachment":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=58771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=58771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=58771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}