{"id":58817,"date":"2023-04-06T10:28:20","date_gmt":"2023-04-06T16:28:20","guid":{"rendered":"http:\/\/bambapolitica.com.mx\/?p=58817"},"modified":"2023-04-06T10:28:27","modified_gmt":"2023-04-06T16:28:27","slug":"billete-de-120-pesos-se-hace-viral-tras-supuestamente-salir-de-un-cajero-automatico","status":"publish","type":"post","link":"https:\/\/bambapolitica.com.mx\/index.php\/2023\/04\/06\/billete-de-120-pesos-se-hace-viral-tras-supuestamente-salir-de-un-cajero-automatico\/","title":{"rendered":"Billete de 120 pesos se hace viral tras supuestamente salir de un cajero autom\u00e1tico"},"content":{"rendered":"\n<p>jueves, 6 Abril del 2023<\/p>\n\n\n\n<p>Banxico se\u00f1ala que, al recibir un billete falso de alg\u00fan cajero autom\u00e1tico, el cliente puede hacer un reclamo ante la instituci\u00f3n de cr\u00e9dito, pero se deben seguir algunas instrucciones.<br>Por medio de las redes sociales, Twitter y Facebook, por mencionar algunos, ha circulado la foto de un billete de 120 pesos que sali\u00f3 de un cajero autom\u00e1tico a un cliente en M\u00e9xico.<\/p>\n\n\n\n<p>Este caso ocurri\u00f3, al parecer en Campeche y se dio a conocer por varios usuarios de Twitter, quienes se han dicho sorprendidos al ver esta imagen que adem\u00e1s, se ha compatido varias veces desde aproximadamente el mes de marzo de 2023.<br>Varios usuarios han reaccionado, comentado y, al mismo tiempo, publicado la foto desde distintas cuentas.<br>\u00bfQu\u00e9 hacer al recibir billetes falsos?<br>Sobre la circulaci\u00f3n de billetes falsos el Banco de M\u00e9xico (Banxico) emite distintas recomendaciones para que, en caso de estar en una situaci\u00f3n as\u00ed, cada persona sepa qu\u00e9 hacer .<\/p>\n\n\n\n<p>Seg\u00fan el art\u00edculo 48 Bis 1 de la Ley de Instituciones de Cr\u00e9dito se tiene derecho a reclamar el importe del billete a la instituci\u00f3n de cr\u00e9dito, ya se si el billete fue entregado en un cajero autom\u00e1tico o en alguna ventanilla bancaria.<\/p>\n\n\n\n<p>\u201cCuando a las instituciones de cr\u00e9dito les sean presentados por sus clientes billetes presuntamente falsos que les hubieran sido entregados en cajeros autom\u00e1ticos o en las ventanillas de alguna de sus sucursales, deber\u00e1n proceder de la forma siguiente:<br>Proporcionar\u00e1n al cliente un formato de reclamaci\u00f3n, en el que \u00e9ste anotar\u00e1 su nombre y domicilio; el lugar, fecha y modo en que le fueron entregadas las piezas, as\u00ed como las caracter\u00edsticas y n\u00famero de \u00e9stas. Adem\u00e1s, a dicho formato deber\u00e1 anexarse fotocopia de alguna identificaci\u00f3n oficial del cliente<br>Retendr\u00e1n las piezas de que se trate, extendiendo al cliente el recibo respectivo y las remitir\u00e1n al Banco de M\u00e9xico para dictamen. Las instituciones deber\u00e1n proporcionar al Banco de M\u00e9xico la informaci\u00f3n que al efecto requiera<\/p>\n\n\n\n<p>Es una obligaci\u00f3n de la instituci\u00f3n de cr\u00e9dito el atender este tipo de eventos; sin embargo, para presentar la reclamaci\u00f3n, s\u00f3lo se tienen hasta 5 d\u00edas h\u00e1biles bancarios posteriores a la fecha en que se recibi\u00f3 la pieza\u201d.<\/p>\n\n\n\n<p>Banxico recomienda que, si te percatas de que te dieron un billete falso, no hagas ning\u00fan pago con \u00e9l porque ese acto est\u00e1 considerado como un delito federal.<\/p>\n\n\n\n<p>\u00bfC\u00f3mo puedo identificar un billete falso?<br>El Banco de M\u00e9xico informa que los billetes emitidos por esta instituci\u00f3n tienen diversas caracter\u00edsticas y elementos de seguridad que se pueden verificar para determinar su autenticidad, las cuales se pueden consultar en la p\u00e1gina &#8216;Dise\u00f1os actuales de billetes y monedas&#8217;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>jueves, 6 Abril del 2023 Banxico se\u00f1ala que, al recibir un billete falso de alg\u00fan&#8230;<\/p>\n","protected":false},"author":3,"featured_media":58818,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-58817","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-del-dia"],"_links":{"self":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/58817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=58817"}],"version-history":[{"count":1,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/58817\/revisions"}],"predecessor-version":[{"id":58819,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/58817\/revisions\/58819"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media\/58818"}],"wp:attachment":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=58817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=58817"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=58817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}