{"id":58827,"date":"2023-04-10T09:13:59","date_gmt":"2023-04-10T15:13:59","guid":{"rendered":"http:\/\/bambapolitica.com.mx\/?p=58827"},"modified":"2023-04-10T09:14:02","modified_gmt":"2023-04-10T15:14:02","slug":"ricardo-monreal-se-mantiene-firme-para-la-candidatura-de-morena-a-la-presidencia-de-la-republica","status":"publish","type":"post","link":"https:\/\/bambapolitica.com.mx\/index.php\/2023\/04\/10\/ricardo-monreal-se-mantiene-firme-para-la-candidatura-de-morena-a-la-presidencia-de-la-republica\/","title":{"rendered":"Ricardo Monreal se mantiene firme para la candidatura de Morena a la Presidencia de la Rep\u00fablica"},"content":{"rendered":"\n<p>lunes, 10 Abril del 2023<\/p>\n\n\n\n<p>Ricardo Monreal refrend\u00f3 su intenci\u00f3n para alcanzar la Presidencia de la Rep\u00fablica de 2024, para profundizar la pol\u00edtica social y generar las condiciones propicias para construir un mejor pa\u00eds.<\/p>\n\n\n\n<p>El doctor aprovech\u00f3 este domingo para agradecer a sus simpatizantes que han resistido meses de hostilidad y descalificaciones.<\/p>\n\n\n\n<p>\u201cPero no nos arredra nada, estamos muy firmes de continuar (\u2026), porque creemos que M\u00e9xico nos lo reclama y nos lo demanda. Ni nos vamos a rajar, ni nos vamos a dejar, ni nos vamos a bajar\u201d.<\/p>\n\n\n\n<p>Monreal afirm\u00f3 que profundizar\u00e1 la pol\u00edtica social, mejorar\u00e1 la estrategia de seguridad p\u00fablica, as\u00ed como los programas para generar empleo y apoyar al campo mexicano.<\/p>\n\n\n\n<p>\u201cTenemos muchos desaf\u00edos: las reservas actuariales, los servicios p\u00fablicos, el bienestar, la salud, la educaci\u00f3n, la solidaridad y la seguridad social\u201d.<\/p>\n\n\n\n<p>Adem\u00e1s, dijo, \u201ctenemos encima el compromiso\u201d para enfrentar los efectos del cambio clim\u00e1tico, los nuevos retos y desaf\u00edos del M\u00e9xico moderno, \u201cpero los podemos enfrentar con \u00e9xito\u201d.<\/p>\n\n\n\n<p>Ricardo Monreal subray\u00f3 que se prev\u00e9 una semana pesada en el Senado de la Rep\u00fablica, pues intensificar\u00e1 el di\u00e1logo para construir los acuerdos que permitan desahogar la agenda legislativa y cumplir con las expectativas y exigencias ciudadanas.<\/p>\n\n\n\n<p>Sin embargo, dijo que retomar\u00e1 los encuentros con militantes de Morena y simpatizantes de su proyecto de naci\u00f3n, por lo que adelant\u00f3 una gira por Veracruz, Campeche y la Ciudad de M\u00e9xico.<\/p>\n\n\n\n<p>\u201cOjal\u00e1 y nos puedas acompa\u00f1ar, para escucharnos y para poder generar condiciones propicias para un M\u00e9xico mejor\u201d, expres\u00f3 Monreal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>lunes, 10 Abril del 2023 Ricardo Monreal refrend\u00f3 su intenci\u00f3n para alcanzar la Presidencia de&#8230;<\/p>\n","protected":false},"author":3,"featured_media":58828,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-58827","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-del-dia"],"_links":{"self":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/58827","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=58827"}],"version-history":[{"count":1,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/58827\/revisions"}],"predecessor-version":[{"id":58829,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/58827\/revisions\/58829"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media\/58828"}],"wp:attachment":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=58827"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=58827"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=58827"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}