{"id":58856,"date":"2023-04-10T11:52:17","date_gmt":"2023-04-10T17:52:17","guid":{"rendered":"http:\/\/bambapolitica.com.mx\/?p=58856"},"modified":"2023-04-10T11:52:19","modified_gmt":"2023-04-10T17:52:19","slug":"el-fin-de-semana-largo-por-semana-santa-deja-267-victimas-de-asesinato","status":"publish","type":"post","link":"https:\/\/bambapolitica.com.mx\/index.php\/2023\/04\/10\/el-fin-de-semana-largo-por-semana-santa-deja-267-victimas-de-asesinato\/","title":{"rendered":"El fin de semana largo por Semana Santa deja 267  victimas de asesinato"},"content":{"rendered":"\n<p>lunes, 10 Abril del 2023<\/p>\n\n\n\n<p>El estado de de M\u00e9xico se posiciono como la identidad con mayor numero de asesinato durante el fin de semana largo por Semana Santa al registrar 28 eventos<\/p>\n\n\n\n<p>De acuerdo con fuentes oficiales 267 personas fueron asesinadas durante el fin de semana largo<\/p>\n\n\n\n<p>De acuerdo con el informe de seguridad de la Secretaria de Seguridad y Protecci\u00f3n Ciudadana SSPC dio a conocer las cifras oficiales de los homicidios <\/p>\n\n\n\n<p>Conforme a las estad\u00edsticas indican que el jueves 6 de abril ocurrieron 65 asesinatos  <\/p>\n\n\n\n<p>En cuento al viernes 7 de abril de abril se reportaron 67 homicidios, el s\u00e1bado 8 de abril 69 asesinatos y el domingo 9 de abril 66 casos<\/p>\n\n\n\n<p>El estado de M\u00e9xico a tomado la posici\u00f3n como la entidad con mayor numero de eventos 28. Guanajuato fue la segunda entidad en la lista con 22 casos<\/p>\n\n\n\n<p>Hasta el 9 de abril suman 641 victimas de homicidios un promedio diario de 7.2 asesinatos <\/p>\n\n\n\n<p>Emanuel Joaqu\u00edn Mateo   <\/p>\n\n\n\n<p> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>lunes, 10 Abril del 2023 El estado de de M\u00e9xico se posiciono como la identidad&#8230;<\/p>\n","protected":false},"author":3,"featured_media":58857,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-58856","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policiaca"],"_links":{"self":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/58856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=58856"}],"version-history":[{"count":1,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/58856\/revisions"}],"predecessor-version":[{"id":58858,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/58856\/revisions\/58858"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media\/58857"}],"wp:attachment":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=58856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=58856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=58856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}