{"id":58971,"date":"2023-04-12T09:28:08","date_gmt":"2023-04-12T15:28:08","guid":{"rendered":"http:\/\/bambapolitica.com.mx\/?p=58971"},"modified":"2023-04-12T09:28:11","modified_gmt":"2023-04-12T15:28:11","slug":"como-gobernadora-trabajare-incansablemente-para-devolverle-la-seguridad-al-edomex-delfina-gomez","status":"publish","type":"post","link":"https:\/\/bambapolitica.com.mx\/index.php\/2023\/04\/12\/como-gobernadora-trabajare-incansablemente-para-devolverle-la-seguridad-al-edomex-delfina-gomez\/","title":{"rendered":"\u201cComo gobernadora, trabajar\u00e9 incansablemente para devolverle la seguridad al Edomex\u201d: Delfina G\u00f3mez"},"content":{"rendered":"\n<p>Mi\u00e9rcoles, 13 de abril del 2023<\/p>\n\n\n\n<p>La maestra Delfina G\u00f3mez propone un plan de transporte seguro y m\u00e1s participaci\u00f3n ciudadana.<br>La maestra Delfina G\u00f3mez, candidata a gobernadora&nbsp;del Estado de M\u00e9xico por Morena, PT y Partido Verde, asegur\u00f3 que su gobierno&nbsp;no descansar\u00e1 hasta devolverle la seguridad a la entidad, la cual es considerada una&nbsp;de las m\u00e1s violentas e inseguras del pa\u00eds.<\/p>\n\n\n\n<p>\u201cComo gobernadora, trabajar\u00e9 incansablemente para devolverle la seguridad al&nbsp;Estado de M\u00e9xico\u201d, se\u00f1al\u00f3 la maestra Delfina G\u00f3mez.<br>Adem\u00e1s, destac\u00f3 el eje transversal Seguridad y&nbsp;Erradicaci\u00f3n de la Violencia que integra su Plan de Gobierno del Bienestar 2023-2029.<\/p>\n\n\n\n<p>La candidata morenista Delfina G\u00f3mez indic\u00f3 que el Estado de M\u00e9xico fue&nbsp;abandonado durante d\u00e9cadas por los gobiernos neoliberales, lo que provoc\u00f3 que&nbsp;hoy existan m\u00e1s de 300 robos al d\u00eda que afectan a los mexiquenses que diariamente&nbsp;se trasladan para salir a trabajar, a la escuela o a realizar sus actividades cotidianas.<\/p>\n\n\n\n<p>\u201cNuestro pueblo anhela vivir sin miedo, salir a trabajar, salir a las calles y usar el&nbsp;transporte p\u00fablico sin la angustia de que algo pueda pasarles a ellos o a sus familias.&nbsp;Vamos a implementar acciones estrat\u00e9gicas, muchas de ellas apoyadas en el&nbsp;despliegue de tecnolog\u00eda para prevenir los delitos que afectan a las familias&nbsp;mexiquenses\u201d, explic\u00f3 la maestra Delfina G\u00f3mez.<br>Estas son algunas acciones del eje transversal \u201cSeguridad y Erradicaci\u00f3n de la&nbsp;Violencia\u201d:<\/p>\n\n\n\n<p>Plan de transporte seguro<br>Acciones estrat\u00e9gicas para prevenir el delito en el transporte p\u00fablico, mediante la&nbsp;vinculaci\u00f3n de las c\u00e1maras de seguridad y botones de p\u00e1nico de las unidades de&nbsp;transporte con los C5.<br>Transformar los organismos de seguridad<br>M\u00e1s y mejores polic\u00edas. Depurar e incrementar el n\u00famero y la calidad profesional de&nbsp;polic\u00edas, custodios, ministerios p\u00fablicos y peritos.<\/p>\n\n\n\n<p>Combatir la violencia desde la ra\u00edz<br>Mediante programas transversales que involucren a los tres \u00f3rdenes de gobierno y,&nbsp;a la sociedad en su conjunto.<\/p>\n\n\n\n<p>M\u00e1s participaci\u00f3n ciudadana<br>Fortalecimiento del Consejo Ciudadano de Seguridad P\u00fablica y la promoci\u00f3n y&nbsp;creaci\u00f3n de redes ciudadanas de seguridad.<\/p>\n\n\n\n<p>Asimismo, la maestra Delfina G\u00f3mez, candidata a gobernadora del Estado de&nbsp;M\u00e9xico por la candidatura com\u00fan \u201cJuntos Hacemos Historia en el Estado de&nbsp;M\u00e9xico\u201d conformada por Morena, el Partido del Trabajo (PT) y el Partido Verde&nbsp;Ecologista de M\u00e9xico (PVEM), asever\u00f3 que su gobierno promover\u00e1 el&nbsp;fortalecimiento del tejido social atendiendo la generaci\u00f3n de empleos, el combate a&nbsp;las adicciones y las violencias de g\u00e9nero e intrafamiliar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mi\u00e9rcoles, 13 de abril del 2023 La maestra Delfina G\u00f3mez propone un plan de transporte&#8230;<\/p>\n","protected":false},"author":3,"featured_media":58972,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-58971","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-del-dia"],"_links":{"self":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/58971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=58971"}],"version-history":[{"count":1,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/58971\/revisions"}],"predecessor-version":[{"id":58973,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/58971\/revisions\/58973"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media\/58972"}],"wp:attachment":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=58971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=58971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=58971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}