{"id":59006,"date":"2023-04-12T11:57:43","date_gmt":"2023-04-12T17:57:43","guid":{"rendered":"http:\/\/bambapolitica.com.mx\/?p=59006"},"modified":"2023-04-12T11:57:45","modified_gmt":"2023-04-12T17:57:45","slug":"cidh-condena-a-mexico-por-uso-de-la-prision-preventiva-oficiosa","status":"publish","type":"post","link":"https:\/\/bambapolitica.com.mx\/index.php\/2023\/04\/12\/cidh-condena-a-mexico-por-uso-de-la-prision-preventiva-oficiosa\/","title":{"rendered":"CIDH condena a M\u00e9xico por uso de la prisi\u00f3n preventiva oficiosa"},"content":{"rendered":"\n<p>Miercoles, 12 de abril del 2023<\/p>\n\n\n\n<p>La CIDH sostiene que M\u00e9xico deber\u00e1 adecuar a est\u00e1ndares internacionales su ordenamiento jur\u00eddico interno sobre la prisi\u00f3n preventiva oficiosa y el arraigo<br>La Corte Interamericana de Derechos Humanos (CIDH) conden\u00f3 al Gobierno de M\u00e9xico por el uso de la prisi\u00f3n preventiva oficiosa y le orden\u00f3 adecuar su ordenamiento jur\u00eddico para hacerlo compatible con la Convenci\u00f3n Americana.<\/p>\n\n\n\n<p>Mediante la sentencia por el Caso Garc\u00eda Rodr\u00edguez y otro vs M\u00e9xico la CIDH sostiene que M\u00e9xico deber\u00e1 adecuar a est\u00e1ndares internacionales su ordenamiento jur\u00eddico interno sobre la prisi\u00f3n preventiva oficiosa y el arraigo.<br>Derivado del an\u00e1lisis del caso la Corte Interamericana encontr\u00f3 al Estado de M\u00e9xico responsable por la violaci\u00f3n de diversos derechos de dos hombres a quienes las autoridades judiciales enviaron a prisi\u00f3n preventiva oficiosa por 17 a\u00f1os y que adem\u00e1s sufrieron torturas en el periodo que estuvieron detenidos.<\/p>\n\n\n\n<p>Se confirmaron violaciones a los derechos a la integridad personal, la libertad personal, las garant\u00edas judiciales, la igualdad ante la ley, la protecci\u00f3n judicial, a ser o\u00eddo, a la presunci\u00f3n de inocencia y al principio de plazo razonable.<\/p>\n\n\n\n<p>El caso se refiere a las violaciones al debido proceso y a la libertad personal en contra de Daniel Garc\u00eda Rodr\u00edguez y Reyes Alp\u00edzar Ort\u00edz, quienes fueron acusados de haber asesinado en 2001 a la regidora de Atizap\u00e1n, Mar\u00eda de los \u00c1ngeles Tam\u00e9s.<\/p>\n\n\n\n<p>Garc\u00eda y Alp\u00edzar permanecieron en prisi\u00f3n preventiva por 17 a\u00f1os, el tiempo m\u00e1s largo que alguien en M\u00e9xico ha estado en la c\u00e1rcel sin sentencia, hasta 2019, cuando quedaron bajo arresto domiciliario con el uso de brazaletes electr\u00f3nicos. En 2022 fueron condenados a 35 a\u00f1os de c\u00e1rcel, sentencia que est\u00e1 en apelaci\u00f3n.<\/p>\n\n\n\n<p>\u201cPara esta Corte es claro que la extensi\u00f3n por m\u00e1s de 17 a\u00f1os de la prisi\u00f3n preventiva signific\u00f3 en los hechos que se aplicara a los procesados una pena encubierta sin una condena, puesto que constituy\u00f3 una medida punitiva sin previo juicio acompa\u00f1ado de sus garant\u00edas, y por un lapso que excede todo plazo razonable ya que este correspondi\u00f3 aproximativamente a la mitad de la pena que se impuso en la sentencia condenatoria\u201d, indica el fallo de la CIDH.<\/p>\n\n\n\n<p>El tribunal internacional tambi\u00e9n concluy\u00f3 que Daniel Garc\u00eda Rodr\u00edguez \u201cfue sometido a malos tratos y torturas psicol\u00f3gicas por parte de las autoridades del Ministerio P\u00fablico del Estado de M\u00e9xico\u201d, situaci\u00f3n que fue denunciada por el sospechoso, sin que los hechos fueran investigados.<\/p>\n\n\n\n<p>\u201cLos maltratos psicol\u00f3gicos que fueron descriptos por Daniel Garc\u00eda son de una extrema severidad pues consistieron en amenazar y detener a sus familiares y seres queridos. Adem\u00e1s, buscaban una finalidad precisa que consisti\u00f3 en obtener su confesi\u00f3n y firma de documentos implicando a otras personas\u201d, indic\u00f3 la CorteIDH.<\/p>\n\n\n\n<p>En cuanto a Reyes Alp\u00edzar, la CIDH determin\u00f3 que el Estado no investig\u00f3 con la debida diligencia las denuncias de tortura que present\u00f3.<\/p>\n\n\n\n<p>En su sentencia, la CIDH orden\u00f3 a M\u00e9xico concluir los procesos penales, revisar la pertinencia de mantener medidas cautelares, y excluir del proceso los antecedentes incriminatorios obtenidos bajo coacci\u00f3n o tortura.<\/p>\n\n\n\n<p>\u201cEl uso de la tortura como mecanismo para obtener confesiones o antecedentes incriminatorios del imputado o acusado no puede tener otra consecuencia que la exclusi\u00f3n de la prueba. De lo contrario, la prohibici\u00f3n de tortura quedar\u00eda vaciada de contenido, convirti\u00e9ndose en un derecho meramente formal sin ninguna consecuencia operativa\u201d, advierte la sentencia.<\/p>\n\n\n\n<p>El Estado tambi\u00e9n est\u00e1 en la obligaci\u00f3n de investigar y sancionar a los responsables de los actos de tortura, as\u00ed como pagar indemnizaciones a ambas v\u00edctimas por concepto de da\u00f1os materiales e inmateriales.<\/p>\n\n\n\n<p>Emanuel Joaquin Mateo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Miercoles, 12 de abril del 2023 La CIDH sostiene que M\u00e9xico deber\u00e1 adecuar a est\u00e1ndares&#8230;<\/p>\n","protected":false},"author":3,"featured_media":59007,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-59006","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policiaca"],"_links":{"self":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/59006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=59006"}],"version-history":[{"count":1,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/59006\/revisions"}],"predecessor-version":[{"id":59008,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/59006\/revisions\/59008"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media\/59007"}],"wp:attachment":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=59006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=59006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=59006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}