{"id":59022,"date":"2023-04-12T12:12:01","date_gmt":"2023-04-12T18:12:01","guid":{"rendered":"http:\/\/bambapolitica.com.mx\/?p=59022"},"modified":"2023-04-12T12:12:03","modified_gmt":"2023-04-12T18:12:03","slug":"teorizar-el-feminismo-desde-el-barrio-entrevista-con-dahlia-de-la-cerda","status":"publish","type":"post","link":"https:\/\/bambapolitica.com.mx\/index.php\/2023\/04\/12\/teorizar-el-feminismo-desde-el-barrio-entrevista-con-dahlia-de-la-cerda\/","title":{"rendered":"Teorizar el feminismo desde el barrio: entrevista con Dahlia de la Cerda"},"content":{"rendered":"\n<p>Miercoles, 12 de abril del 2023<\/p>\n\n\n\n<p>Con franqueza y autocr\u00edtica, la escritora retrata en Desde los zulos, que recientemente publica Sexto Piso, una serie de vivencias y reflexiones sobre la marginalidad y el borrado hist\u00f3rico de las mujeres. Ganadora del Premio Nacional de Cuento Joven en 2019, la autora apuesta por explorar y denunciar los vicios que han permeado<br>a los movimientos emancipatorios<br>POR DONOVAN KREMER<br>Crecer situada en la marginalidad, en el punto remoto del olvido, y emerger desde ah\u00ed con una literatura de pasos firmes, reivindicativa, es lo que caracteriza a Dahlia de la Cerda (Aguascalientes, 1985), que a su vez es ya un fen\u00f3meno cr\u00edtico y neurol\u00f3gico de los feminismos ramificados.<\/p>\n\n\n\n<p>Su apuesta es total, de ah\u00ed que manifieste una prosa que circunda entre la autoficci\u00f3n, la cr\u00f3nica y el pensamiento feminista, prueba de ello es Desde los zulos (Sexto Piso, 2023), donde hace de la experiencia personal un recurso con el cual logra que conceptos abstractos como el de la \u201copresi\u00f3n\u201d sean palpables, dejando de lado al \u201cente patriarcal\u201d al optar por la reflexi\u00f3n de las relaciones de poder, la violencia, el racismo, la transfobia y las desigualdades pol\u00edtico y socioecon\u00f3micas que trasminan los movimientos emancipatorios.<\/p>\n\n\n\n<p>La tambi\u00e9n autora de Perras de reserva, obra por la cual gan\u00f3 el Premio Nacional de Cuento Joven Comala 2019, catapulta un feminismo que recupera las voces, las vivencias y las teorizaciones de mujeres que saltan de la marginalidad, del borrado hist\u00f3rico. Es, quiz\u00e1, \u201cFeminismo sin cuarto propio\u201d el ensayo que delinea su visi\u00f3n y a la par nutre su literatura situada. En este sentido, comenta que su objetivo te\u00f3rico y literario (al que llama praxis) es \u201ccomplejizar a las mujeres\u201d.<\/p>\n\n\n\n<p>La transici\u00f3n de un entorno precario a uno con mayores privilegios es una situaci\u00f3n con la que batalla, lo reconoce en p\u00e1rrafos y a viva voz, no acaba de adaptarse a los reflectores, a una vida fuera del barrio y, sin embargo, guarda una fascinaci\u00f3n por el estilo de vida m\u00e1s holgado. Al momento de la entrevista, Dahlia se encuentra en la colonia Roma, una zona con est\u00e1ndares de clase media-alta, con una gentrificaci\u00f3n evidente en cada esquina, dentro de la cafeter\u00eda el P\u00e9ndulo, rodeada de libreros y desconocidos que conversan en otro idioma o leen o juegan partidas de ajedrez en un mutismo que los separa.<\/p>\n\n\n\n<p>Emanuel Joaquin Mateo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Miercoles, 12 de abril del 2023 Con franqueza y autocr\u00edtica, la escritora retrata en Desde&#8230;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-59022","post","type-post","status-publish","format-standard","hentry","category-cultura"],"_links":{"self":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/59022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=59022"}],"version-history":[{"count":1,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/59022\/revisions"}],"predecessor-version":[{"id":59023,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/59022\/revisions\/59023"}],"wp:attachment":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=59022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=59022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=59022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}