{"id":59135,"date":"2023-04-15T10:57:10","date_gmt":"2023-04-15T16:57:10","guid":{"rendered":"http:\/\/bambapolitica.com.mx\/?p=59135"},"modified":"2023-04-14T10:58:17","modified_gmt":"2023-04-14T16:58:17","slug":"crean-app-de-taxis-para-mujeres-en-edomex","status":"publish","type":"post","link":"https:\/\/bambapolitica.com.mx\/index.php\/2023\/04\/15\/crean-app-de-taxis-para-mujeres-en-edomex\/","title":{"rendered":"Crean app de taxis para mujeres en Edomex"},"content":{"rendered":"\n<p>S\u00e1bado , 15 de abril del 2023<\/p>\n\n\n\n<p>Datos del Inegi se\u00f1alan que 91 por ciento de las mujeres mayores de 18 a\u00f1os se sienten inseguras al viajar en el transporte p\u00fablico debido al acoso que viven.<br>Ante los altos \u00edndices de violencia de g\u00e9nero e inseguridad que se ha presentado en el transporte p\u00fablico y privado, un grupo de emprendedoras del Estado de M\u00e9xico lanz\u00f3 un nuevo servicio de taxi por aplicaci\u00f3n a la que llamaron Woman Drive.<\/p>\n\n\n\n<p>De acuerdo con datos del Instituto Nacional de Estad\u00edstica y Geograf\u00eda (Inegi) alrededor de 91.21 por ciento de las mujeres mayores de 18 a\u00f1os se sienten inseguras al viajar en el transporte p\u00fablico debido de al acoso cotidiano que se vive.<br>\u00bfDe qu\u00e9 trata Woman Drive?<br>Seg\u00fan sus fundadoras, esta aplicaci\u00f3n responde a la necesidad de traslados seguros en la entidad, en medio de lo que las emprendedoras consideran como una nula respuesta por parte de las autoridades correspondientes.<\/p>\n\n\n\n<p>\u201cLa idea surge a partir de la necesidad de brindar un transporte m\u00e1s seguro y m\u00e1s confiable para las mujeres. Es bien importante el tema de la inseguridad para las mujeres en el transporte p\u00fablico y creo que es un tema que se tiene no tan atendido\u201d, coment\u00f3 Ana Paulina S\u00e1nchez, conductora de Woman Drive.<br>La mayor parte de los traslados que se hacen en la aplicaci\u00f3n son de estudiantes o madres que llevan a sus hijas e hijos a la escuela; tambi\u00e9n es una gran opci\u00f3n para quienes desean regresar seguras a casa.<br>\u201cEn nuestros viajes lo que nosotras hemos detectado que hay muchos servicios escolares. Nosotras les llamamos &#8220;escolar&#8221;: chicas universitarias, chicas de preparatoria, mam\u00e1s. Tambi\u00e9n chicas que dicen &#8216;yo me voy de fiesta&#8217;, o &#8216;me voy al concierto con mi hija&#8217;, y programan un servicio para que pasemos por ellas despu\u00e9s del evento\u201d, dijo la conductora.<br>La aplicaci\u00f3n adem\u00e1s cuenta con un apartado de emprendimiento para que las usuarias promocionen sus servicios y juntas se apoyen econ\u00f3micamente.<\/p>\n\n\n\n<p>En este momento hay 20 conductoras, quienes sostienen, se someten a estrictos controles de seguridad y psicom\u00e9tricos, el servicio abarca Toluca y Metepec y esperan que se pueda ampliar a m\u00e1s zonas el servicio.<\/p>\n\n\n\n<p>\u201cLas usuarias se sienten cuidadas, atentas, con confianza y con mucha calidez respecto al servicio que se les brinda\u201d, asegur\u00f3 Paulina S\u00e1nchez.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00e1bado , 15 de abril del 2023 Datos del Inegi se\u00f1alan que 91 por ciento&#8230;<\/p>\n","protected":false},"author":3,"featured_media":59136,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-59135","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-del-dia"],"_links":{"self":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/59135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=59135"}],"version-history":[{"count":1,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/59135\/revisions"}],"predecessor-version":[{"id":59137,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/59135\/revisions\/59137"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media\/59136"}],"wp:attachment":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=59135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=59135"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=59135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}