{"id":59163,"date":"2023-04-15T11:43:39","date_gmt":"2023-04-15T17:43:39","guid":{"rendered":"http:\/\/bambapolitica.com.mx\/?p=59163"},"modified":"2023-04-14T11:45:31","modified_gmt":"2023-04-14T17:45:31","slug":"al-menos-21-lesionados-por-choque-en-la-mexico-queretaro","status":"publish","type":"post","link":"https:\/\/bambapolitica.com.mx\/index.php\/2023\/04\/15\/al-menos-21-lesionados-por-choque-en-la-mexico-queretaro\/","title":{"rendered":"Al menos 21 lesionados por choque en la M\u00e9xico-Quer\u00e9taro"},"content":{"rendered":"\n<p>Sabado , 15 de abril del 2023<\/p>\n\n\n\n<p>Un cami\u00f3n de transporte de pasajeros choc\u00f3 contra un cami\u00f3n recolector sobre la carretera M\u00e9xico-Quer\u00e9taro, dejando 21 lesionadas<br>Unas 21 personas resultaron lesionadas en un choque sobre la carretera M\u00e9xico-Quer\u00e9taro.<\/p>\n\n\n\n<p>El percance ocurri\u00f3 con direcci\u00f3n a la Ciudad de M\u00e9xico, a la altura de El Colorado<br>Protecci\u00f3n Civil del estado de Quer\u00e9taro inform\u00f3 que un cami\u00f3n de pasajeros, que transportaba a empleados de la empresa EmQro, se impact\u00f3 contra un cami\u00f3n recolector.<\/p>\n\n\n\n<p>La unidad privada result\u00f3 con severos da\u00f1os en la parte delantera, que incluyen la rotura del parabrisas.<\/p>\n\n\n\n<p>Derivado del choque autoridades evaluaron a 21 personas, quienes viajaban a bordo del cami\u00f3n de pasajeros.<\/p>\n\n\n\n<p>La circulaci\u00f3n sobre la M\u00e9xico-Quer\u00e9taro se vio afectada durante las labores de retiro de las unidades.<\/p>\n\n\n\n<p>Emanuel Joaquin Mateo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sabado , 15 de abril del 2023 Un cami\u00f3n de transporte de pasajeros choc\u00f3 contra&#8230;<\/p>\n","protected":false},"author":3,"featured_media":59164,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-59163","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policiaca"],"_links":{"self":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/59163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=59163"}],"version-history":[{"count":1,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/59163\/revisions"}],"predecessor-version":[{"id":59165,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/59163\/revisions\/59165"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media\/59164"}],"wp:attachment":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=59163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=59163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=59163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}