{"id":59180,"date":"2023-04-28T11:15:18","date_gmt":"2023-04-28T17:15:18","guid":{"rendered":"http:\/\/bambapolitica.com.mx\/?p=59180"},"modified":"2023-04-28T11:15:22","modified_gmt":"2023-04-28T17:15:22","slug":"lopez-obrador-denuncia-mala-fe-sobre-su-salud-al-retomar-actividades","status":"publish","type":"post","link":"https:\/\/bambapolitica.com.mx\/index.php\/2023\/04\/28\/lopez-obrador-denuncia-mala-fe-sobre-su-salud-al-retomar-actividades\/","title":{"rendered":"L\u00f3pez Obrador denuncia \u201cmala fe\u201d sobre su salud al retomar actividades"},"content":{"rendered":"\n<p>El presidente mexicano,\u00a0<strong><a rel=\"noreferrer noopener\" href=\"https:\/\/twitter.com\/lopezobrador_\" target=\"_blank\">Andr\u00e9s Manuel<\/a>\u00a0L\u00f3pez Obrador<\/strong>, denunci\u00f3 que hubo \u201c<strong>mala fe<\/strong>\u201d y \u201c<strong>amarillismo<\/strong>\u201d sobre su salud al retomar este viernes sus actividades oficiales tras cinco d\u00edas de su\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/lopezdoriga.com\/nacional\/reaparece-lopez-obrador-en-la-mananera-tras-su-contagio-por-covid-19\/\" target=\"_blank\">contagio por\u00a0<strong>COVID-19<\/strong><\/a>.<\/p>\n\n\n\n<p>La salud del mandatario, de 69 a\u00f1os, caus\u00f3 inquietud tras su contagio de COVID-19 el domingo pasado, despu\u00e9s del que estuvo 72 horas sin emitir ning\u00fan mensaje.<\/p>\n\n\n\n<p>El presidente ya hab\u00eda contra\u00eddo COVID-19 dos veces antes, la primera en enero de 2021 y la segunda en enero de 2022, y en ambas ocasiones public\u00f3 im\u00e1genes desde el aislamiento.<\/p>\n\n\n\n<p>Adem\u00e1s, padece de hipertensi\u00f3n, en enero de 2022 tuvo un cateterismo, una exploraci\u00f3n en el coraz\u00f3n, y en diciembre de 2013 sufri\u00f3 un infarto agudo de miocardio, por lo que entonces tuvo una cirug\u00eda coronaria.<\/p>\n\n\n\n<p>\u201cEstamos bien y con muchos deseos de seguir transformando nuestro pa\u00eds en beneficio de nuestro querido pueblo\u201d, insisti\u00f3 ahora L\u00f3pez Obrador.<\/p>\n\n\n\n<p>La informaci\u00f3n sobre su salud caus\u00f3 un conflicto pol\u00edtico, en el que organizaciones civiles y la oposici\u00f3n exigieron transparencia por considerarlo un asunto de seguridad nacional e inter\u00e9s p\u00fablico.<\/p>\n\n\n\n<p>Mientras que el Gobierno de M\u00e9xico denunci\u00f3 una \u201c<strong>campa\u00f1a de odio<\/strong>\u201d en contra del mandatario por las especulaciones, como un presunto infarto que se desminti\u00f3.<\/p>\n\n\n\n<p>\u201cPrimero (quiero) agradecerle de todo coraz\u00f3n al pueblo de M\u00e9xico por todo su apoyo, su solidaridad. Si digo pueblo, estoy pensando en casi todos los mexicanos que expresaron su preocupaci\u00f3n por mi contagio de covid\u201d, coment\u00f3 L\u00f3pez Obrador.<\/p>\n\n\n\n<p>La especulaci\u00f3n creci\u00f3 por versiones encontradas sobre su salud.<\/p>\n\n\n\n<p>El d\u00eda de su contagio, el vocero de la Presidencia,&nbsp;<strong>Jes\u00fas Ram\u00edrez Cuevas<\/strong>, afirm\u00f3 que el mandatario estaba bien, aunque ya ten\u00eda s\u00edntomas de la enfermedad.<\/p>\n\n\n\n<p>Mientras que el mandatario reconoci\u00f3 el mi\u00e9rcoles que tuvo un \u201cdesmayo transitorio\u201d, algo que el Gobierno hab\u00eda desmentido.<\/p>\n\n\n\n<p>Pese a la pol\u00e9mica, L\u00f3pez Obrador destac\u00f3 que durante su enfermedad \u201chubo muestras de cari\u00f1o, muchas bendiciones, buenos deseos, cadenas de oraci\u00f3n, mucha solidaridad. Se portaron, como siempre, muy bien. Es un amor rec\u00edproco\u201d.<\/p>\n\n\n\n<p>Emanuel Joaquin Mateo<\/p>\n\n\n\n<figure class=\"wp-block-embed\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/b56fd6b65b47adfaa0e1957f580c2ae7.safeframe.googlesyndication.com\/safeframe\/1-0-40\/html\/container.html\n<\/div><\/figure>\n\n\n\n<p>El presidente L\u00f3pez Obrador denunci\u00f3 \u201csensacionalismo, amarillismo, mala fe\u201d sobre su estado de salud, tras el contagio por COVID-19<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente mexicano,\u00a0Andr\u00e9s Manuel\u00a0L\u00f3pez Obrador, denunci\u00f3 que hubo \u201cmala fe\u201d y \u201camarillismo\u201d sobre su salud&#8230;<\/p>\n","protected":false},"author":3,"featured_media":59182,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-59180","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"_links":{"self":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/59180","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=59180"}],"version-history":[{"count":1,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/59180\/revisions"}],"predecessor-version":[{"id":59183,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/59180\/revisions\/59183"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media\/59182"}],"wp:attachment":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=59180"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=59180"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=59180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}