{"id":59187,"date":"2023-04-28T11:25:01","date_gmt":"2023-04-28T17:25:01","guid":{"rendered":"http:\/\/bambapolitica.com.mx\/?p=59187"},"modified":"2023-04-28T11:25:02","modified_gmt":"2023-04-28T17:25:02","slug":"al-menos-cinco-muertos-en-ataque-ruso-con-misiles-contra-ciudades-de-ucrania","status":"publish","type":"post","link":"https:\/\/bambapolitica.com.mx\/index.php\/2023\/04\/28\/al-menos-cinco-muertos-en-ataque-ruso-con-misiles-contra-ciudades-de-ucrania\/","title":{"rendered":"Al menos cinco muertos en ataque ruso con misiles contra ciudades de Ucrania"},"content":{"rendered":"\n<p>Al menos tres personas murieron esta madrugada en la ciudad de\u00a0<strong>Um\u00e1n<\/strong>, en el centro de\u00a0<strong>Ucrania<\/strong>, y otras dos en\u00a0<strong>Dnipr\u00f3<\/strong>\u00a0(este) en un ataque masivo con misiles rusos que ha alcanzado zonas civiles, informaron las autoridades ucranianas.<\/p>\n\n\n\n<p>Seg\u00fan la autoridad militar de la provincia de\u00a0<strong>Cherkasy<\/strong>, en la que se encuentra Um\u00e1n, un misil impact\u00f3 en un bloque de viviendas, destruyendo el edificio y matando a tres personas. Otros ocho civiles han resultado heridos.<\/p>\n\n\n\n<p>En Dnipr\u00f3, el alcalde de la ciudad, Boris Filatov, inform\u00f3 de la muerte de una\u00a0<strong>mujer<\/strong>\u00a0y de su hijo de tres a\u00f1os como consecuencia de otro ataque ruso. La capital ucraniana,\u00a0<strong>Kiev,<\/strong>\u00a0tambi\u00e9n ha sido alcanzada por varios misiles sin que se conozcan por el momento si han ocasionado v\u00edctimas.<\/p>\n\n\n\n<p>Emnanuel Joaquin Mateo<\/p>\n\n\n\n<figure class=\"wp-block-embed\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/9a7d8a7f2c8e732a2f7c90bd0afb21a8.safeframe.googlesyndication.com\/safeframe\/1-0-40\/html\/container.html\n<\/div><\/figure>\n\n\n\n<p>Seg\u00fan autoridades de Ucrania, un misil impact\u00f3 en un bloque de viviendas, destruyendo el edificio y matando a tres personas<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al menos tres personas murieron esta madrugada en la ciudad de\u00a0Um\u00e1n, en el centro de\u00a0Ucrania,&#8230;<\/p>\n","protected":false},"author":3,"featured_media":59188,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-59187","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional"],"_links":{"self":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/59187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=59187"}],"version-history":[{"count":1,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/59187\/revisions"}],"predecessor-version":[{"id":59189,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/59187\/revisions\/59189"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media\/59188"}],"wp:attachment":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=59187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=59187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=59187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}