{"id":59495,"date":"2023-05-09T12:18:42","date_gmt":"2023-05-09T18:18:42","guid":{"rendered":"http:\/\/bambapolitica.com.mx\/?p=59495"},"modified":"2023-05-09T12:18:46","modified_gmt":"2023-05-09T18:18:46","slug":"pegan-a-atizapan-los-robos-crecen-5-tipos","status":"publish","type":"post","link":"https:\/\/bambapolitica.com.mx\/index.php\/2023\/05\/09\/pegan-a-atizapan-los-robos-crecen-5-tipos\/","title":{"rendered":"Pegan a Atizap\u00e1n los robos; crecen 5 tipos"},"content":{"rendered":"\n<p>Martes 9 de mayo 2023<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"m36-35-37\">En marzo robo a transe\u00fante aumenta 30% comparado con febrero; en transporte p\u00fablico, 54%; en calles del municipio gobernado por el panista Pedro Rodr\u00edguez, vecinos dicen sentir temor<\/h2>\n\n\n\n<p id=\"m86-85-87\">\u201cHace una semana a mi prima la asaltaron en la escalera al subir a la casa, llevaba a su beb\u00e9 en los brazos y la aventaron, quedaron muy lastimados\u201d, confi\u00f3 a La Raz\u00f3n Sof\u00eda, trabajadora de una farmacia ubicada en bulevar Adolfo L\u00f3pez Mateos, en la colonia Potrero de Atizap\u00e1n de Zaragoza.<\/p>\n\n\n\n<p id=\"m96-95-97\">Por la zona, las calles lucen solitarias y muchos comercios tienen rejas para protegerse de los asaltos. En este municipio del Estado de M\u00e9xico, gobernado por el panista Pedro Rodr\u00edguez Villegas, cinco modalidades del delito de robo presentaron alza durante marzo, en comparaci\u00f3n con el mes inmediato anterior. Entre ellos est\u00e1 el robo a transe\u00fante, con 30 por ciento de aumento, ya que en marzo hubo 95 casos, contra 73 de febrero.<\/p>\n\n\n\n<p id=\"m101-100-102\">La farmacia en la que trabaja Sof\u00eda \u2014el nombre es ficticio a petici\u00f3n suya\u2014 es uno de los negocios que est\u00e1n enrejados. \u201cEsto me hace sentir m\u00e1s tranquila, aqu\u00ed los vecinos son muy unidos, pero a determinada hora se van y aqu\u00ed pasan algunos muchachos que uno nunca sabe \u2026 la reja me hace sentir m\u00e1s segura\u201d expres\u00f3 con timidez.<\/p>\n\n\n\n<p id=\"m111-110-112\">En este municipio, que forma parte del corredor azul, crecieron en total siete delitos durante el pasado mes de marzo, entre ellos el robo a negocio, con 48 por ciento. Uno de los delitos que presenta alza es el de homicidio, con 50 por ciento, ya que en febrero hubo dos asesinatos y en marzo la cifra fue de tres.<\/p>\n\n\n\n<p id=\"m142-141-143\">Adem\u00e1s, de acuerdo con cifras del Observatorio Nacional Ciudadano, el robo en transporte p\u00fablico creci\u00f3 54.5 por ciento, al pasar los expedientes de 11 a 17 entre un mes y otro.<\/p>\n\n\n\n<p id=\"m147-146-148\">Esto se refleja en el sentir de la poblaci\u00f3n, la cual dice sentir inseguridad y miedo de sufrir un asalto tanto en la calle como en el transporte p\u00fablico, porque, aseguran, \u201clos asaltos se dan sobre todo en las combis\u201d.<\/p>\n\n\n\n<p id=\"m157-156-158\">El fen\u00f3meno se ve tambi\u00e9n retratado en la m\u00e1s reciente Encuesta Nacional de Seguridad P\u00fablica Urbana (ENSU) del Inegi, la cual revela que la percepci\u00f3n de inseguridad en Atizap\u00e1n de Zaragoza aument\u00f3<\/p>\n\n\n\n<p id=\"m162-161-163\">1.8 puntos durante el primer trimestre de este a\u00f1o, en comparaci\u00f3n con el mismo periodo inmediato anterior, al pasar de 39 a 40.8 por ciento.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"620\" height=\"295\" src=\"https:\/\/bambapolitica.com.mx\/wp-content\/uploads\/2023\/05\/6459b03f33ff2.png\" alt=\"\" class=\"wp-image-59496\" srcset=\"https:\/\/bambapolitica.com.mx\/wp-content\/uploads\/2023\/05\/6459b03f33ff2.png 620w, https:\/\/bambapolitica.com.mx\/wp-content\/uploads\/2023\/05\/6459b03f33ff2-300x143.png 300w, https:\/\/bambapolitica.com.mx\/wp-content\/uploads\/2023\/05\/6459b03f33ff2-260x124.png 260w, https:\/\/bambapolitica.com.mx\/wp-content\/uploads\/2023\/05\/6459b03f33ff2-50x24.png 50w, https:\/\/bambapolitica.com.mx\/wp-content\/uploads\/2023\/05\/6459b03f33ff2-150x71.png 150w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/figure>\n\n\n\n<p id=\"m167-166-168\">Otras dos modalidades de robo, a casa habitaci\u00f3n y con violencia, tambi\u00e9n tuvieron incremento. En el primer caso, las carpetas pasaron de 25 a 27 de un mes a otro, lo que represente un alza del 8 por ciento.<\/p>\n\n\n\n<p id=\"m172-171-173\">En el segundo el aumento fue de 8.6 por ciento, toda vez que en febrero se iniciaron 69 averiguaciones previas, mientras que en marzo la cifra fue de 75.<\/p>\n\n\n\n<p id=\"m177-176-178\">\u201cAqu\u00ed de d\u00eda est\u00e1 tranquilo, el problema es cuando se empieza a oscurecer, por eso procuramos cerrar todos a la misma hora para evitar arriesgarnos\u201d, coment\u00f3 la encargada de una dulcer\u00eda.<\/p>\n\n\n\n<p id=\"m182-181-183\">La mujer refiri\u00f3 que los comerciantes est\u00e1n en constante comunicaci\u00f3n, para poder auxiliarse unos a otros. \u201cEn una ocasi\u00f3n agarramos a un asaltante y lo golpearon los vecinos\u201d, remarc\u00f3.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.razon.com.mx\/estados\/alza-cinco-tipos-robo-atizapan-527613\">https:\/\/www.razon.com.mx\/estados\/alza-cinco-tipos-robo-atizapan-527613<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Martes 9 de mayo 2023 En marzo robo a transe\u00fante aumenta 30% comparado con febrero;&#8230;<\/p>\n","protected":false},"author":3,"featured_media":59497,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17,4,2],"tags":[],"class_list":["post-59495","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","category-noticias-del-dia","category-policiaca"],"_links":{"self":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/59495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=59495"}],"version-history":[{"count":1,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/59495\/revisions"}],"predecessor-version":[{"id":59498,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/59495\/revisions\/59498"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media\/59497"}],"wp:attachment":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=59495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=59495"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=59495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}