{"id":59995,"date":"2023-05-25T11:29:07","date_gmt":"2023-05-25T17:29:07","guid":{"rendered":"http:\/\/bambapolitica.com.mx\/?p=59995"},"modified":"2023-05-25T11:29:12","modified_gmt":"2023-05-25T17:29:12","slug":"pan-se-moreniza-y-propone-presidenciable-por-encuesta","status":"publish","type":"post","link":"https:\/\/bambapolitica.com.mx\/index.php\/2023\/05\/25\/pan-se-moreniza-y-propone-presidenciable-por-encuesta\/","title":{"rendered":"PAN se moreniza y propone presidenciable &#8220;por encuesta&#8221;"},"content":{"rendered":"\n<p>Jueves 25 de mayo 2023<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La propuesta de Marko Cort\u00e9s consta de tres etapas: convocatoria, debates y encuesta final en noviembre; juntar firmas, un requisito.<\/h2>\n\n\n\n<p>El Partido Acci\u00f3n Nacional (PAN) plante\u00f3 al PRI, PRD y grupos empresariales apostar por emparejar el proceso de selecci\u00f3n de su candidatura presidencial con el de Morena,&nbsp;y hasta seguir sus pasos, para recuperar el tiempo perdido: lanzar convocatoria en julio; depuraci\u00f3n de aspirantes, foros y debates en agosto as\u00ed como septiembre; y una encuesta final en noviembre.<\/p>\n\n\n\n<p>MILENIO confirm\u00f3 que el m\u00e9todo, el cual Marko Cort\u00e9s espera sea respaldado por Alejandro Moreno y Jes\u00fas Zambrano, es lanzar la convocatoria en julio y pedir requisitos como: haber sido considerado en mediciones de encuestas externas, los cuales les den un posicionamiento de al menos el 30 por ciento de reconocimiento de la ciudadan\u00eda y de intenci\u00f3n de voto, que los haga competitivos frente a las corcholatas de Morena, y la entrega de firmas equivalentes al uno por ciento del padr\u00f3n electoral de al menos 17 entidades.<\/p>\n\n\n\n<p>Una vez cumplidos los requisitos, es decir, depurada la lista de aspirantes, la segunda fase ser\u00e1 realizar foros y debates regionales en todo el pa\u00eds para posicionarse ante la ciudadan\u00eda durante al menos dos meses.&nbsp;<\/p>\n\n\n\n<p>Y para finalizar, al mismo estilo de Morena, se realizar\u00eda una encuesta con los mejores posicionados&nbsp;para definir en noviembre qui\u00e9n ser\u00e1 la persona abanderada presidencial.<\/p>\n\n\n\n<p>Para todo este proceso, el PAN plantea crear una especie de Comisi\u00f3n Electoral&nbsp;\u2014integrada por liderazgos de los tres partidos pol\u00edticos y la sociedad civil\u2014, descartando elecciones primarias, para garantizar que los finalistas lleguen bajo las mismas condiciones y no con m\u00e9todos diferentes de cada partido.<\/p>\n\n\n\n<p>Sin embargo, en las \u00faltimas horas se desataron enfrentamientos entre aspirantes y liderazgos. Entre la confusi\u00f3n de quienes creen que deber\u00e1n reunir un mill\u00f3n de firmas, aunque ese n\u00famero no sea preciso; quienes cuestionan qui\u00e9n verificar\u00e1 la validez de esos apoyos si es una facultad exclusiva del INE; quienes critican la burocracia y tardanza del proceso y quienes se aferran a las primarias entre los partidos coaligados.<br><\/p>\n\n\n\n<p>Propuesta del PAN, rechazada por PRD y Lilly T\u00e9llez&nbsp;<\/p>\n\n\n\n<p>El m\u00e9todo que el PAN puso sobre la mesa para llevar la batuta del 2024 no ha quedado claro, ni mucho menos, respaldado al interior del propio partido, pues sin ning\u00fan aval previo, Marko Cort\u00e9s se adelant\u00f3 a anticipar algunos de los requisitos que pretenden imponer para depurar la lista de decenas de suspirantes que han y siguen levantando la mano para la carrera presidencial.<\/p>\n\n\n\n<p>Dentro, como fuera del PAN, ha sido rechazada la idea de Cort\u00e9s sobre mantener la esencia que ha caracterizado a las candidaturas presidenciales panistas de tener el respaldo de la militancia, y pasarlo ahora al apoyo ciudadano.<\/p>\n\n\n\n<p>Los principales punteros se han inconformado con la idea de este m\u00e9todo. Del lado del PRD, su dirigente Jes\u00fas Zambrano, sostuvo que \u201cde ninguna manera\u201d aceptar\u00edan la recolecci\u00f3n de firmas como requisito, mientras que Miguel \u00c1ngel Mancera advirti\u00f3 que no existe certeza en c\u00f3mo se comprobar\u00e1 la veracidad de las firmas y qui\u00e9n las contar\u00e1.<\/p>\n\n\n\n<p>\u201cUrge la construcci\u00f3n de un m\u00e9todo conjunto en donde puedan estar las opiniones y las ideas sumadas, no la enumeraci\u00f3n de requisitos sino la construcci\u00f3n de un m\u00e9todo. Si cuando las firmas se han verificado por el INE resulta una gran cantidad de firmas falsas, me parece que un proceso as\u00ed ser\u00eda poco adecuado. Si ese es el m\u00e9todo dif\u00edcilmente va a haber un consenso y dif\u00edcilmente se va a lograr la unidad que se espera\u201d, dijo en MILENIO Televisi\u00f3n.<br>Mientras que dentro del propio PAN, la senadora Lilly T\u00e9llez incluso ha acusado que es un m\u00e9todo para favorecer a Santiago Creel y se aventur\u00f3 a sostener que se requieren 30 millones de pesos para cumplir con este requisito.<\/p>\n\n\n\n<p>Impreciso, juntar un mill\u00f3n de firmar<br>Gran parte de la confusi\u00f3n se centra en la cifra de un mill\u00f3n de firmas, lo que es impreciso, pues aunque el padr\u00f3n electoral nacional es de 95 millones 884 mil 693, la propuesta que se ha establecido hasta ahora, es que los aspirantes presenten el uno por ciento del padr\u00f3n electoral de al menos 17 entidades federativas, no del padr\u00f3n nacional \u00edntegro, por lo que la cifra depender\u00e1 de la estrategia que asuma cada aspirante y las entidades por las cuales apueste.<\/p>\n\n\n\n<p>Por ejemplo, si los aspirantes optan por las 17 entidades con el padr\u00f3n electoral m\u00e1s peque\u00f1o (Hidalgo, Sinaloa, Sonora, San Luis Potos\u00ed, Quer\u00e9taro, Tabasco, Yucat\u00e1n, Morelos, Quintana Roo, Durango, Zacatecas, Aguascalientes, Tlaxcala, Nayarit, Campeche, Baja California Sur y Colima) en conjunto, tendr\u00edan que reunir 244 mil 660 firmas.<\/p>\n\n\n\n<p>Aunque los panistas esperar\u00edan que se compruebe el respaldo al menos en sus cinco bastiones, que juntos, sumar\u00edan 122 mil 106 firmas. Por Guanajuato, 46 mil 647, al tener el padr\u00f3n electoral m\u00e1s grande entre los gobiernos panistas, con 4.6 millones de personas mayores de edad; le seguir\u00edan 29 mil 671 firmas en Chihuahua, 18 mil 225 en Quer\u00e9taro, 17 mil 59 en Yucat\u00e1n y 10 mil 524 en Aguascalientes.<\/p>\n\n\n\n<p>Tambi\u00e9n depender\u00e1 del origen de cada aspirante, quienes deber\u00edan al menos, presentar el respaldo de su entidad natal.&nbsp;<\/p>\n\n\n\n<p>Por ejemplo, Lilly T\u00e9llez tendr\u00eda que entregar el respaldo de Sonora, que es el n\u00famero 18 en cuanto a tama\u00f1o del padr\u00f3n, en contraste con Santiago Creel, de la Ciudad de M\u00e9xico, la segunda entidad con m\u00e1s electores y que el uno por ciento asciende a 77 mil 430 personas.<\/p>\n\n\n\n<p>En contraste, el m\u00e9todo de las primarias en las que insiste principalmente la iniciativa privada, tiene imposibilidades legales, pues se tratar\u00eda de una elecci\u00f3n interna, lo que las autoridades electorales catalogar\u00edan como un proceso de precampa\u00f1a que s\u00f3lo estar\u00eda permitido realizarse hasta ese periodo que comenzar\u00eda hasta diciembre.<br>https:\/\/www.milenio.com\/politica\/pan-propone-copiar-morena-elegir-candidato-presidencial<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jueves 25 de mayo 2023 La propuesta de Marko Cort\u00e9s consta de tres etapas: convocatoria,&#8230;<\/p>\n","protected":false},"author":3,"featured_media":59996,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-59995","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-del-dia"],"_links":{"self":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/59995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=59995"}],"version-history":[{"count":1,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/59995\/revisions"}],"predecessor-version":[{"id":59997,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/59995\/revisions\/59997"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media\/59996"}],"wp:attachment":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=59995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=59995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=59995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}