{"id":60047,"date":"2023-05-26T11:58:28","date_gmt":"2023-05-26T17:58:28","guid":{"rendered":"http:\/\/bambapolitica.com.mx\/?p=60047"},"modified":"2023-05-26T11:58:37","modified_gmt":"2023-05-26T17:58:37","slug":"metro-cdmx-hoy-linea-3-restablecida-pero-con-tremendo-caos","status":"publish","type":"post","link":"https:\/\/bambapolitica.com.mx\/index.php\/2023\/05\/26\/metro-cdmx-hoy-linea-3-restablecida-pero-con-tremendo-caos\/","title":{"rendered":"Metro CDMX hoy: L\u00ednea 3 restablecida, pero con tremendo caos"},"content":{"rendered":"\n<p>Viernes 26 de mayo 2023<\/p>\n\n\n\n<p>Usuarios del Metro CDMX reportan aglomeraci\u00f3n y servicio lento en algunas l\u00edneas este viernes 26 de mayo, principalmente en la L\u00ednea 3, direcci\u00f3n Universidad.<\/p>\n\n\n\n<p>El&nbsp;<strong>Metro de la&nbsp;Ciudad de M\u00e9xico&nbsp;(CDMX)&nbsp;<\/strong>da servicio diariamente a m\u00e1s de cuatro millones de usuarios. Te presentamos el avance, saturaci\u00f3n, servicio y todos los pormenores que ocurren en el<a href=\"https:\/\/www.excelsior.com.mx\/metro\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;<\/a><strong><a href=\"https:\/\/www.excelsior.com.mx\/metro\" target=\"_blank\" rel=\"noreferrer noopener\">Sistema de Transporte Colectivo<\/a>&nbsp;(STC) en este viernes 26 de mayo de 2023.<\/strong><\/p>\n\n\n\n<p>Usuarios de la\u00a0<strong>L\u00ednea 3 del\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/www.metro.cdmx.gob.mx\/\" target=\"_blank\">Metro<\/a><\/strong>, que va de\u00a0<strong>Indios Verdes a Universidad<\/strong>, reportan servicio lento y hasta 10 minutos de espera para poder abordar un tren, lo que deriva en tremendo caos.<\/p>\n\n\n\n<p>Asimismo, reportan retrasos en L<strong>\u00ednea 9, que va de Pantitl\u00e1n a Tacubaya<\/strong>, aseguran est\u00e1n demorando much\u00edsimo el arribo de trenes y hay saturaci\u00f3n de usuarios. &nbsp;<\/p>\n\n\n\n<p>A las 6:33 de la ma\u00f1ana, el Metro inform\u00f3 que<strong>\u00a0el paso de trenes es lento en l\u00edneas 3, 4 y, A,\u00a0<\/strong>principalmente, con tiempos de espera de entre seis y cinco minutos; mientras que report\u00f3\u00a0<strong>afluencia alta de usuarios en l\u00edneas 3, 6, 9, A y B.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 hacer si sufres acoso o agresi\u00f3n en el Metro?<\/strong><\/h2>\n\n\n\n<p>En caso de emergencia por acoso o agresi\u00f3n dentro del Metro, comun\u00edcate a la L\u00ednea SOS de Mujeres *765, esto para recibir atenci\u00f3n especializada en casos de violencia de g\u00e9nero.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 opciones hay para la L\u00ednea 1 que est\u00e1 en obra?<\/strong><\/h2>\n\n\n\n<p>El STC da a conocer que con motivo de la Nueva L\u00ednea 1, una opci\u00f3n de movilidad en la CDMX y Zona Metropolitana del Valle de M\u00e9xico desde Pantitl\u00e1n a Chapultepec es la L\u00ednea 2 del Sistema de Transporte El\u00e9ctrico de la CDMX que conecta con las l\u00edneas 2, 3, 4, 5, 9 y A del Metro; as\u00ed como las l\u00edneas 1, 3, 4, 5 y 7 del Metrob\u00fas y con la L\u00ednea 1 del Troleb\u00fas que corre por Eje Central.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Estaciones abiertas en L\u00ednea 12<\/strong><\/h3>\n\n\n\n<p>El tramo subterr\u00e1neo de la L\u00ednea 12 del Metro CDMX, que va de Mixcoac a Atlalilco, fue reabierto el domingo 15 de enero del 2023. Las estaciones que ya est\u00e1n en operaci\u00f3n son:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Mixcoac<\/li>\n\n\n\n<li>Insurgentes Sur<\/li>\n\n\n\n<li>Hospital 20 de Noviembre<\/li>\n\n\n\n<li>Zapata<\/li>\n\n\n\n<li>Parque de los Venados<\/li>\n\n\n\n<li>Eje Central<\/li>\n\n\n\n<li>Ermita<\/li>\n\n\n\n<li>Mexicaltzingo<\/li>\n\n\n\n<li>Atlalilco<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Viernes 26 de mayo 2023 Usuarios del Metro CDMX reportan aglomeraci\u00f3n y servicio lento en&#8230;<\/p>\n","protected":false},"author":3,"featured_media":60048,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-60047","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-del-dia"],"_links":{"self":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/60047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=60047"}],"version-history":[{"count":1,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/60047\/revisions"}],"predecessor-version":[{"id":60049,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/60047\/revisions\/60049"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media\/60048"}],"wp:attachment":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=60047"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=60047"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=60047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}