{"id":60095,"date":"2023-05-29T12:13:42","date_gmt":"2023-05-29T18:13:42","guid":{"rendered":"http:\/\/bambapolitica.com.mx\/?p=60095"},"modified":"2023-05-29T12:13:44","modified_gmt":"2023-05-29T18:13:44","slug":"un-video-ha-causado-indignacion-en-redes-sociales-porque-se-ve-como-una-persona-arroja-a-un-perro-a-una-cazuela-con-aceite-hirviendo-en-un-evidente-caso-de-maltrato-animal-e","status":"publish","type":"post","link":"https:\/\/bambapolitica.com.mx\/index.php\/2023\/05\/29\/un-video-ha-causado-indignacion-en-redes-sociales-porque-se-ve-como-una-persona-arroja-a-un-perro-a-una-cazuela-con-aceite-hirviendo-en-un-evidente-caso-de-maltrato-animal-e\/","title":{"rendered":"Un video ha causado indignaci\u00f3n en redes sociales porque se ve c\u00f3mo una persona arroja\u00a0a un\u00a0perro\u00a0a una\u00a0cazuela con aceite hirviendo, en un evidente caso de\u00a0maltrato animal, esto en el municipio de\u00a0Tecamac,\u00a0en el\u00a0Estado de M\u00e9xico."},"content":{"rendered":"\n<p>Lunes 29 de mayo 2023<\/p>\n\n\n\n<p>Seg\u00fan reportes de algunas personas que han subido el video, as\u00ed como de albergues de perros que han sido rescatados de la calle, los sucesos ocurrieron el 28 de mayo. La fecha del video,&nbsp;que ha sido tomado de una casa a lado del establecimiento donde el perro fue aventado, muestra que todo sucedi\u00f3 alrededor del mediod\u00eda.<\/p>\n\n\n\n<p>En las im\u00e1genes se ve a dos perros en la calle acerc\u00e1ndose al local donde se encuentra la cazuela. Segundos despu\u00e9s una persona con playera azul sale del establecimiento y agarra a uno de los perritos para inmediatamente arrojarlo a la cazuela.<\/p>\n\n\n\n<p>Lo siguiente que se observa es al perrito tratando de luchar por salir del l\u00edquido hirviendo y por instantes parecen salir se\u00f1ales de vapor. Las personas alrededor se quedan viendo sin hacer nada, e incluso un segundo sujeto sale del local para apagar el gas que estaba encendido y\u00a0calentando la cazuela, pero sin sacar al perrito.<\/p>\n\n\n\n<p>La persona que arroj\u00f3 al perro al l\u00edquido hirviendo tom\u00f3 un coche estilo hatchback blanco con placas con terminaci\u00f3n 22-5.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfCu\u00e1l es el castigo por maltrato animal en el Estado de M\u00e9xico?<\/h2>\n\n\n\n<p>Una reciente modificaci\u00f3n en el 2021 aprobada por el Congreso del Estado de M\u00e9xico llev\u00f3 a un endurecimiento en el c\u00f3digo penal para condenar el maltrato animal, esto luego del asesinato del perrito Silver en Tlalnepantla.<\/p>\n\n\n\n<p>La sanci\u00f3n se increment\u00f3 a los&nbsp;<strong>seis a\u00f1os de prisi\u00f3n<\/strong>&nbsp;para quien cause la muerte no inmediata o prolongue la agon\u00eda de cualquier animal.<\/p>\n\n\n\n<p>El caso del perro Silver fue difundido por una grabaci\u00f3n en redes sociales donde se ve\u00eda c\u00f3mo ocho personas lo golpearon hasta matarlo.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.excelsior.com.mx\/nacional\/perrito-arrojado-aceite-hirviendo-tecamac\/1589412\">https:\/\/www.excelsior.com.mx\/nacional\/perrito-arrojado-aceite-hirviendo-tecamac\/1589412<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lunes 29 de mayo 2023 Seg\u00fan reportes de algunas personas que han subido el video,&#8230;<\/p>\n","protected":false},"author":3,"featured_media":60096,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-60095","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policiaca"],"_links":{"self":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/60095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=60095"}],"version-history":[{"count":1,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/60095\/revisions"}],"predecessor-version":[{"id":60097,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/60095\/revisions\/60097"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media\/60096"}],"wp:attachment":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=60095"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=60095"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=60095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}