{"id":60168,"date":"2023-05-31T12:01:38","date_gmt":"2023-05-31T18:01:38","guid":{"rendered":"http:\/\/bambapolitica.com.mx\/?p=60168"},"modified":"2023-05-31T12:01:42","modified_gmt":"2023-05-31T18:01:42","slug":"era-policia-sujeto-que-avento-perrito-a-cazo-en-tecamac-trabajaba-en-la-ssc-cdmx","status":"publish","type":"post","link":"https:\/\/bambapolitica.com.mx\/index.php\/2023\/05\/31\/era-policia-sujeto-que-avento-perrito-a-cazo-en-tecamac-trabajaba-en-la-ssc-cdmx\/","title":{"rendered":"\u00a1Era polic\u00eda! Sujeto que avent\u00f3 perrito a cazo en Tec\u00e1mac trabajaba en la SSC CDMX"},"content":{"rendered":"\n<p>Miercoles 31 de mayo 2023<\/p>\n\n\n\n<p>El sujeto que avent\u00f3 a perrito a un cazo en Tec\u00e1mac era polic\u00eda adscrito a la SSC CDMX; fue suspendido de su cargo desde que fue identificado.<\/p>\n\n\n\n<p>El&nbsp;<strong>sujeto que avent\u00f3 a un&nbsp;<a href=\"https:\/\/www.excelsior.com.mx\/animales\" target=\"_blank\" rel=\"noreferrer noopener\">perrito<\/a>&nbsp;a un cazo con aceite hirviendo en Tec\u00e1mac era polic\u00eda<\/strong>&nbsp;adscrito a la&nbsp;<strong>Secretar\u00eda de Seguridad Ciudadana (SSC) de la Ciudad de M\u00e9xico (CDMX).&nbsp;<\/strong><\/p>\n\n\n\n<p>As\u00ed lo inform\u00f3 la misma<strong>\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/www.ssc.cdmx.gob.mx\/\" target=\"_blank\">corporaci\u00f3n<\/a>\u00a0de seguridad encabezada por Omar Garc\u00eda Harfuch.<\/strong>\u00a0Mediante una tarjeta informativa se\u00f1al\u00f3 que\u00a0<strong>Sergio \u2019N\u2019\u00a0<\/strong>formaba parte de la instituci\u00f3n, sin embargo, desde que se identific\u00f3 fue suspendido del cargo.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Esta Secretar\u00eda informa que form\u00f3 parte de la instituci\u00f3n, sin embargo, desde el momento que fue identificado y que se gir\u00f3 una orden de aprehensi\u00f3n en su contra por parte de la FGJ-EDOMEX, fue suspendido inmediatamente\u201d, se lee en el comunicado.&nbsp;<\/p>\n<\/blockquote>\n\n\n\n<p>La dependencia indic\u00f3 que&nbsp;<strong>colaboraron con informaci\u00f3n para dar con su paradero<\/strong>, as\u00ed como con las investigaciones de gabinete y de campo, adem\u00e1s de que se despleg\u00f3 personal operativo en coordinaci\u00f3n con otras instituciones para lograr su detenci\u00f3n.&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Esta Secretar\u00eda no tolerar\u00e1 conductas contrarias al c\u00f3digo de \u00e9tica y los principios que la rigen, y habr\u00e1 cero tolerancia en la comisi\u00f3n de actos que da\u00f1en a la ciudadan\u00eda\u201d, enfatiz\u00f3 la SSC.&nbsp;<\/p>\n<\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Sergio \u2019N\u2019 avent\u00f3 a perrito a un cazo con aceite hirviendo&nbsp;<\/strong><\/h2>\n\n\n\n<p>A trav\u00e9s de redes sociales fue difundido un&nbsp;<strong>video<\/strong>&nbsp;de una c\u00e1mara de seguridad en el que se aprecia al individuo arrojar al can al cazo.<\/p>\n\n\n\n<p>Los hechos ocurrieron\u00a0<strong>el pasado 28 de mayo en la colonia San Pablo Tecalco del municipio de Tec\u00e1mac.<\/strong><\/p>\n\n\n\n<p>Este martes\u00a0<strong>el hombre fue detenido en calles de la alcald\u00eda Coyoac\u00e1n<\/strong>, posteriormente fue trasladado a la agencia 50 de la Fiscal\u00eda capitalina, donde entre empujones e insultos fue custodiado por agentes polic\u00edacos.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.excelsior.com.mx\/comunidad\/sujeto-que-avento-perrito-a-cazo-en-tecamac-era-policia-de-la-ssc-cdmx\/1589791\">https:\/\/www.excelsior.com.mx\/comunidad\/sujeto-que-avento-perrito-a-cazo-en-tecamac-era-policia-de-la-ssc-cdmx\/1589791<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Miercoles 31 de mayo 2023 El sujeto que avent\u00f3 a perrito a un cazo en&#8230;<\/p>\n","protected":false},"author":3,"featured_media":60169,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-60168","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-del-dia"],"_links":{"self":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/60168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=60168"}],"version-history":[{"count":1,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/60168\/revisions"}],"predecessor-version":[{"id":60170,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/60168\/revisions\/60170"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media\/60169"}],"wp:attachment":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=60168"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=60168"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=60168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}