{"id":73935,"date":"2024-07-31T08:30:07","date_gmt":"2024-07-31T14:30:07","guid":{"rendered":"https:\/\/bambapolitica.com.mx\/?p=73935"},"modified":"2024-07-31T08:30:11","modified_gmt":"2024-07-31T14:30:11","slug":"cuadrillas-de-sacmex-piden-moche-a-vecinos-de-la-unidad-ctm-culhuacan","status":"publish","type":"post","link":"https:\/\/bambapolitica.com.mx\/index.php\/2024\/07\/31\/cuadrillas-de-sacmex-piden-moche-a-vecinos-de-la-unidad-ctm-culhuacan\/","title":{"rendered":"CUADRILLAS DE SACMEX PIDEN \u201cMOCHE\u201d A VECINOS DE LA UNIDAD CTM CULHUAC\u00c1N"},"content":{"rendered":"\n<p>31 de Julio 2024<\/p>\n\n\n\n<p>PAN recolectar\u00e1 firmas vecinales para denunciar al jefe de zona de Sacmex que encabeza las extorsiones en las unidades de la CTM Culhuac\u00e1n.<\/p>\n\n\n\n<p>Sacmex reporta subejercicios en la Cuenta P\u00fablica de a\u00f1os anteriores; el Gobierno de Morena no quiere invertir pero s\u00ed extorsiona a los vecinos.<\/p>\n\n\n\n<p>Las extorsiones de brigadistas del Sistema de Aguas de la Ciudad de M\u00e9xico son cada vez m\u00e1s evidentes y descaradas, ya que cierran v\u00e1lvulas de agua y cobran para reabrirlas.<\/p>\n\n\n\n<p>As\u00ed lo denunci\u00f3 este domingo el diputado local del PAN, Ricardo Rubio Torres, quien cuenta con diversas quejas vecinales por estos casos y las cuales, llevar\u00e1 ante la Contralor\u00eda e incluso, FGJCDMX.<\/p>\n\n\n\n<p>\u201cLos vecinos nos narran que la falta de agua en sus unidades es m\u00e1s constante; antes ten\u00edan agua una o dos veces al d\u00eda y ahora solamente son dos d\u00edas a la semana, por lo que tienen que almacenar el l\u00edquido vital para su uso habitual\u201d.<\/p>\n\n\n\n<p>Rubio indic\u00f3 que los vecinos, para que tengan agua, deben pagar una cuota que no es precisamente su recibo de Sacmex, sino una especie de \u201ccooperaci\u00f3n\u201d a los brigadistas que acuden para, supuestamente auxiliar a los vecinos que no tienen agua.<\/p>\n\n\n\n<p>El diputado federal del PAN, H\u00e9ctor Sa\u00fal T\u00e9llez Hern\u00e1ndez, anunci\u00f3 una colecta de firmas para armar una denuncia formal en contra de los mandos regionales de la zona sur de Sacmex, que son quienes orquestan estas extorsiones para brindar agua.<\/p>\n\n\n\n<p>\u201cAdem\u00e1s, junto con los vecinos vamos a instalar c\u00e1maras de vigilancia en domicilios cercanos a las bombas y v\u00e1lvulas de Sacmex de las CTM de Culhuac\u00e1n, para tener evidencia de los momentos en que se cierran y se abren con objeto de verificar si son decisiones legales\u201d.<\/p>\n\n\n\n<p>T\u00e9llez Hern\u00e1ndez pidi\u00f3 a los vecinos acercarse al PAN para denunciar estos moches que pide Sacmex en la zona de culhuacanes. \u201cLe debemos recordar a los vecinos que Sacmex tiene un presupuesto que tan solo durante el 2023, tuvo un subejercicio del 53 por ciento, es decir, que la dependencia no gast\u00f3 m\u00e1s de la mitad del dinero que tiene para infraestructura, rehabilitaci\u00f3n o mantenimiento de plantas\u201d.<\/p>\n\n\n\n<p>El panista se\u00f1al\u00f3 que el PAN instalar\u00e1 m\u00f3dulos de atenci\u00f3n ciudadana en todos los culhuacanes para que los vecinos denuncien estas injusticias. \u201cPagar por agua es la herencia que Morena nos quiere imponer, ellos son corruptos\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>31 de Julio 2024 PAN recolectar\u00e1 firmas vecinales para denunciar al jefe de zona de&#8230;<\/p>\n","protected":false},"author":3,"featured_media":73936,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-73935","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-del-dia"],"_links":{"self":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/73935","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=73935"}],"version-history":[{"count":1,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/73935\/revisions"}],"predecessor-version":[{"id":73937,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/73935\/revisions\/73937"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media\/73936"}],"wp:attachment":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=73935"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=73935"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=73935"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}