{"id":84771,"date":"2025-08-19T09:58:07","date_gmt":"2025-08-19T15:58:07","guid":{"rendered":"https:\/\/bambapolitica.com.mx\/?p=84771"},"modified":"2025-08-19T09:58:10","modified_gmt":"2025-08-19T15:58:10","slug":"congresistas-respaldan-fortalecimiento-de-la-nueva-escuela-mexicana","status":"publish","type":"post","link":"https:\/\/bambapolitica.com.mx\/index.php\/2025\/08\/19\/congresistas-respaldan-fortalecimiento-de-la-nueva-escuela-mexicana\/","title":{"rendered":"Congresistas respaldan fortalecimiento de la Nueva Escuela Mexicana"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li>Durante el evento, la gobernadora Delfina G\u00f3mez reconoci\u00f3 el respaldo del congreso al Plan de Desarrollo del Estado de M\u00e9xico y su presupuesto, los cuales han sido aprobados por el Poder Legislativo.<\/li>\n<\/ul>\n\n\n\n<p>Los diputados Jos\u00e9 Francisco V\u00e1zquez Rodr\u00edguez y Maurilio Hern\u00e1ndez Gonz\u00e1lez, presidentes de la Junta de Coordinaci\u00f3n Pol\u00edtica y de la Directiva de la LXII Legislatura mexiquense, respectivamente, participaron en la inauguraci\u00f3n del Congreso Internacional de Educaci\u00f3n: Tendencias para la Excelencia Educativa \u2014 encabezada por la gobernadora Delfina G\u00f3mez \u00c1lvarez \u2014 cuyo fin es fortalecer la Nueva Escuela Mexicana y transitar a una educaci\u00f3n de excelencia, incluyente y con sentido social.<\/p>\n\n\n\n<p>En el evento, al que tambi\u00e9n acudieron diputadas y diputados locales, entre ellos, Rigoberto Vargas Cervantes, presidente de la Comisi\u00f3n Legislativa de Educaci\u00f3n, Cultura, Ciencia, Tecnolog\u00eda e Innovaci\u00f3n, la mandataria mexiquense destac\u00f3 que este tipo de acciones son posibles gracias al trabajo coordinado con el Poder Legislativo, que ha respaldado iniciativas clave como el Plan de Desarrollo del Estado de M\u00e9xico 2023\u20132029 y su presupuesto.<\/p>\n\n\n\n<p>En este sentido, subray\u00f3 que invertir en educaci\u00f3n genera m\u00faltiples beneficios para la sociedad.<\/p>\n\n\n\n<p>A\u00f1adi\u00f3 que este congreso contribuye al cumplimiento de los objetivos del Plan de Desarrollo, entre ellos la revalorizaci\u00f3n del personal docente y administrativo del sector educativo, con su formaci\u00f3n y actualizaci\u00f3n en congruencia con la Nueva Escuela Mexicana, concebida como un modelo educativo con enfoque cr\u00edtico, humanista y comunitario, orientado a la formaci\u00f3n integral de las y los estudiantes.<\/p>\n\n\n\n<p>A la inauguraci\u00f3n tambi\u00e9n asistieron Fernando D\u00edaz Ju\u00e1rez, presidente del Tribunal Superior de Justicia y del Consejo de la Judicatura del Poder Judicial; Horacio Duarte Olivares, secretario general de Gobierno; Miguel \u00c1ngel Hern\u00e1ndez Espejel, secretario de Educaci\u00f3n, Ciencia, Tecnolog\u00eda e Innovaci\u00f3n del gobierno estatal, personas l\u00edderes magisteriales del \u00e1mbito federal y estatal, as\u00ed como especialistas y ponentes nacionales e internacionales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los diputados Jos\u00e9 Francisco V\u00e1zquez Rodr\u00edguez y Maurilio Hern\u00e1ndez Gonz\u00e1lez, presidentes de la Junta de&#8230;<\/p>\n","protected":false},"author":3,"featured_media":84772,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-84771","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-del-dia"],"_links":{"self":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/84771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=84771"}],"version-history":[{"count":1,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/84771\/revisions"}],"predecessor-version":[{"id":84773,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/84771\/revisions\/84773"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media\/84772"}],"wp:attachment":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=84771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=84771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=84771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}