{"id":84878,"date":"2025-08-25T09:56:47","date_gmt":"2025-08-25T15:56:47","guid":{"rendered":"https:\/\/bambapolitica.com.mx\/?p=84878"},"modified":"2025-08-25T09:56:52","modified_gmt":"2025-08-25T15:56:52","slug":"gobernadora-delfina-gomez-alvarez-impulsa-un-servicio-publico-etico-incluyente-y-responsable-secretaria-hilda-salazar-gil","status":"publish","type":"post","link":"https:\/\/bambapolitica.com.mx\/index.php\/2025\/08\/25\/gobernadora-delfina-gomez-alvarez-impulsa-un-servicio-publico-etico-incluyente-y-responsable-secretaria-hilda-salazar-gil\/","title":{"rendered":"Gobernadora Delfina G\u00f3mez \u00c1lvarez impulsa un servicio p\u00fablico \u00e9tico, incluyente y responsable: Secretaria Hilda Salazar Gil"},"content":{"rendered":"\n<p>El Estado de M\u00e9xico, sede de la Segunda Asamblea Ordinaria de la Regi\u00f3n Centro-Pac\u00edfico de la CPCE-F.<\/p>\n\n\n\n<p>Hilda Salazar Gil, Secretaria de la Contralor\u00eda del Estado de M\u00e9xico, asegur\u00f3 que la administraci\u00f3n encabezada por la Gobernadora Delfina G\u00f3mez \u00c1lvarez se encuentra comprometida con un proyecto hist\u00f3rico y \u00e9tico, de dignificaci\u00f3n del servicio p\u00fablico, incluyente y socialmente responsable.<\/p>\n\n\n\n<p>En reuni\u00f3n con sus hom\u00f3logos de la Regi\u00f3n Centro-Pac\u00edfico de la Comisi\u00f3n Permanente de Contralores Estados-Federaci\u00f3n (CPCE-F), agreg\u00f3 que se busca mejorar la capacidad de respuesta ante las necesidades de la ciudadan\u00eda con transparencia, rendici\u00f3n de cuentas y cero tolerancia a la corrupci\u00f3n, bajo la encomienda de trabajar con sensibilidad y cercan\u00eda al pueblo, haciendo efectivo el principio de \u201cm\u00e1s territorio, menos escritorio\u201d.<\/p>\n\n\n\n<p>Salazar Gil record\u00f3 que, dentro del Plan de Desarrollo del Estado de M\u00e9xico 2023-2029, en su Eje 1. Cero Corrupci\u00f3n y Gobierno del Pueblo y para el Pueblo, se estableci\u00f3 como l\u00ednea de acci\u00f3n el impulso de la \u00e9tica p\u00fablica para prevenir y combatir la corrupci\u00f3n al interior de la administraci\u00f3n p\u00fablica estatal; sin soslayar la necesidad de que las personas servidoras p\u00fablicas adquieran una nueva conciencia \u00e9tica, regida por valores y principios humanistas, donde la honestidad sea el eje rector para desempe\u00f1ar sus tareas y atribuciones.<\/p>\n\n\n\n<p>Al destacar que la administraci\u00f3n p\u00fablica requiere control y vigilancia constantes para asegurar que sus \u00f3rganos y funcionarios act\u00faen en favor del inter\u00e9s p\u00fablico y no personal, precis\u00f3 que la supervisi\u00f3n es especialmente crucial en el manejo de la hacienda p\u00fablica, a fin de garantizar el uso legal y correcto de los recursos.<\/p>\n\n\n\n<p>En presencia de Guadalupe Araceli Garc\u00eda Mart\u00ednez, Subsecretaria Anticorrupci\u00f3n y Buen Gobierno y Presidenta Suplente de la CPCE-F, la Contralora estatal apunt\u00f3 que la corrupci\u00f3n es un riesgo permanente, por lo que es fundamental ejercer una fiscalizaci\u00f3n t\u00e9cnica que verifique y eval\u00fae las actividades de quienes manejan fondos y recursos estatales.<\/p>\n\n\n\n<p>En ese sentido, y en su calidad de Coordinadora de la Regi\u00f3n Centro-Pac\u00edfico de la CPCE-F, Hilda Salazar Gil mencion\u00f3 que la dependencia a su cargo ha implementado el control de confianza como una herramienta de evaluaci\u00f3n aplicada a las personas servidoras p\u00fablicas involucradas en funciones sensibles, como el manejo de fondos, auditor\u00edas, adquisiciones, supervisi\u00f3n de obras y otorgamiento de licencias, entre otros.<\/p>\n\n\n\n<p>Acompa\u00f1ada tambi\u00e9n de Mar\u00eda Guadalupe Ram\u00edrez Zepeda, Secretaria de Transparencia y Rendici\u00f3n de Cuentas del Estado de Sinaloa y Coordinadora Nacional de la CPCE-F, detall\u00f3 que dicha estrategia tambi\u00e9n est\u00e1 destinada a fortalecer la integridad en el servicio p\u00fablico y recuperar de manera paulatina la confianza de la ciudadan\u00eda en las instituciones y en el nuevo orden jur\u00eddico que se construye d\u00eda con d\u00eda en todo el pa\u00eds.<\/p>\n\n\n\n<p>Cabe se\u00f1alar que a esta Segunda Asamblea Ordinaria de la Regi\u00f3n Centro-Pac\u00edfico de la CPCE-F asistieron titulares de las contralor\u00edas de Sinaloa (Coordinadora Nacional), Baja California Sur (Vocer\u00eda), San Luis Potos\u00ed (Comisario), Morelos y Michoac\u00e1n, as\u00ed como representantes de la Ciudad de M\u00e9xico, Guerrero y Quer\u00e9taro.<\/p>\n\n\n\n<p>Como parte de la agenda de trabajo, se presentaron ponencias a cargo de Guadalupe Araceli Garc\u00eda Mart\u00ednez, Subsecretaria Anticorrupci\u00f3n y Buen Gobierno federal, con el tema \u201cJ\u00f3venes Auditores\u201d; Irais Graciela Barreto Canales, Titular de la Unidad de Participaci\u00f3n Social y Responsabilidad Compartida de la Secretar\u00eda Anticorrupci\u00f3n y Buen Gobierno, con el tema \u201cSemillero de Honestidad\u201d; y V\u00edctor Alfonso Ch\u00e1vez L\u00f3pez, Magistrado de la Cuarta Secci\u00f3n Especializada en Materia de Responsabilidades Administrativas en Toluca, con el tema \u201cAcoso y Hostigamiento Sexual\u201d.<\/p>\n\n\n\n<p>Por parte de la Secretar\u00eda de la Contralor\u00eda, Jazm\u00edn Mendoza Garc\u00eda, Titular de la Unidad Estatal de Evaluaci\u00f3n de Confianza present\u00f3 la organizaci\u00f3n y funcionamiento del \u00e1rea a su cargo, que es pionera a nivel nacional en evaluar a personal encargado de manejar recurso p\u00fablico, su vigilancia, as\u00ed como a encargados de adquisiciones y responsables de la obra p\u00fablica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Estado de M\u00e9xico, sede de la Segunda Asamblea Ordinaria de la Regi\u00f3n Centro-Pac\u00edfico de&#8230;<\/p>\n","protected":false},"author":3,"featured_media":84879,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-84878","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-del-dia"],"_links":{"self":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/84878","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=84878"}],"version-history":[{"count":1,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/84878\/revisions"}],"predecessor-version":[{"id":84880,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/84878\/revisions\/84880"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media\/84879"}],"wp:attachment":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=84878"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=84878"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=84878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}