{"id":85048,"date":"2025-09-01T10:37:28","date_gmt":"2025-09-01T16:37:28","guid":{"rendered":"https:\/\/bambapolitica.com.mx\/?p=85048"},"modified":"2025-09-01T10:37:39","modified_gmt":"2025-09-01T16:37:39","slug":"realizara-sict-trabajos-de-conservacion-en-carreteras-los-reyes-texcoco-y-texcoco-ecatepec","status":"publish","type":"post","link":"https:\/\/bambapolitica.com.mx\/index.php\/2025\/09\/01\/realizara-sict-trabajos-de-conservacion-en-carreteras-los-reyes-texcoco-y-texcoco-ecatepec\/","title":{"rendered":"Realizar\u00e1 SICT trabajos de conservaci\u00f3n en carreteras Los Reyes-Texcoco y Texcoco-Ecatepec"},"content":{"rendered":"\n<p>Los trabajos ser\u00e1n de 22:00 a 04:30 hrs para reducir afectaciones viales y dar mayor seguridad a los usuarios.<\/p>\n\n\n\n<p>La Secretar\u00eda de Infraestructura, Comunicaciones y Transportes (SICT) en el Estado de M\u00e9xico inform\u00f3 que a partir del 1 de septiembre y hasta el 16 de diciembre de 2025.&nbsp;<\/p>\n\n\n\n<p>Se llevar\u00e1n a cabo labores de conservaci\u00f3n peri\u00f3dica en dos importantes v\u00edas de la entidad, la carretera Los Reyes-Texcoco, en el tramo que comprende del kil\u00f3metro 0+000 al 16+000, y la Texcoco-Ecatepec, del kil\u00f3metro 33+000 al 40+000.<br><\/p>\n\n\n\n<p>Trabajos se realizar\u00e1n en la noche<br>Los trabajos se realizar\u00e1n en horario nocturno, de 22:00 a 04:30 horas, con el prop\u00f3sito de reducir afectaciones al tr\u00e1nsito vehicular y garantizar mayor seguridad a los usuarios.&nbsp;<\/p>\n\n\n\n<p>En total, se atender\u00e1 una meta de 26 kil\u00f3metros, con el apoyo de maquinaria especializada y cuadrillas de la SICT.<\/p>\n\n\n\n<p>V\u00edas que ser\u00e1n intervenidas<br>En el tramo Los Reyes-Texcoco, la conservaci\u00f3n se ejecutar\u00e1 en el sentido Texcoco-Los Reyes, mediante fresado y la colocaci\u00f3n de nueva carpeta asf\u00e1ltica.&nbsp;<\/p>\n\n\n\n<p>Debido a estas labores, se prev\u00e9 reducci\u00f3n de carriles, por lo que se implementar\u00e1 se\u00f1alamiento preventivo para orientar a los conductores.<\/p>\n\n\n\n<p>Como rutas alternas, la SICT recomend\u00f3 utilizar las avenidas Siervo de la Naci\u00f3n y General Mariano Ruiz, as\u00ed como la Carretera Federal 136D Pe\u00f1\u00f3n-Texcoco y la autopista estatal 57D Circuito Exterior Mexiquense, con el fin de evitar contratiempos en los traslados.<\/p>\n\n\n\n<p>La dependencia federal reiter\u00f3 su compromiso de mantener en condiciones \u00f3ptimas la red carretera del Estado de M\u00e9xico y pidi\u00f3 a los automovilistas respetar los se\u00f1alamientos viales y manejar con precauci\u00f3n en las zonas de obra.<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los trabajos ser\u00e1n de 22:00 a 04:30 hrs para reducir afectaciones viales y dar mayor&#8230;<\/p>\n","protected":false},"author":3,"featured_media":85049,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-85048","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-del-dia"],"_links":{"self":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/85048","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=85048"}],"version-history":[{"count":1,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/85048\/revisions"}],"predecessor-version":[{"id":85050,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/85048\/revisions\/85050"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media\/85049"}],"wp:attachment":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=85048"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=85048"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=85048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}