{"id":88013,"date":"2026-01-21T06:15:05","date_gmt":"2026-01-21T12:15:05","guid":{"rendered":"https:\/\/bambapolitica.com.mx\/?p=88013"},"modified":"2026-01-21T06:15:07","modified_gmt":"2026-01-21T12:15:07","slug":"gobierno-del-edomex-da-banderazo-de-salida-a-27-nuevas-unidades-de-la-linea-ii-del-mexibus-en-beneficio-de-mas-de-102-mil-usuarios","status":"publish","type":"post","link":"https:\/\/bambapolitica.com.mx\/index.php\/2026\/01\/21\/gobierno-del-edomex-da-banderazo-de-salida-a-27-nuevas-unidades-de-la-linea-ii-del-mexibus-en-beneficio-de-mas-de-102-mil-usuarios\/","title":{"rendered":"*Gobierno del EdoM\u00e9x da banderazo de salida a 27 nuevas unidades de la L\u00ednea II del Mexib\u00fas en beneficio de m\u00e1s de 102 mil usuarios"},"content":{"rendered":"\n<p>La renovaci\u00f3n beneficiar\u00e1 a habitantes de Ecatepec, Coacalco, Tultitl\u00e1n y Cuautitl\u00e1n Izcalli._<\/p>\n\n\n\n<p>La nueva flota incluye autobuses 100 % el\u00e9ctricos y de tecnolog\u00eda Euro 6, con la que se dejar\u00e1 de emitir anualmente 490 toneladas de contaminantes a la atm\u00f3sfera._<\/p>\n\n\n\n<p>Con el firme compromiso de transformar la movilidad y ofrecer traslados dignos a la poblaci\u00f3n mexiquense, el Gobierno de la Maestra Delfina G\u00f3mez \u00c1lvarez dio el banderazo de la renovaci\u00f3n de la flota de la L\u00ednea II del Mexib\u00fas, sistema de transporte que atiende diariamente a m\u00e1s de 102 mil usuarios.<\/p>\n\n\n\n<p>Esta acci\u00f3n contempla la incorporaci\u00f3n de 57 unidades de \u00faltima generaci\u00f3n que brindar\u00e1n servicio en el corredor Las Am\u00e9ricas (Ecatepec) &#8211; La Quebrada (Cuautitl\u00e1n Izcalli).<\/p>\n\n\n\n<p>El banderazo de salida del nuevo parque vehicular, realizado en el marco aniversario once de esta ruta de transporte, beneficiar\u00e1 a la poblaci\u00f3n de Ecatepec, Coacalco, Tultitl\u00e1n y Cuautitl\u00e1n Izcalli.<\/p>\n\n\n\n<p>Durante el evento, donde tambi\u00e9n se inaugur\u00f3 la infraestructura de carga el\u00e9ctrica y paneles solares, Ricardo Delgado Reynoso, Subsecretario de Movilidad, dijo que la prioridad de la actual administraci\u00f3n gubernamental es dignificar el transporte, para brindar seguridad, confiabilidad y reducir los tiempos de traslado.<\/p>\n\n\n\n<p>Por su parte, Alejandro Viedma Vel\u00e1zquez, Subsecretario General de Gobierno, subray\u00f3 que la administraci\u00f3n de la Maestra Delfina G\u00f3mez respalda a los transportistas que est\u00e1n en proceso de modernizaci\u00f3n de sus unidades y agreg\u00f3 que esto es muestra de que la suma de esfuerzos entre el Gobierno del Estado de M\u00e9xico y el sector privado generan beneficios directos para la poblaci\u00f3n que m\u00e1s lo necesita.<\/p>\n\n\n\n<p>La renovaci\u00f3n del parque vehicular implic\u00f3 una inversi\u00f3n superior a los 200 millones de pesos por parte de la empresa Transcomunicador y conlleva amplios beneficios ambientales, pues dejar\u00e1n de emitirse anualmente 490 toneladas de contaminantes a la atm\u00f3sfera.<\/p>\n\n\n\n<p>La nueva flota se integra por 30 autobuses articulados de 18 metros con motor Euro 6; 15 autobuses 100 por ciento el\u00e9ctricos, ambos con capacidad para 160 pasajeros, que posicionan al estado de M\u00e9xico a la vanguardia en electromovilidad, as\u00ed como 12 unidades del servicio rosa de 12 metros con capacidad para 80 personas.<\/p>\n\n\n\n<p>Asimismo, las unidades cuentan con infraestructura de accesibilidad universal, c\u00e1maras de vigilancia y sensores de aforo para brindar mayor seguridad y protecci\u00f3n a quienes utilizan este transporte; son unidades m\u00e1s silenciosas y eficientes, que mejoran el bienestar de sus operadoras durante la jornada laboral.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La renovaci\u00f3n beneficiar\u00e1 a habitantes de Ecatepec, Coacalco, Tultitl\u00e1n y Cuautitl\u00e1n Izcalli._ La nueva flota&#8230;<\/p>\n","protected":false},"author":8,"featured_media":88014,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-88013","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-del-dia"],"_links":{"self":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/88013","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=88013"}],"version-history":[{"count":1,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/88013\/revisions"}],"predecessor-version":[{"id":88015,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/88013\/revisions\/88015"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media\/88014"}],"wp:attachment":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=88013"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=88013"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=88013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}