{"id":88023,"date":"2026-01-21T06:25:54","date_gmt":"2026-01-21T12:25:54","guid":{"rendered":"https:\/\/bambapolitica.com.mx\/?p=88023"},"modified":"2026-01-21T06:25:57","modified_gmt":"2026-01-21T12:25:57","slug":"el-partido-revolucionario-institucional-en-veracruz-reconoce-y-respalda-plenamente-el-legado-politico-del-lic-fidel-herrera-beltran-un-hombre-que-se-formo-en-las-filas-del-priismo-y-que-sirvio-a-mex","status":"publish","type":"post","link":"https:\/\/bambapolitica.com.mx\/index.php\/2026\/01\/21\/el-partido-revolucionario-institucional-en-veracruz-reconoce-y-respalda-plenamente-el-legado-politico-del-lic-fidel-herrera-beltran-un-hombre-que-se-formo-en-las-filas-del-priismo-y-que-sirvio-a-mex\/","title":{"rendered":"El Partido Revolucionario Institucional en Veracruz reconoce y respalda plenamente el legado pol\u00edtico del Lic. Fidel Herrera Beltr\u00e1n, un hombre que se form\u00f3 en las filas del priismo y que sirvi\u00f3 a M\u00e9xico\u00a0\u00a0y a\u00a0\u00a0Veracruz con compromiso, visi\u00f3n y resultados como Diputado Federal, Senador de la Rep\u00fablica y Gobernador del Estado."},"content":{"rendered":"\n<p><br>Fidel Herrera Beltr\u00e1n fue un extraordinario l\u00edder priista, un gran ser humano y un excepcional gobernador de los veracruzanos, cuyo trabajo y trayectoria siguen siendo parte fundamental de la historia pol\u00edtica contempor\u00e1nea de Veracruz.<\/p>\n\n\n\n<p>Los se\u00f1alamientos realizados por el senador Sa\u00fal Monreal son infundados, falsos y carentes de sustento. Desde Morena se insiste en descalificar al pasado para ocultar su incapacidad de dar resultados en el presente.<\/p>\n\n\n\n<p>El PRI Veracruz respalda tambi\u00e9n el mensaje emitido por Fidel Herrera Borunda, quien ha defendido con dignidad la memoria, el trabajo y la aportaci\u00f3n pol\u00edtica de su padre al desarrollo del estado.<\/p>\n\n\n\n<p>En el PRI no permitiremos que se mancille el legado de quienes sirvieron con lealtad a Veracruz.<\/p>\n\n\n\n<p>Adolfo Ramirez Arana &#8211; Carolina Gudi\u00f1o Corro \/ Dirigentes del PRI Veracruz<\/p>\n\n\n\n<p>PRI Oficial M\u00e9xico Alejandro Moreno C\u00e1rdenas Carolina Viggiano Jorge Meade<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fidel Herrera Beltr\u00e1n fue un extraordinario l\u00edder priista, un gran ser humano y un excepcional&#8230;<\/p>\n","protected":false},"author":8,"featured_media":88024,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-88023","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-del-dia"],"_links":{"self":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/88023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=88023"}],"version-history":[{"count":1,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/88023\/revisions"}],"predecessor-version":[{"id":88025,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/88023\/revisions\/88025"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media\/88024"}],"wp:attachment":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=88023"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=88023"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=88023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}