{"id":89393,"date":"2026-03-11T05:39:19","date_gmt":"2026-03-11T11:39:19","guid":{"rendered":"https:\/\/bambapolitica.com.mx\/?p=89393"},"modified":"2026-03-11T05:39:24","modified_gmt":"2026-03-11T11:39:24","slug":"se-integro-en-texcoco-el-comite-municipal-para-el-manejo-del-fuego","status":"publish","type":"post","link":"https:\/\/bambapolitica.com.mx\/index.php\/2026\/03\/11\/se-integro-en-texcoco-el-comite-municipal-para-el-manejo-del-fuego\/","title":{"rendered":"SE INTEGR\u00d3 EN TEXCOCO EL COMIT\u00c9 MUNICIPAL PARA EL MANEJO DEL FUEGO"},"content":{"rendered":"\n<p>Se trata de salvaguardar la integridad de la poblaci\u00f3n reafirmando el compromiso de Texcoco con la protecci\u00f3n ambiental y la gesti\u00f3n integral de riesgos.<\/p>\n\n\n\n<p>Los integrantes del Comit\u00e9 Municipal del Manejo del Fuego, deber\u00e1n trabajar coordinadamente para salvaguardar la vida, el patrimonio, el medio ambiente del municipio de Texcoco.<\/p>\n\n\n\n<p>En el municipio de Texcoco se instal\u00f3 el Comit\u00e9 Municipal del Manejo del Fuego, que tiene como finalidad fortalecer la coordinaci\u00f3n entre autoridades instituciones y la sociedad civil para prevenir y combatir incendios en la zona forestal y de pastizal que en los \u00faltimos meses se han incrementado.<\/p>\n\n\n\n<p>El Secretario T\u00e9cnico del Comit\u00e9 del Municipal del Manejo del Fuego Jes\u00fas Emilio Duarte Olivares, se\u00f1al\u00f3 que este comit\u00e9 trabajar\u00e1 de la mano con la prevenci\u00f3n con la finalidad de salvaguardar la integridad de la poblaci\u00f3n reafirmando el compromiso de Texcoco con la protecci\u00f3n ambiental y la gesti\u00f3n Integral de Riesgos.<\/p>\n\n\n\n<p>El Secretario del Ayuntamiento Jos\u00e9 Alfonso Valtierra Guzm\u00e1n, en representaci\u00f3n del Presidente Municipal de Texcoco Nazario Guti\u00e9rrez Mart\u00ednez, fue el encargado de realizar la instalaci\u00f3n de la sesi\u00f3n del Comit\u00e9 Municipal del Manejo del Fuego.<\/p>\n\n\n\n<p>Jes\u00fas Duarte Olivares, al referirse a los incendios registrados en Texcoco, se\u00f1al\u00f3 que solo en el mes de enero se tuvieron 127 incendios, de los que 97 fueron de pastizal, 3 forestales, inform\u00f3 que en lo que va de este a\u00f1o, para el mes de febrero se presentaron 105 incendios de pastizal y 11 incendios forestales, en los que va del mes de marzo van 33 incendios de pastizal y cinco incendio forestales.<\/p>\n\n\n\n<p>Explic\u00f3 que el incendio m\u00e1s fuerte se registr\u00f3 en el incendio del cerro de la rana entre San Miguel Tlaixpan y la purificaci\u00f3n, mismo que se propag\u00f3 debido a los fuertes vientos y a los sec\u00f3 del pasto, situaciones que se pueden prevenir si todos trabajamos en conjunto desde la vigilancia y haciendo conciencia entre la ciudadan\u00eda para prevenir ante que tener que atender una emergencia.<\/p>\n\n\n\n<p>Record\u00f3 que en Texcoco el bando municipal de gobierno establece que las \u201cquemas agr\u00edcolas\u201d, est\u00e1n prohibidas, y que en caso de que se realicen deben estar bajo la supervisi\u00f3n de la Direcci\u00f3n de Protecci\u00f3n Civil, Gesti\u00f3n Integral de Riesgos, Bomberos y Atenci\u00f3n M\u00e9dica Prehospitalaria, con la finalidad de prevenir que se descontrole y haya mayores consecuencias, pero de preferencia evitarlas al m\u00e1ximo.<\/p>\n\n\n\n<p>El Comit\u00e9 Municipal del Manejo del Fuego, qued\u00f3 integrado por:&nbsp;<\/p>\n\n\n\n<p>\u2022 Presidente del Comit\u00e9:<\/p>\n\n\n\n<p>Nazario Guti\u00e9rrez Mart\u00ednez&nbsp;<\/p>\n\n\n\n<p>Presidente Municipal Constitucional de Texcoco<\/p>\n\n\n\n<p>\u2022 Secretario T\u00e9cnico:<\/p>\n\n\n\n<p>Jesus Emilio Duarte Olivares<\/p>\n\n\n\n<p>Director de Protecci\u00f3n Civil y Gesti\u00f3n Integral del Riesgo, Bomberos y Atenci\u00f3n M\u00e9dica Prehospitalaria<\/p>\n\n\n\n<p>Vocal\u00edas:<\/p>\n\n\n\n<p>\u2022 Yesenia Armas Tob\u00f3n<\/p>\n\n\n\n<p>Presidenta del Sistema Municipal DIF<\/p>\n\n\n\n<p>\u2022 M\u00f3nica quintero Miranda<\/p>\n\n\n\n<p>&nbsp;Directora de Desarrollo Urbano y Ecolog\u00eda<\/p>\n\n\n\n<p>\u2022 Jesus P\u00e1ez Rivera<\/p>\n\n\n\n<p>Director del Campo<\/p>\n\n\n\n<p>\u2022 Comisario Roberto Hern\u00e1ndez Romero<\/p>\n\n\n\n<p>Director de Seguridad P\u00fablica y Movilidad<\/p>\n\n\n\n<p>\u2022 Miguel \u00c1ngel Olivares G\u00e1lvez<\/p>\n\n\n\n<p>Director de Obras P\u00fablicas&nbsp;<\/p>\n\n\n\n<p>\u2022 Andr\u00e9s Barr\u00f3n Meza<\/p>\n\n\n\n<p>Director de Servicios P\u00fablicos<\/p>\n\n\n\n<p>\u2022 Lenin Adcel Ram\u00edrez Villanueva<\/p>\n\n\n\n<p>Director de Agua Potable y Alcantarillado<\/p>\n\n\n\n<p>\u2022 Elba Tania Mar\u00edn S\u00e1nchez<\/p>\n\n\n\n<p>Directora General de Administraci\u00f3n<\/p>\n\n\n\n<p>\u2022 Lumi Vargas Moreno<\/p>\n\n\n\n<p>Encargada de Despacho de la Direcci\u00f3n de Imagen y Comunicaci\u00f3n Social<\/p>\n\n\n\n<p>\u2022 Mario Esteban S\u00e1nchez G\u00f3mez<\/p>\n\n\n\n<p>Juez C\u00edvico<\/p>\n\n\n\n<p>\u2022 N\u00e9stor Jos\u00e9 Villamil Garc\u00eda<\/p>\n\n\n\n<p>Delegado Regional Forestal Texcoco (representante de PROBOSQUE)<\/p>\n\n\n\n<p>\u2022 Diana Lorena S\u00e1nchez Vida\u00f1a<\/p>\n\n\n\n<p>Delegada Regional de Texcoco de la Coordinaci\u00f3n General de Conservaci\u00f3n Ecol\u00f3gica de la Secretar\u00eda de Medio Ambiente del Estado de M\u00e9xico<\/p>\n\n\n\n<p>\u2022 Cmte. Edgar Santiago Hern\u00e1ndez<\/p>\n\n\n\n<p>Subdirector Operativo de Texcoco de la Secretar\u00eda de Seguridad del Estado de M\u00e9xico<\/p>\n\n\n\n<p>\u2022 David Meraz S\u00e1nchez<\/p>\n\n\n\n<p>Presidente de la Uni\u00f3n de Ejidos del Monte Tl\u00e1loc.<\/p>\n\n\n\n<p>A nombre del Presidente Municipal Nazario Guti\u00e9rrez Mart\u00ednez el Secretario del Ayuntamiento Jos\u00e9 Alfonso Valtierra Guzm\u00e1n, tom\u00f3 protesta a los integrantes del Comit\u00e9 Municipal del Manejo del Fuego, con el compromiso de trabajar coordinadamente para salvaguardar la vida, el patrimonio, el medio ambiente del municipio de Texcoco.<\/p>\n\n\n\n<p>De esta manera declar\u00f3 formalmente instalado el Comit\u00e9 Municipal del Manejo del Fuego, que comenzar\u00e1 a operar a partir de la presente fecha, para coordinar acciones que tengan que ver con incendios forestales y de pastizal que amenacen la vida de sociedad civil y el ecosistema del municipio de Texcoco.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se trata de salvaguardar la integridad de la poblaci\u00f3n reafirmando el compromiso de Texcoco con&#8230;<\/p>\n","protected":false},"author":8,"featured_media":89394,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-89393","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-del-dia"],"_links":{"self":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/89393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=89393"}],"version-history":[{"count":1,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/89393\/revisions"}],"predecessor-version":[{"id":89395,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/89393\/revisions\/89395"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media\/89394"}],"wp:attachment":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=89393"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=89393"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=89393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}