{"id":91187,"date":"2026-05-05T11:57:13","date_gmt":"2026-05-05T17:57:13","guid":{"rendered":"https:\/\/bambapolitica.com.mx\/?p=91187"},"modified":"2026-05-05T11:57:50","modified_gmt":"2026-05-05T17:57:50","slug":"tras-peticion-de-extradicion-a-ruben-rocha-y-otros-nueve-servidores-se-ha-desatado-una-campana-de-la-derecha-adjudicando-corrupcion-a-la-4t-sheinbaum","status":"publish","type":"post","link":"https:\/\/bambapolitica.com.mx\/index.php\/2026\/05\/05\/tras-peticion-de-extradicion-a-ruben-rocha-y-otros-nueve-servidores-se-ha-desatado-una-campana-de-la-derecha-adjudicando-corrupcion-a-la-4t-sheinbaum\/","title":{"rendered":"Tras petici\u00f3n de extradici\u00f3n a Rub\u00e9n Rocha y otros nueve servidores se ha desatado una campa\u00f1a de la derecha adjudicando corrupci\u00f3n a la 4T, Sheinbaum"},"content":{"rendered":"\n<p>Al destacar que debe prevalecer la justicia y la soberan\u00eda, la presidenta Claudia Sheinbaum inform\u00f3 que tras la solicitud de licencia que hiciera el gobernador Rub\u00e9n Rocha al cargo, instruy\u00f3 al Gabinete de Seguridad a acudir a Sinaloa para reunirse con la gobernadora interina Yeraldine Bonilla para ratificar los t\u00e9rminos de colaboraci\u00f3n con el gobierno de Sinaloa para preservar la seguridad en la entidad.<\/p>\n\n\n\n<p> En conferencia ma\u00f1anera la mandataria federal indic\u00f3 que por el momento en que se encuentra el proceso de solicitud de extradici\u00f3n del Departamento de Justicia estadunidense contra Rocha y otros funcionarios, mencion\u00f3 que pidi\u00f3 a la Secretar\u00eda de Relaciones Exteriores solicitarle a la Fiscal\u00eda General de la Rep\u00fablica analizar si hay elementos de prueba para que fuera procedente la solicitud. <\/p>\n\n\n\n<p>Indica que esta se origina a partir de que en una oficina del distrito sur de Nueva York se presenta la denuncia. Por eso se pidi\u00f3 a la Canciller\u00eda porque se est\u00e1 pidiendo la detenci\u00f3n urgente con motivos de extradici\u00f3n. \u201cLa canciller\u00eda plantea \u00bfpor qu\u00e9 es tan urgente? \u00bfqu\u00e9 pruebas tienen?\u201d. La FGR le pide m\u00e1s pruebas, porque no vienen las pruebas que acrediten la urgencia. Eso es lo que va. <\/p>\n\n\n\n<p>Contesta y en este caso porque es tan urgente\u201d. Se\u00f1ala que es tiempo de principios y un principio que no es negociable es la soberan\u00eda, con cualquier gobernador, incluso de la oposici\u00f3n. \u201cNunca en la historia hab\u00edan pedido con urgencia una orden de aprehensi\u00f3n contra un gobernador, que me corresponde, la defensa de la soberan\u00eda y en segundo la justicia. Lo que debe prevalecer es verdad, justicia y la soberan\u00eda\u201d. Sheinbaum se pregunt\u00f3 \u201c\u00bfQu\u00e9 objetivo ten\u00eda sacarlo de ocho columnas si saben que deber\u00eda haber confidencialidad?\u201d.<\/p>\n\n\n\n<p> Tambi\u00e9n cuestion\u00f3 las cr\u00edticas de su visita a Palenque que ya estaba programada porque es la uni\u00f3n entre el Tren Interoce\u00e1nico y el Tren Maya, pero ya est\u00e1n diciendo \u201cya fue la Presidenta a pedir l\u00ednea. No tendr\u00eda nada de malo que me reuniera con el presidente Andr\u00e9s Manuel L\u00f3pez Obrador. No me reun\u00ed, pero ya fue a pedir l\u00ednea, desde Palenque est\u00e1n orientado la pol\u00edtica nacional, tiene mucho de misoginia como si la presidenta no pudiera tomar. Record\u00f3 que, en su momento, M\u00e9xico envi\u00f3 a Estados Unidos a \u201c94 jefes de organizaciones criminales que estaban detenidos, de todos los grupos criminales\u201d.<\/p>\n\n\n\n<p> Destac\u00f3 que la estrategia de seguridad permiti\u00f3 reducir en un 44 por ciento los homicidios registrados en M\u00e9xico. Se detuvo a un alcalde de Tequila, surgido de Morena, por sus nexos con el crimen organizado o al alcalde de Teuchitl\u00e1n que pertenece a Movimiento Ciudadano, por los hechos ocurridos en ese municipios. \u201cPor ciento, uno de los hermanos de este alcalde por v\u00ednculos con huachicol\u201d.<\/p>\n\n\n\n<p> Sheinbaum consider\u00f3 que a partir de que en una Corte de Nueva York solicit\u00f3 la detenci\u00f3n provisional con fines de extradici\u00f3n al gobernador de Sinaloa, Rub\u00e9n Rocha y otros nueve servidores se ha desatado una campa\u00f1a de la derecha nacional e internacional adjudicando corrupci\u00f3n a su movimiento. \u201cNosotros no protegemos a nadie. Llegamos al poder para acabar con el r\u00e9gimen de corrupci\u00f3n. Hasta ahora sino hubi\u00e9ramos acabado la corrupci\u00f3n del pasado no habr\u00eda un bill\u00f3n de pesos para programas del Bienestar\u201d.<\/p>\n\n\n\n<p> No habr\u00eda m\u00e1s recaudaci\u00f3n y no habr\u00edan salido 13.5 millones de personas de la pobreza. De acuerdo al gobierno federal, existe una confusi\u00f3n en torno a lo que realmente es la solicitud presentada por el Departamento de Justicia, pues en el Tratado de Extradici\u00f3n hay dos procedimientos diferenciados: una solicitud formal de extradici\u00f3n y una solicitud de aprehensi\u00f3n con fines de extradici\u00f3n en virtud de que hay una urgencia por la posible sustracci\u00f3n u obstrucci\u00f3n de la justicia. <\/p>\n\n\n\n<p>En la interpretaci\u00f3n del gobierno mexicano, la petici\u00f3n que se formul\u00f3 la semana pasada fue una petici\u00f3n de aprehensi\u00f3n por la urgencia, pero, en principio no est\u00e1 acreditada la urgencia. Por ello se requerir\u00e1 mayor n\u00famero de pruebas que acrediten esa urgencia. Una vez que sea enviadas m\u00e1s pruebas, correr\u00eda el plazo de sesenta d\u00edas en los cuales, la Fiscal\u00eda General de la Rep\u00fablica turne el expediente ante un juez de control para que este determine si es procedente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al destacar que debe prevalecer la justicia y la soberan\u00eda, la presidenta Claudia Sheinbaum inform\u00f3&#8230;<\/p>\n","protected":false},"author":3,"featured_media":91188,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-91187","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-del-dia"],"_links":{"self":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/91187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=91187"}],"version-history":[{"count":1,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/91187\/revisions"}],"predecessor-version":[{"id":91189,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/91187\/revisions\/91189"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media\/91188"}],"wp:attachment":[{"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=91187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=91187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bambapolitica.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=91187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}